{"id":95960,"date":"2020-06-29T17:28:47","date_gmt":"2020-06-29T15:28:47","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/feliway-friends\/"},"modified":"2026-08-06T11:48:05","modified_gmt":"2026-08-06T09:48:05","slug":"feliway-friends","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/feliway-friends\/","title":{"rendered":"Feliway Friends"},"content":{"rendered":"<p><strong>FELIWAY\u00a0<em>Friends<\/em> est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:<\/strong><\/p>\n<ul>\n<li><span data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:8,&quot;2&quot;:{&quot;6&quot;:1}}\uee10{&quot;1&quot;:16}\" data-sheets-userformat=\"{&quot;2&quot;:897,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;FELIWAY Friends est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:&quot;}\">Bagarres<\/span><\/li>\n<li><span data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:8,&quot;2&quot;:{&quot;6&quot;:1}}\uee10{&quot;1&quot;:16}\" data-sheets-userformat=\"{&quot;2&quot;:897,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;FELIWAY Friends est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:&quot;}\">Courses-poursuites<\/span><\/li>\n<li><span data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:8,&quot;2&quot;:{&quot;6&quot;:1}}\uee10{&quot;1&quot;:16}\" data-sheets-userformat=\"{&quot;2&quot;:897,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;FELIWAY Friends est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:&quot;}\">Obstructions<\/span><\/li>\n<li><span data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:8,&quot;2&quot;:{&quot;6&quot;:1}}\uee10{&quot;1&quot;:16}\" data-sheets-userformat=\"{&quot;2&quot;:897,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;FELIWAY Friends est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:&quot;}\">Intimidations<\/span><\/li>\n<\/ul>\n<p><span data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:8,&quot;2&quot;:{&quot;6&quot;:1}}\uee10{&quot;1&quot;:16}\" data-sheets-userformat=\"{&quot;2&quot;:899,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:3,&quot;3&quot;:6},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;FELIWAY Friends aide vos chats \u00e0 mieux s\u2019entendre \u00e0 la maison. Son effet continu assure une bonne entente permanente.&quot;}\">FELIWAY\u00a0<em>Friends<\/em>\u00a0aide vos chats \u00e0 mieux s\u2019entendre \u00e0 la maison. Son effet continu assure une bonne entente permanente.<\/span><\/p>\n<div class=\"extra-desc\">Jusqu&#8217;\u00e0\u00a0<b>30 jours<\/b>\u00a0d&#8217;harmonie entre les chats<\/div>\n<div class=\"extra-desc\">\n<ul>\n<li>\u00a01 x Diffuseur<\/li>\n<li>\u00a01 x Flacon FELIWAY <i>Friends<\/i>\u00a048 ml<\/li>\n<\/ul>\n<p>Facile d&#8217;utilisation :<\/h3>\n<\/div>\n<div class=\"product_block_content\">\n<ol>\n<li>Branchez le diffuseur sur une prise \u00e9lectrique.<\/li>\n<li>Laissez le diffuseur allum\u00e9 en permanence afin de pr\u00e9server la bonne entente entre vos chats.<\/li>\n<li>Remplacez la recharge tous les 30 jours au besoin.<\/li>\n<\/ol>\n<div class=\"product_block_content\">\n<ul>\n<li style=\"list-style-type: none;\"><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>FELIWAY\u00a0<em>Friends<\/em>\u00a0est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:<\/strong><\/p>\n<ul>\n<li><span data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:8,&quot;2&quot;:{&quot;6&quot;:1}}\uee10{&quot;1&quot;:16}\" data-sheets-userformat=\"{&quot;2&quot;:897,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;FELIWAY Friends est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:&quot;}\">Bagarres<\/span><\/li>\n<li><span data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:8,&quot;2&quot;:{&quot;6&quot;:1}}\uee10{&quot;1&quot;:16}\" data-sheets-userformat=\"{&quot;2&quot;:897,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;FELIWAY Friends est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:&quot;}\">Courses-poursuites<\/span><\/li>\n<li><span data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:8,&quot;2&quot;:{&quot;6&quot;:1}}\uee10{&quot;1&quot;:16}\" data-sheets-userformat=\"{&quot;2&quot;:897,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;FELIWAY Friends est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:&quot;}\">Obstructions<\/span><\/li>\n<li><span data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:8,&quot;2&quot;:{&quot;6&quot;:1}}\uee10{&quot;1&quot;:16}\" data-sheets-userformat=\"{&quot;2&quot;:897,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;FELIWAY Friends est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:&quot;}\">Intimidations<\/span><\/li>\n<\/ul>\n<p><span data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:8,&quot;2&quot;:{&quot;6&quot;:1}}\uee10{&quot;1&quot;:16}\" data-sheets-userformat=\"{&quot;2&quot;:899,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:3,&quot;3&quot;:6},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;FELIWAY Friends aide vos chats \u00e0 mieux s\u2019entendre \u00e0 la maison. Son effet continu assure une bonne entente permanente.&quot;}\">FELIWAY\u00a0<em>Friends<\/em>\u00a0aide vos chats \u00e0 mieux s\u2019entendre \u00e0 la maison. Son effet continu assure une bonne entente permanente.<\/span><\/p>\n<div class=\"extra-desc\">Jusqu&#8217;\u00e0\u00a0<b>30 jours<\/b>\u00a0d&#8217;harmonie entre les chats<\/div>\n","protected":false},"featured_media":690424,"template":"","meta":[],"product_cat":[2759,2697,12567],"product_tag":[],"class_list":["post-95960","product","type-product","status-publish","has-post-thumbnail","product_cat-anti-stress-et-anxiete-pour-chat","product_cat-chat","product_cat-produit-veterinaire-du-chat","pa_marque-ceva","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feliway Friends Ceva - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"FELIWAY\u00a0Friends\u00a0est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:   Bagarres  Courses-poursuites  Obstructions  Intimidations  FELIWAY\u00a0Friends\u00a0aide vos chats \u00e0 mieux s\u2019entendre \u00e0 la maison. Son effet continu assure une bonne entente permanente. Jusqu&#039;\u00e0\u00a030 jours\u00a0d&#039;harmonie entre les chats\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feliway Friends Ceva - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"FELIWAY\u00a0Friends\u00a0est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:   Bagarres  Courses-poursuites  Obstructions  Intimidations  FELIWAY\u00a0Friends\u00a0aide vos chats \u00e0 mieux s\u2019entendre \u00e0 la maison. Son effet continu assure une bonne entente permanente. Jusqu&#039;\u00e0\u00a030 jours\u00a0d&#039;harmonie entre les chats\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/feliway-friends\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-06T09:48:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/FELIWAY_Friends_Carousel1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/firminy-42700\\\/boutique\\\/product\\\/feliway-friends\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/firminy-42700\\\/boutique\\\/product\\\/feliway-friends\\\/\",\"name\":\"Feliway Friends Ceva - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/firminy-42700\\\/boutique\\\/product\\\/feliway-friends\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/firminy-42700\\\/boutique\\\/product\\\/feliway-friends\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/FELIWAY_Friends_Carousel1.png\",\"datePublished\":\"2020-06-29T15:28:47+00:00\",\"dateModified\":\"2026-08-06T09:48:05+00:00\",\"description\":\"FELIWAY\u00a0Friends\u00a0est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats: Bagarres Courses-poursuites Obstructions Intimidations FELIWAY\u00a0Friends\u00a0aide vos chats \u00e0 mieux s\u2019entendre \u00e0 la maison. Son effet continu assure une bonne entente permanente. Jusqu'\u00e0\u00a030 jours\u00a0d'harmonie entre les chats\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/firminy-42700\\\/boutique\\\/product\\\/feliway-friends\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/firminy-42700\\\/boutique\\\/product\\\/feliway-friends\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/firminy-42700\\\/boutique\\\/product\\\/feliway-friends\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/FELIWAY_Friends_Carousel1.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/FELIWAY_Friends_Carousel1.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/firminy-42700\\\/boutique\\\/product\\\/feliway-friends\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Feliway Friends\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Ceva\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feliway Friends Ceva - V\u00e9torino","description":"FELIWAY\u00a0Friends\u00a0est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:   Bagarres  Courses-poursuites  Obstructions  Intimidations  FELIWAY\u00a0Friends\u00a0aide vos chats \u00e0 mieux s\u2019entendre \u00e0 la maison. Son effet continu assure une bonne entente permanente. Jusqu'\u00e0\u00a030 jours\u00a0d'harmonie entre les chats","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Feliway Friends Ceva - V\u00e9torino","og_description":"FELIWAY\u00a0Friends\u00a0est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats:   Bagarres  Courses-poursuites  Obstructions  Intimidations  FELIWAY\u00a0Friends\u00a0aide vos chats \u00e0 mieux s\u2019entendre \u00e0 la maison. Son effet continu assure une bonne entente permanente. Jusqu'\u00e0\u00a030 jours\u00a0d'harmonie entre les chats","og_url":"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/feliway-friends\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-08-06T09:48:05+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/FELIWAY_Friends_Carousel1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/firminy-42700\/boutique\/product\/feliway-friends\/","url":"https:\/\/www.vetorino.com\/veterinaire\/firminy-42700\/boutique\/product\/feliway-friends\/","name":"Feliway Friends Ceva - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/firminy-42700\/boutique\/product\/feliway-friends\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/firminy-42700\/boutique\/product\/feliway-friends\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/FELIWAY_Friends_Carousel1.png","datePublished":"2020-06-29T15:28:47+00:00","dateModified":"2026-08-06T09:48:05+00:00","description":"FELIWAY\u00a0Friends\u00a0est une solution facile d\u2019utilisation pour r\u00e9duire les signes de conflits entre vos chats: Bagarres Courses-poursuites Obstructions Intimidations FELIWAY\u00a0Friends\u00a0aide vos chats \u00e0 mieux s\u2019entendre \u00e0 la maison. Son effet continu assure une bonne entente permanente. Jusqu'\u00e0\u00a030 jours\u00a0d'harmonie entre les chats","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/firminy-42700\/boutique\/product\/feliway-friends\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/firminy-42700\/boutique\/product\/feliway-friends\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/firminy-42700\/boutique\/product\/feliway-friends\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/FELIWAY_Friends_Carousel1.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/FELIWAY_Friends_Carousel1.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/firminy-42700\/boutique\/product\/feliway-friends\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Feliway Friends"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Ceva","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/wp-json\/wp\/v2\/product\/95960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/wp-json\/wp\/v2\/media\/690424"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/wp-json\/wp\/v2\/media?parent=95960"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/wp-json\/wp\/v2\/product_cat?post=95960"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/wp-json\/wp\/v2\/product_tag?post=95960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}