{"id":296450,"date":"2022-02-21T09:42:39","date_gmt":"2022-02-21T08:42:39","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=296450"},"modified":"2024-08-08T17:22:27","modified_gmt":"2024-08-08T15:22:27","slug":"obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/","title":{"rendered":"Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes !"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"296450\" class=\"elementor elementor-296450\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54ceb411 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54ceb411\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5fd6e35e\" data-id=\"5fd6e35e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59aa04a6 elementor-widget elementor-widget-text-editor\" data-id=\"59aa04a6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><h2 class=\"wp-block-heading\">Identifier les signes de surpoids et d&#8217;ob\u00e9sit\u00e9 chez le chien et le chat<\/h2><p><\/p><p><\/p><p>Lorsque l\u2019on sait qu\u2019<strong>un tiers des animaux sont en surpoids<\/strong>, cela alerte. Il vaut mieux pr\u00e9venir que gu\u00e9rir ! <strong>Savoir identifier les signes de surpoids et d\u2019ob\u00e9sit\u00e9 chez le chien et le chat<\/strong> est indispensable.<\/p><p>Si de multiples causes entrent en jeu dans le surpoids, <strong>l\u2019ob\u00e9sit\u00e9 chez le chien et le chat<\/strong>, le probl\u00e8me majeur est l\u2019<strong>alimentation<\/strong>. En effet, beaucoup de propri\u00e9taires d\u2019animaux de compagnie pensent que la nourriture est synonyme d\u2019amour. De ce fait, ils suralimentent leur <strong>chien<\/strong> ou <strong>chat<\/strong>. Ils ne se rendent pas toujours compte mais au fur et \u00e0 mesure de ces quelques doses en trop, l\u2019animal va <strong>prendre du poids<\/strong> et cela va influer sur son bien-\u00eatre, entra\u00eener des pathologies\u2026<\/p><p><\/p><p><\/p><h2 class=\"has-text-align-left wp-block-heading\">Comment savoir le poids id\u00e9al de son chat ou de son chien ?<\/h2><p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-296477 alignleft\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-169x300.jpg\" alt=\"Comment savoir le poids id\u00e9al de son chat ou de son chien ?\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-169x300.jpg 169w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-576x1024.jpg 576w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-768x1365.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-864x1536.jpg 864w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-1152x2048.jpg 1152w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-555x987.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-64x114.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg 1440w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/p><p><\/p><p><\/p><p>Faites attention, chaque animal est singulier et a son propre <strong>poids id\u00e9al<\/strong>. Il est donc indispensable de consulter votre v\u00e9t\u00e9rinaire pour calculer avec pr\u00e9cision l\u2019<strong>IMC<\/strong> \u2013 indice de masse corporelle \u2013 de votre chien ou de votre chien. Cet IMC est cl\u00e9 pour \u00e9tablir son poids id\u00e9al. En outre, sa <strong>race<\/strong>, sa <strong>taille<\/strong> et son <strong>\u00e2ge<\/strong> comptent \u00e9galement. Une fois que vous connaissez le poids id\u00e9al de votre <strong>animal de compagnie<\/strong>, il vous sera tr\u00e8s facile d\u2019identifier s\u2019il est en <strong>surpoids<\/strong> ou a des <strong>signes d\u2019ob\u00e9sit\u00e9<\/strong>. Pour le surpoids, cela correspond \u00e0 un poids sup\u00e9rieur de <strong>15 \u00e0 20%<\/strong> par rapport \u00e0 son poids id\u00e9al. Pour l\u2019ob\u00e9sit\u00e9, c\u2019est 30 \u00e0 40% en plus de son poids id\u00e9al.<\/p><p>Ces pourcentages ne sont peut-\u00eatre pas significatifs \u00e0 proprement parler, mais traduits en chiffres, ces <strong>exc\u00e8s de poids<\/strong> sont consid\u00e9rables pour votre chien ou votre chat.<\/p><p><\/p><p><\/p><h2 class=\"has-text-align-left wp-block-heading\">Un exemple d&#8217;un exc\u00e8s de poids chez le chat<\/h2><p><\/p><p><\/p><p>Par exemple, pour un chat adulte qui p\u00e8se en moyenne 4kg, son <strong>surpoids<\/strong> correspondra \u00e0 un exc\u00e8s de poids de 800 g et son ob\u00e9sit\u00e9 \u00e0 un exc\u00e8s de poids de 1,2kg ou davantage.<\/p><p><\/p><p><\/p><p><\/p><p><\/p><h2 class=\"wp-block-heading\">Exemple d&#8217;un exc\u00e8s de poids chez un chien<\/h2><p><\/p><p><\/p><p>Pour les <strong>chiens<\/strong>, les calculs sont plus compliqu\u00e9s que pour un chat. En effet, il faut prendre en compte leur taille \u00e0 <strong>l\u2019\u00e2ge adulte<\/strong> selon la race etc. :<\/p><ul><li>Pour les <strong>chiens de petite taille<\/strong>\u00a0: leur poids doit \u00eatre inf\u00e9rieur \u00e0 10kg.<\/li><li>Pour les <strong>chiens de taille moyenne<\/strong>\u00a0: leur poids doit \u00eatre entre 11 et 25kg.<\/li><li>Pour les <strong>chiens de grande taille<\/strong>\u00a0: poids de plus de 25kg.<\/li><li>Pour les <strong>chiens de tr\u00e8s grande taille<\/strong>\u00a0: poids 40kg ou un peu plus.<\/li><\/ul><p>Il y a aussi des cas sp\u00e9cifiques.<\/p><p><\/p><p><\/p><h2 class=\"wp-block-heading\">Des illustrations sp\u00e9cifiques de surpoids chez le chien<\/h2><p><img decoding=\"async\" class=\"size-medium wp-image-296479 alignright\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/strength-gb541843e7_1920-193x300.jpg\" alt=\"Des illustrations sp\u00e9cifiques de surpoids chez le chien\" width=\"193\" height=\"300\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/strength-gb541843e7_1920-193x300.jpg 193w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/strength-gb541843e7_1920-657x1024.jpg 657w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/strength-gb541843e7_1920-768x1197.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/strength-gb541843e7_1920-986x1536.jpg 986w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/strength-gb541843e7_1920-555x865.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/strength-gb541843e7_1920-64x100.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/strength-gb541843e7_1920.jpg 1232w\" sizes=\"(max-width: 193px) 100vw, 193px\" \/><\/p><p><\/p><p><\/p><p>Pour un chien type <strong>Jack Russel<\/strong> de petite taille d\u2019un poids moyen de 7kg\u00a0: son surpoids correspond \u00e0 un exc\u00e8s de poids de 1kg et l\u2019ob\u00e9sit\u00e9 est pour un exc\u00e8s de poids de 2kg ou plus.<\/p><p>Pour un chien type <strong>Epagneul breton<\/strong> de taille moyenne et d\u2019un poids de 15kg. Le surpoids survient d\u00e8s un exc\u00e8s de poids de 2kg. Un exc\u00e8s de poids de 4kg et plus est d\u00e9j\u00e0 de l\u2019ob\u00e9sit\u00e9.<\/p><p>Pour un chien type <strong>Labrador<\/strong> de grande taille, d\u2019un poids de 30kg. Le surpoids correspond \u00e0 un exc\u00e8s de 4,5kg. L\u2019ob\u00e9sit\u00e9 correspond \u00e0 un exc\u00e8s de poids de 9kg et davantage.<\/p><p>Pour un chien type <strong>Terre Neuve<\/strong>, de taille tr\u00e8s grande et d\u2019un poids de 55kg, le surpoids est un exc\u00e8s de 8kg. <strong>L\u2019ob\u00e9sit\u00e9<\/strong> correspond \u00e0 un exc\u00e8s de poids \u00e0 partir de 16kg suppl\u00e9mentaires.<\/p><h2>Les signes de surpoids pour votre animal de compagnie<\/h2><p>Le probl\u00e8me c\u2019est que ces signes sont souvent progressifs et qu\u2019il n\u2019est pas toujours facile pour les <strong>propri\u00e9taires d\u2019animaux de compagnie<\/strong> d\u2019intervenir suffisamment en amont. Les kilos finissent par s\u2019accumuler et il peut d\u00e9j\u00e0 \u00eatre trop tard.<\/p><p>De ce fait, il est primordial que vous ameniez r\u00e9guli\u00e8rement votre <strong>chien ou votre chat<\/strong> chez le v\u00e9t\u00e9rinaire. C\u2019est un professionnel qui a l\u2019expertise et l\u2019habitude pour vous aider \u00e0 calculer, \u00e0 <strong>identifier les signes de surpoids et d\u2019ob\u00e9sit\u00e9<\/strong> chez votre animal et qui pourra vous conseiller en fonction. N\u00e9anmoins, vous pouvez vous aussi agir \u00e0 votre niveau. Caressez r\u00e9guli\u00e8rement votre <strong>animal<\/strong> sur le flanc en effectuant une petite pression. Cela vous donnera un premier signe de la condition de votre chien ou de votre chat. Vous devez <strong>pouvoir sentir ses c\u00f4tes<\/strong>. Si vous ne les sentez pas, c\u2019est que probablement la graisse s\u2019accumule.<\/p><p>En plus de ce petit test r\u00e9gulier facile \u00e0 effectuer, surveillez les signes suivants\u00a0:<\/p><ul><li>Votre animal a soudainement des sautes d\u2019humeur\u00a0;<\/li><li>Il dort plus qu\u2019auparavant\u00a0;<\/li><li>Il s\u2019essouffle plus vite\u00a0;<\/li><li>Il est plus lent, \u00e0 du mal \u00e0 se d\u00e9placer, \u00e0 marcher\u00a0;<\/li><li>Vous devez desserrer son collier<\/li><li>Sa taille ne se voit plus.<\/li><\/ul><p>Si vous d\u00e9tectez un ou plusieurs de ces signes, que vous ne sentez plus les c\u00f4tes de votre chien ou votre chat, il est certain qu\u2019il a <strong>pris du poids<\/strong> et vous devriez vite rectifier le tir.<\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e8ae50 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e8ae50\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a75c296\" data-id=\"4a75c296\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70c82694 elementor-widget elementor-widget-heading\" data-id=\"70c82694\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"line-height: 1.4;margin-top: 20px;margin-bottom: 10px;font-size: 18px;text-align: center\">S\u00e9lections de produits v\u00e9t\u00e9rinaire contre le surpoids ou l'ob\u00e9sit\u00e9 du chien et du chat<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-545ab9ab product_alcyon elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"545ab9ab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-50f16595\" data-id=\"50f16595\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-330ac7b5 elementor-widget elementor-widget-image\" data-id=\"330ac7b5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299272\" alt=\"prescription-diet-chat-metabolic-croquettes-poulet_vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-1024x1024.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-1536x1536.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino.jpg 2000w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d239308 elementor-widget elementor-widget-heading\" data-id=\"3d239308\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hill's\nMETABOLIC CROQUETTES POUR CHAT AU POULET - HILL'S PRESCRIPTION DIET<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27769b7c elementor-widget elementor-widget-text-editor\" data-id=\"27769b7c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s Prescription Diet Metabolic Weight Management est un aliment sec pour chat au poulet. Aide les chats \u00e0 perdre du poids naturellement et \u00e0 se maintenir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74236de elementor-align-center elementor-widget elementor-widget-button\" data-id=\"74236de\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/feline-metabolic\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-23c46c3a\" data-id=\"23c46c3a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aa660c7 elementor-widget elementor-widget-image\" data-id=\"3aa660c7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299274\" alt=\"dog-adult-lightsterilise-optiweight-poulet-vetorinodog-adult-lightsterilise-optiweight-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dfaceae elementor-widget elementor-widget-heading\" data-id=\"2dfaceae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PROPLAN DOG OPTIWEIGHT ALL SIZE LIGHT\/STERILISED POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c274531 elementor-widget elementor-widget-text-editor\" data-id=\"3c274531\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Purina Pro Plan All Sizes Adult Light est un aliment complet pour les chiens adultes en surpoids ou st\u00e9rilis\u00e9s de toutes tailles pour r\u00e9guler leur poids de forme.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2498c568 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2498c568\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/proplan-dog-optiweight-toutes-races-light-sterilised-poulet\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6b2dab24\" data-id=\"6b2dab24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69674484 elementor-widget elementor-widget-image\" data-id=\"69674484\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299277\" alt=\"cat-neutered-satiety-balance-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino.png 458w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-370fbedc elementor-widget elementor-widget-heading\" data-id=\"370fbedc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Royal Canin\nCAT NEUTERED SATIETY BALANCE - ROYAL CANIN VET CARE NUTRITION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b8764e elementor-widget elementor-widget-text-editor\" data-id=\"68b8764e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les croquettes Neutered Satiety Balance sont recommand\u00e9es pour les chats st\u00e9rilis\u00e9s jusqu\u2019\u00e0 7 ans. Aide \u00e0 la perte du poids de l&#8217;animal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62eb08 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"62eb08\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/vcn-cat-neutered-satiety-balance\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-54b7836c\" data-id=\"54b7836c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f277a33 elementor-widget elementor-widget-image\" data-id=\"2f277a33\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299273\" alt=\"prescription-diet-chien-metabolic-croquettes-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-1024x1024.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-1536x1536.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino.jpg 2000w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac62fb1 elementor-widget elementor-widget-heading\" data-id=\"ac62fb1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's\nMETABOLIC CROQUETTES POUR CHIEN AU POULET - HILL'S PRESCRIPTION DIET\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12e03017 elementor-widget elementor-widget-text-editor\" data-id=\"12e03017\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s Prescription Diet Metabolic Weight Management est un\u00a0 aliment sec pour chien au poulet. Aide les chiens \u00e0 perdre rapidement du poids et se maintenir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-276989d7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"276989d7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/canine-metabolic\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f709cd product_centravet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f709cd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f69cc16\" data-id=\"f69cc16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5f7cab elementor-widget elementor-widget-image\" data-id=\"c5f7cab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299272\" alt=\"prescription-diet-chat-metabolic-croquettes-poulet_vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-1024x1024.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-1536x1536.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino.jpg 2000w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27b85a2 elementor-widget elementor-widget-heading\" data-id=\"27b85a2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hill's\nMETABOLIC CROQUETTES POUR CHAT AU POULET - HILL'S PRESCRIPTION DIET<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b21016a elementor-widget elementor-widget-text-editor\" data-id=\"b21016a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s Prescription Diet Metabolic Weight Management est un aliment sec pour chat au poulet. Aide les chats \u00e0 perdre du poids naturellement et \u00e0 se maintenir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41e927a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"41e927a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/feline-metabolic\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-046443e\" data-id=\"046443e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-525d842 elementor-widget elementor-widget-image\" data-id=\"525d842\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299274\" alt=\"dog-adult-lightsterilise-optiweight-poulet-vetorinodog-adult-lightsterilise-optiweight-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdd167d elementor-widget elementor-widget-heading\" data-id=\"bdd167d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PROPLAN DOG OPTIWEIGHT ALL SIZE LIGHT\/STERILISED POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bcab50 elementor-widget elementor-widget-text-editor\" data-id=\"6bcab50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Purina Pro Plan All Sizes Adult Light est un aliment complet pour les chiens adultes en surpoids ou st\u00e9rilis\u00e9s de toutes tailles pour r\u00e9guler leur poids de forme.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fbdf77 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6fbdf77\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/dog-all-size-adult-light-sterilised-chicken-optiweight\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fe0b07f\" data-id=\"fe0b07f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3834495 elementor-widget elementor-widget-image\" data-id=\"3834495\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299277\" alt=\"cat-neutered-satiety-balance-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino.png 458w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b64bf9 elementor-widget elementor-widget-heading\" data-id=\"0b64bf9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Royal Canin\nCAT NEUTERED SATIETY BALANCE - ROYAL CANIN VET CARE NUTRITION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96a1c34 elementor-widget elementor-widget-text-editor\" data-id=\"96a1c34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les croquettes Neutered Satiety Balance sont recommand\u00e9es pour les chats st\u00e9rilis\u00e9s jusqu\u2019\u00e0 7 ans. Aide \u00e0 la perte du poids de l&#8217;animal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cde31e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6cde31e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/vet-care-nutrition-cat-neutered-satiety-balance\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-681a452\" data-id=\"681a452\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f3d98f elementor-widget elementor-widget-image\" data-id=\"7f3d98f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299273\" alt=\"prescription-diet-chien-metabolic-croquettes-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-1024x1024.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-1536x1536.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino.jpg 2000w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2438d66 elementor-widget elementor-widget-heading\" data-id=\"2438d66\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's\nMETABOLIC CROQUETTES POUR CHIEN AU POULET - HILL'S PRESCRIPTION DIET\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c61bd13 elementor-widget elementor-widget-text-editor\" data-id=\"c61bd13\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s Prescription Diet Metabolic Weight Management est un\u00a0 aliment sec pour chien au poulet. Aide les chiens \u00e0 perdre rapidement du poids et se maintenir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44fca14 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"44fca14\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/canine-metabolic-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b1be8af product_coveto elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b1be8af\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b410c0a\" data-id=\"b410c0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c313578 elementor-widget elementor-widget-image\" data-id=\"c313578\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299272\" alt=\"prescription-diet-chat-metabolic-croquettes-poulet_vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-1024x1024.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-1536x1536.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chat-metabolic-croquettes-poulet_vetorino.jpg 2000w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fe5107 elementor-widget elementor-widget-heading\" data-id=\"4fe5107\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hill's\nMETABOLIC CROQUETTES POUR CHAT AU POULET - HILL'S PRESCRIPTION DIET<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d89654 elementor-widget elementor-widget-text-editor\" data-id=\"2d89654\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s Prescription Diet Metabolic Weight Management est un aliment sec pour chat au poulet. Aide les chats \u00e0 perdre du poids naturellement et \u00e0 se maintenir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1f4f30 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e1f4f30\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/feline-metabolic\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5b05ad2\" data-id=\"5b05ad2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09814d6 elementor-widget elementor-widget-image\" data-id=\"09814d6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299274\" alt=\"dog-adult-lightsterilise-optiweight-poulet-vetorinodog-adult-lightsterilise-optiweight-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-adult-lightsterilise-optiweight-poulet-vetorino.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a41371e elementor-widget elementor-widget-heading\" data-id=\"a41371e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PROPLAN DOG OPTIWEIGHT ALL SIZE LIGHT\/STERILISED POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-911c4d4 elementor-widget elementor-widget-text-editor\" data-id=\"911c4d4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Purina Pro Plan All Sizes Adult Light est un aliment complet pour les chiens adultes en surpoids ou st\u00e9rilis\u00e9s de toutes tailles pour r\u00e9guler leur poids de forme.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3a5232 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c3a5232\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/dog-all-size-adult-light-sterilised-chicken-optiweight-sac-de-14-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e670216\" data-id=\"e670216\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84a00b4 elementor-widget elementor-widget-image\" data-id=\"84a00b4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299277\" alt=\"cat-neutered-satiety-balance-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-neutered-satiety-balance-vetorino.png 458w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1c13f2 elementor-widget elementor-widget-heading\" data-id=\"f1c13f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Royal Canin\nCAT NEUTERED SATIETY BALANCE - ROYAL CANIN VET CARE NUTRITION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38e46c9 elementor-widget elementor-widget-text-editor\" data-id=\"38e46c9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les croquettes Neutered Satiety Balance sont recommand\u00e9es pour les chats st\u00e9rilis\u00e9s jusqu\u2019\u00e0 7 ans. Aide \u00e0 la perte du poids de l&#8217;animal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bab534e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bab534e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/vet-care-nutrition-cat-neutered-satiety-balance-sac-de-12-kg-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ea8f00d\" data-id=\"ea8f00d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4508222 elementor-widget elementor-widget-image\" data-id=\"4508222\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299273\" alt=\"prescription-diet-chien-metabolic-croquettes-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-1024x1024.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-1536x1536.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prescription-diet-chien-metabolic-croquettes-poulet-vetorino.jpg 2000w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5da5cb elementor-widget elementor-widget-heading\" data-id=\"f5da5cb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's\nMETABOLIC CROQUETTES POUR CHIEN AU POULET - HILL'S PRESCRIPTION DIET\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ad8485 elementor-widget elementor-widget-text-editor\" data-id=\"9ad8485\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s Prescription Diet Metabolic Weight Management est un\u00a0 aliment sec pour chien au poulet. Aide les chiens \u00e0 perdre rapidement du poids et se maintenir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-297afc8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"297afc8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/drocourt-78440\/boutique\/product\/canine-metabolic-sac-de-15-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34974802 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34974802\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d660de8\" data-id=\"7d660de8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40701123 elementor-widget elementor-widget-text-editor\" data-id=\"40701123\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"color: #078ed2;text-align: center\"><a href=\"https:\/\/www.vetorino.com\/boutique\/?s=weight&amp;post_type=product\">D\u00e9couvrez notre s\u00e9lection de produits sp\u00e9cialement con\u00e7us pour une bonne gestion du poids de votre chien ou de votre chat <\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Identifier les signes de surpoids et d&#8217;ob\u00e9sit\u00e9 chez le chien et le chat Lorsque l\u2019on sait qu\u2019un tiers des animaux sont en surpoids, cela alerte. Il vaut mieux pr\u00e9venir que gu\u00e9rir ! Savoir identifier les signes de surpoids et d\u2019ob\u00e9sit\u00e9 chez le chien et le chat est indispensable. Si de multiples causes entrent en jeu [&hellip;]<\/p>\n","protected":false},"author":10426,"featured_media":296477,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14086,14087,14095,14094],"tags":[],"class_list":["post-296450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chat","category-chien","category-sante-et-prevention-chat","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes ! - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Cliquez ici pour d\u00e9couvrir tout concernant l&#039;ob\u00e9sit\u00e9 et surpoids du chien et du chat ! Reconna\u00eetre les signes, pr\u00e9venir le surpoids et plus !\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes ! - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Cliquez ici pour d\u00e9couvrir tout concernant l&#039;ob\u00e9sit\u00e9 et surpoids du chien et du chat ! Reconna\u00eetre les signes, pr\u00e9venir le surpoids et plus !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-21T08:42:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:22:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe V\u00e9torino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe V\u00e9torino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/\"},\"author\":{\"name\":\"Equipe V\u00e9torino\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/6c2a6631b1dafb889300d67266761861\"},\"headline\":\"Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes !\",\"datePublished\":\"2022-02-21T08:42:39+00:00\",\"dateModified\":\"2024-08-08T15:22:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/\"},\"wordCount\":1428,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg\",\"articleSection\":[\"Chat\",\"Chien\",\"Sant\u00e9 et pr\u00e9vention pour chat\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/\",\"name\":\"Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes ! - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg\",\"datePublished\":\"2022-02-21T08:42:39+00:00\",\"dateModified\":\"2024-08-08T15:22:27+00:00\",\"description\":\"Cliquez ici pour d\u00e9couvrir tout concernant l'ob\u00e9sit\u00e9 et surpoids du chien et du chat ! Reconna\u00eetre les signes, pr\u00e9venir le surpoids et plus !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg\",\"width\":1440,\"height\":2560,\"caption\":\"Comment savoir le poids id\u00e9al de son chat ou de son chien ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/21\\\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sant\u00e9 et pr\u00e9vention pour chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/category\\\/chat\\\/sante-et-prevention-chat\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/6c2a6631b1dafb889300d67266761861\",\"name\":\"Equipe V\u00e9torino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"caption\":\"Equipe V\u00e9torino\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/rungis-94150\\\/boutique\\\/author\\\/equipe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes ! - V\u00e9torino","description":"Cliquez ici pour d\u00e9couvrir tout concernant l'ob\u00e9sit\u00e9 et surpoids du chien et du chat ! Reconna\u00eetre les signes, pr\u00e9venir le surpoids et plus !","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes ! - V\u00e9torino","og_description":"Cliquez ici pour d\u00e9couvrir tout concernant l'ob\u00e9sit\u00e9 et surpoids du chien et du chat ! Reconna\u00eetre les signes, pr\u00e9venir le surpoids et plus !","og_url":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2022-02-21T08:42:39+00:00","article_modified_time":"2024-08-08T15:22:27+00:00","og_image":[{"width":1440,"height":2560,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Equipe V\u00e9torino","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Equipe V\u00e9torino","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/"},"author":{"name":"Equipe V\u00e9torino","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/6c2a6631b1dafb889300d67266761861"},"headline":"Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes !","datePublished":"2022-02-21T08:42:39+00:00","dateModified":"2024-08-08T15:22:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/"},"wordCount":1428,"commentCount":0,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg","articleSection":["Chat","Chien","Sant\u00e9 et pr\u00e9vention pour chat","Sant\u00e9 pour chien"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/","url":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/","name":"Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes ! - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg","datePublished":"2022-02-21T08:42:39+00:00","dateModified":"2024-08-08T15:22:27+00:00","description":"Cliquez ici pour d\u00e9couvrir tout concernant l'ob\u00e9sit\u00e9 et surpoids du chien et du chat ! Reconna\u00eetre les signes, pr\u00e9venir le surpoids et plus !","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/parichat-chk-GwrtD96KoJQ-unsplash-scaled.jpg","width":1440,"height":2560,"caption":"Comment savoir le poids id\u00e9al de son chat ou de son chien ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/21\/obesite-et-surpoids-du-chien-et-du-chat-reconnaitre-les-signes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"Sant\u00e9 et pr\u00e9vention pour chat","item":"https:\/\/www.vetorino.com\/boutique\/category\/chat\/sante-et-prevention-chat\/"},{"@type":"ListItem","position":4,"name":"Ob\u00e9sit\u00e9 et surpoids du chien et du chat : Reconna\u00eetre les signes !"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/6c2a6631b1dafb889300d67266761861","name":"Equipe V\u00e9torino","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","caption":"Equipe V\u00e9torino"},"url":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/author\/equipe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/posts\/296450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/users\/10426"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/comments?post=296450"}],"version-history":[{"count":44,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/posts\/296450\/revisions"}],"predecessor-version":[{"id":301318,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/posts\/296450\/revisions\/301318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/media\/296477"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/media?parent=296450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/categories?post=296450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/tags?post=296450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}