{"id":98070,"date":"2020-06-29T22:58:38","date_gmt":"2020-06-29T20:58:38","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/"},"modified":"2025-02-21T23:26:55","modified_gmt":"2025-02-21T22:26:55","slug":"jouet-latex-pour-chien-oeuf-pop-up","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/","title":{"rendered":"Jouet latex pour chien : Oeuf Pop-Up"},"content":{"rendered":"<p>En latex. Sympa le poussin appara\u00eet lorsqu&#8217;on appuie sur l&#8217;\u0152uf&#8230; un petit jeu de cache-cache qui fascinera votre chien !<br \/>\nColoris assortis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cet \u0153uf \u00ab Pop up \u00bb aux couleurs p\u00e9tantes contient un poussin \u00e0 l\u2019int\u00e9rieur. En le mordillant, votre chien va faire sortir le petit poussin de sa coquille. Une vraie surprise pour votre toutou qui va vite avoir envie de recommencer pour revoir son nouveau petit camarade !<\/p>\n","protected":false},"featured_media":620899,"template":"","meta":[],"product_cat":[12550,2698,12621],"product_tag":[],"class_list":{"0":"post-98070","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-du-chien","7":"product_cat-chien","8":"product_cat-jeux-educatifs-pour-chien","9":"pa_marque-karlie","11":"first","12":"outofstock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jouet latex pour chien : Oeuf Pop-Up Karlie - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Cet \u0153uf \u00ab Pop up \u00bb aux couleurs p\u00e9tantes contient un poussin \u00e0 l\u2019int\u00e9rieur. En le mordillant, votre chien va faire sortir le petit poussin de sa coquille. Une vraie surprise pour votre toutou qui va vite avoir envie de recommencer pour revoir son nouveau petit camarade !\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jouet latex pour chien : Oeuf Pop-Up Karlie - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Cet \u0153uf \u00ab Pop up \u00bb aux couleurs p\u00e9tantes contient un poussin \u00e0 l\u2019int\u00e9rieur. En le mordillant, votre chien va faire sortir le petit poussin de sa coquille. Une vraie surprise pour votre toutou qui va vite avoir envie de recommencer pour revoir son nouveau petit camarade !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-21T22:26:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/1031795_E_01_1000x.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"5,11&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"Rupture de stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-latex-pour-chien-oeuf-pop-up\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-latex-pour-chien-oeuf-pop-up\\\/\",\"name\":\"Jouet latex pour chien : Oeuf Pop-Up Karlie - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-latex-pour-chien-oeuf-pop-up\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-latex-pour-chien-oeuf-pop-up\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1031795_E_01_1000x.png\",\"datePublished\":\"2020-06-29T20:58:38+00:00\",\"dateModified\":\"2025-02-21T22:26:55+00:00\",\"description\":\"Cet \u0153uf \u00ab Pop up \u00bb aux couleurs p\u00e9tantes contient un poussin \u00e0 l\u2019int\u00e9rieur. En le mordillant, votre chien va faire sortir le petit poussin de sa coquille. Une vraie surprise pour votre toutou qui va vite avoir envie de recommencer pour revoir son nouveau petit camarade !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-latex-pour-chien-oeuf-pop-up\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-latex-pour-chien-oeuf-pop-up\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-latex-pour-chien-oeuf-pop-up\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1031795_E_01_1000x.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1031795_E_01_1000x.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-latex-pour-chien-oeuf-pop-up\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jouet latex pour chien : Oeuf Pop-Up\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Karlie\" \/>\n<meta property=\"product:price:amount\" content=\"5.11\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-JOU771\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jouet latex pour chien : Oeuf Pop-Up Karlie - V\u00e9torino","description":"Cet \u0153uf \u00ab Pop up \u00bb aux couleurs p\u00e9tantes contient un poussin \u00e0 l\u2019int\u00e9rieur. En le mordillant, votre chien va faire sortir le petit poussin de sa coquille. Une vraie surprise pour votre toutou qui va vite avoir envie de recommencer pour revoir son nouveau petit camarade !","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Jouet latex pour chien : Oeuf Pop-Up Karlie - V\u00e9torino","og_description":"Cet \u0153uf \u00ab Pop up \u00bb aux couleurs p\u00e9tantes contient un poussin \u00e0 l\u2019int\u00e9rieur. En le mordillant, votre chien va faire sortir le petit poussin de sa coquille. Une vraie surprise pour votre toutou qui va vite avoir envie de recommencer pour revoir son nouveau petit camarade !","og_url":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-02-21T22:26:55+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/1031795_E_01_1000x.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"5,11&euro;","Disponibilit\u00e9":"Rupture de stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/","name":"Jouet latex pour chien : Oeuf Pop-Up Karlie - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/1031795_E_01_1000x.png","datePublished":"2020-06-29T20:58:38+00:00","dateModified":"2025-02-21T22:26:55+00:00","description":"Cet \u0153uf \u00ab Pop up \u00bb aux couleurs p\u00e9tantes contient un poussin \u00e0 l\u2019int\u00e9rieur. En le mordillant, votre chien va faire sortir le petit poussin de sa coquille. Une vraie surprise pour votre toutou qui va vite avoir envie de recommencer pour revoir son nouveau petit camarade !","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/1031795_E_01_1000x.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/1031795_E_01_1000x.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-latex-pour-chien-oeuf-pop-up\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Jouet latex pour chien : Oeuf Pop-Up"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Karlie","product_price_amount":"5.11","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"C-JOU771","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/product\/98070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/media\/620899"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/media?parent=98070"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/product_cat?post=98070"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/product_tag?post=98070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}