{"id":98494,"date":"2020-06-30T01:06:36","date_gmt":"2020-06-29T23:06:36","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/kong-jumbler-ball\/"},"modified":"2026-05-12T02:59:09","modified_gmt":"2026-05-12T00:59:09","slug":"kong-jumbler-ball","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/product\/kong-jumbler-ball\/","title":{"rendered":"Kong Jumbler Ball"},"content":{"rendered":"<p>Le <strong>KONG Jumbler<\/strong> est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter. Disponible en \u00a0deux tailles diff\u00e9rentes, le KONG Jumbler garantit des parties de jeu dynamiques entre vous et votre chien.<\/p>\n<ul>\n<li>Le couineur et la balle int\u00e9rieure mobile incitent au jeu<\/li>\n<li>Id\u00e9al pour s\u2019amuser de mani\u00e8re interactive<\/li>\n<li>Les poignets du jouet permettent de le ramasser et de le secouer facilement<\/li>\n<li>Disponible en deux tailles : moyen\/grand et grand\/extra grand<\/li>\n<li>Couleur vari\u00e9e en fonction arrivage fournisseur<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le <strong>KONG Jumbler<\/strong> est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":76636,"template":"","meta":[],"product_cat":[12550,2698,12621],"product_tag":[],"class_list":{"0":"post-98494","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-du-chien","7":"product_cat-chien","8":"product_cat-jeux-educatifs-pour-chien","9":"pa_marque-kong","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kong Jumbler Ball Kong - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter.  &nbsp;\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kong Jumbler Ball Kong - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter.  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/product\/kong-jumbler-ball\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T00:59:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/balle-jumbler-medium-large-chien-72.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-jumbler-ball\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-jumbler-ball\\\/\",\"name\":\"Kong Jumbler Ball Kong - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-jumbler-ball\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-jumbler-ball\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/balle-jumbler-medium-large-chien-72.jpg\",\"datePublished\":\"2020-06-29T23:06:36+00:00\",\"dateModified\":\"2026-05-12T00:59:09+00:00\",\"description\":\"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\\\/rapporter. &nbsp;\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-jumbler-ball\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-jumbler-ball\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-jumbler-ball\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/balle-jumbler-medium-large-chien-72.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/balle-jumbler-medium-large-chien-72.jpg\",\"width\":700,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-jumbler-ball\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kong Jumbler Ball\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Kong\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kong Jumbler Ball Kong - V\u00e9torino","description":"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter.  &nbsp;","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Kong Jumbler Ball Kong - V\u00e9torino","og_description":"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter.  &nbsp;","og_url":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/product\/kong-jumbler-ball\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-05-12T00:59:09+00:00","og_image":[{"width":700,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/balle-jumbler-medium-large-chien-72.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-jumbler-ball\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/kong-jumbler-ball\/","name":"Kong Jumbler Ball Kong - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-jumbler-ball\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-jumbler-ball\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/balle-jumbler-medium-large-chien-72.jpg","datePublished":"2020-06-29T23:06:36+00:00","dateModified":"2026-05-12T00:59:09+00:00","description":"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter. &nbsp;","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-jumbler-ball\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/kong-jumbler-ball\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-jumbler-ball\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/balle-jumbler-medium-large-chien-72.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/balle-jumbler-medium-large-chien-72.jpg","width":700,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-jumbler-ball\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Kong Jumbler Ball"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Kong","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/product\/98494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/media\/76636"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/media?parent=98494"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/product_cat?post=98494"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/rungis-94150\/boutique\/wp-json\/wp\/v2\/product_tag?post=98494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}