{"id":101647,"date":"2020-06-30T11:50:00","date_gmt":"2020-06-30T09:50:00","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/rumi-c3\/"},"modified":"2026-07-08T09:41:21","modified_gmt":"2026-07-08T07:41:21","slug":"rumi-c3","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/rumi-c3\/","title":{"rendered":"Rumi C3"},"content":{"rendered":"<p>Aliment compl\u00e9mentaire pr\u00e9conis\u00e9 <strong>pour la relance de la digestion et de la motricit\u00e9 du rumen<\/strong> lors de troubles gastriques et m\u00e9taboliques<\/p>\n<p class=\"title\"><strong>Conseils et Recommandations<\/strong><\/p>\n<ul>\n<li><em>Bovins adultes : 1 sachet matin et soir, pendant 2 jours. Diluer 1 sachet dans un volume d&#8217;eau adapt\u00e9 (300 \u00e0 500 ml), m\u00e9langer \u00e0 l&#8217;aide d&#8217;un fouet et administrer au pistolet doseur.<\/em><\/li>\n<li><em>Ovins et caprins adultes : 1\/4 sachet matin et soir, pendant 2 jours. Diluer la dose dans 100 mL d&#8217;eau, m\u00e9langer \u00e0 l&#8217;aide d&#8217;un fouet et administrer au pistolet doseur.<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Aliment compl\u00e9mentaire pr\u00e9conis\u00e9 <strong>pour la relance de la digestion et de la motricit\u00e9 du rumen<\/strong> lors de troubles gastriques et m\u00e9taboliques<\/p>\n<p class=\"title\"><strong>Conseils et Recommandations<\/strong><\/p>\n<ul>\n<li><em>Bovins adultes : 1 sachet matin et soir, pendant 2 jours. Diluer 1 sachet dans un volume d&#8217;eau adapt\u00e9 (300 \u00e0 500 ml), m\u00e9langer \u00e0 l&#8217;aide d&#8217;un fouet et administrer au pistolet doseur.<\/em><\/li>\n<li><em>Ovins et caprins adultes : 1\/4 sachet matin et soir, pendant 2 jours. Diluer la dose dans 100 mL d&#8217;eau, m\u00e9langer \u00e0 l&#8217;aide d&#8217;un fouet et administrer au pistolet doseur.<\/em><\/li>\n<\/ul>\n","protected":false},"featured_media":904082,"template":"","meta":[],"product_cat":[6864,6870,6871,6873],"product_tag":[],"class_list":{"0":"post-101647","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-animaux-delevage","7":"product_cat-bovins","8":"product_cat-caprins","9":"product_cat-ovins","10":"pa_marque-savetis","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rumi C3 Savetis - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Aliment compl\u00e9mentaire pr\u00e9conis\u00e9 pour la relance de la digestion et de la motricit\u00e9 du rumen lors de troubles gastriques et m\u00e9taboliques Conseils et Recommandations    Bovins adultes : 1 sachet matin et soir, pendant 2 jours. Diluer 1 sachet dans un volume d&#039;eau adapt\u00e9 (300 \u00e0 500 ml), m\u00e9langer \u00e0 l&#039;aide d&#039;un fouet et administrer au pistolet doseur.  Ovins et caprins adultes : 1\/4 sachet matin et soir, pendant 2 jours. Diluer la dose dans 100 mL d&#039;eau, m\u00e9langer \u00e0 l&#039;aide d&#039;un fouet et administrer au pistolet doseur.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rumi C3 Savetis - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Aliment compl\u00e9mentaire pr\u00e9conis\u00e9 pour la relance de la digestion et de la motricit\u00e9 du rumen lors de troubles gastriques et m\u00e9taboliques Conseils et Recommandations    Bovins adultes : 1 sachet matin et soir, pendant 2 jours. Diluer 1 sachet dans un volume d&#039;eau adapt\u00e9 (300 \u00e0 500 ml), m\u00e9langer \u00e0 l&#039;aide d&#039;un fouet et administrer au pistolet doseur.  Ovins et caprins adultes : 1\/4 sachet matin et soir, pendant 2 jours. Diluer la dose dans 100 mL d&#039;eau, m\u00e9langer \u00e0 l&#039;aide d&#039;un fouet et administrer au pistolet doseur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/rumi-c3\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T07:41:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/SAVETIS-1807410-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"443\" \/>\n\t<meta property=\"og:image:height\" content=\"564\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/rumi-c3\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/rumi-c3\\\/\",\"name\":\"Rumi C3 Savetis - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/rumi-c3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/rumi-c3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/SAVETIS-1807410-2.png\",\"datePublished\":\"2020-06-30T09:50:00+00:00\",\"dateModified\":\"2026-07-08T07:41:21+00:00\",\"description\":\"Aliment compl\u00e9mentaire pr\u00e9conis\u00e9 pour la relance de la digestion et de la motricit\u00e9 du rumen lors de troubles gastriques et m\u00e9taboliques Conseils et Recommandations Bovins adultes : 1 sachet matin et soir, pendant 2 jours. Diluer 1 sachet dans un volume d'eau adapt\u00e9 (300 \u00e0 500 ml), m\u00e9langer \u00e0 l'aide d'un fouet et administrer au pistolet doseur. Ovins et caprins adultes : 1\\\/4 sachet matin et soir, pendant 2 jours. Diluer la dose dans 100 mL d'eau, m\u00e9langer \u00e0 l'aide d'un fouet et administrer au pistolet doseur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/rumi-c3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/rumi-c3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/rumi-c3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/SAVETIS-1807410-2.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/SAVETIS-1807410-2.png\",\"width\":443,\"height\":564},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/rumi-c3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rumi C3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Savetis\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rumi C3 Savetis - V\u00e9torino","description":"Aliment compl\u00e9mentaire pr\u00e9conis\u00e9 pour la relance de la digestion et de la motricit\u00e9 du rumen lors de troubles gastriques et m\u00e9taboliques Conseils et Recommandations    Bovins adultes : 1 sachet matin et soir, pendant 2 jours. Diluer 1 sachet dans un volume d'eau adapt\u00e9 (300 \u00e0 500 ml), m\u00e9langer \u00e0 l'aide d'un fouet et administrer au pistolet doseur.  Ovins et caprins adultes : 1\/4 sachet matin et soir, pendant 2 jours. Diluer la dose dans 100 mL d'eau, m\u00e9langer \u00e0 l'aide d'un fouet et administrer au pistolet doseur.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Rumi C3 Savetis - V\u00e9torino","og_description":"Aliment compl\u00e9mentaire pr\u00e9conis\u00e9 pour la relance de la digestion et de la motricit\u00e9 du rumen lors de troubles gastriques et m\u00e9taboliques Conseils et Recommandations    Bovins adultes : 1 sachet matin et soir, pendant 2 jours. Diluer 1 sachet dans un volume d'eau adapt\u00e9 (300 \u00e0 500 ml), m\u00e9langer \u00e0 l'aide d'un fouet et administrer au pistolet doseur.  Ovins et caprins adultes : 1\/4 sachet matin et soir, pendant 2 jours. Diluer la dose dans 100 mL d'eau, m\u00e9langer \u00e0 l'aide d'un fouet et administrer au pistolet doseur.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/rumi-c3\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-07-08T07:41:21+00:00","og_image":[{"width":443,"height":564,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/SAVETIS-1807410-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/rumi-c3\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/rumi-c3\/","name":"Rumi C3 Savetis - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/rumi-c3\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/rumi-c3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/SAVETIS-1807410-2.png","datePublished":"2020-06-30T09:50:00+00:00","dateModified":"2026-07-08T07:41:21+00:00","description":"Aliment compl\u00e9mentaire pr\u00e9conis\u00e9 pour la relance de la digestion et de la motricit\u00e9 du rumen lors de troubles gastriques et m\u00e9taboliques Conseils et Recommandations Bovins adultes : 1 sachet matin et soir, pendant 2 jours. Diluer 1 sachet dans un volume d'eau adapt\u00e9 (300 \u00e0 500 ml), m\u00e9langer \u00e0 l'aide d'un fouet et administrer au pistolet doseur. Ovins et caprins adultes : 1\/4 sachet matin et soir, pendant 2 jours. Diluer la dose dans 100 mL d'eau, m\u00e9langer \u00e0 l'aide d'un fouet et administrer au pistolet doseur.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/rumi-c3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/rumi-c3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/rumi-c3\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/SAVETIS-1807410-2.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/SAVETIS-1807410-2.png","width":443,"height":564},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/rumi-c3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Rumi C3"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Savetis","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product\/101647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/media\/904082"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/media?parent=101647"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product_cat?post=101647"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product_tag?post=101647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}