{"id":130254,"date":"2020-11-25T20:08:04","date_gmt":"2020-11-25T19:08:04","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/element-vet-baume-reparateur\/"},"modified":"2026-07-14T11:58:52","modified_gmt":"2026-07-14T09:58:52","slug":"element-vet-baume-reparateur","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/element-vet-baume-reparateur\/","title":{"rendered":"Baume r\u00e9parateur"},"content":{"rendered":"<p>Action protectrice et adoucissante. Gr&acirc;ce &agrave; sa texture, le Baume p&eacute;n&egrave;tre rapidement sans laisser la peau ou le poil gras.<br \/>\nR&eacute;pulsif contre les insectes volants (HE).<\/p>\n<p><strong>Toutes l&eacute;sions cutan&eacute;es <\/strong>:<\/p>\n<ul>\n<li>Coupures\/crevasses des coussinets,<\/li>\n<li>L&eacute;sions des espaces interdigitaux,<\/li>\n<li>Ecz&eacute;ma, escarres, irritations.<\/li>\n<li>Piqures,<\/li>\n<li>Plaies, br&ucirc;lures,<\/li>\n<li>Manque d&#039;hydratation ou sensibilit&eacute; des coussinets, cales de coudes,<\/li>\n<li>Coupures.<\/li>\n<\/ul>\n<p><strong>Sport canin : <\/strong>indispensable pour soigner les irritations des coussinets dues &agrave; la neige, au sel, goudron ou sols durs.<br \/>\n<strong>Pour les chevaux : <\/strong>blessure &agrave; la commissure des l&egrave;vres, au garrot, frottements &agrave; cause de la selle, du filet, des protections. S&eacute;cheresse des naseaux.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Action protectrice et adoucissante. Gr&acirc;ce &agrave; sa texture, le Baume p&eacute;n&egrave;tre rapidement sans laisser la peau ou le poil gras. R&eacute;pulsif contre les insectes volants (HE). Toutes l&eacute;sions cutan&eacute;es : Coupures\/crevasses des coussinets, L&eacute;sions des espaces interdigitaux, Ecz&eacute;ma, escarres, irritations. Piqures, Plaies, br&ucirc;lures, Manque d&#039;hydratation ou sensibilit&eacute; des coussinets, cales de coudes, Coupures. Sport canin [&hellip;]<\/p>\n","protected":false},"featured_media":130253,"template":"","meta":[],"product_cat":[12547],"product_tag":[],"class_list":{"0":"post-130254","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cheval","7":"pa_marque-element-vet","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baume r\u00e9parateur Element Vet - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Action protectrice et adoucissante. Gr&acirc;ce &agrave; sa texture, le Baume p&eacute;n&egrave;tre rapidement sans laisser la peau ou le poil gras.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baume r\u00e9parateur Element Vet - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Action protectrice et adoucissante. Gr&acirc;ce &agrave; sa texture, le Baume p&eacute;n&egrave;tre rapidement sans laisser la peau ou le poil gras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/element-vet-baume-reparateur\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T09:58:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/FilsBAU002FormatMediumTypeIM-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"21,38&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/element-vet-baume-reparateur\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/element-vet-baume-reparateur\\\/\",\"name\":\"Baume r\u00e9parateur Element Vet - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/element-vet-baume-reparateur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/element-vet-baume-reparateur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/FilsBAU002FormatMediumTypeIM-1.png\",\"datePublished\":\"2020-11-25T19:08:04+00:00\",\"dateModified\":\"2026-07-14T09:58:52+00:00\",\"description\":\"Action protectrice et adoucissante. Gr&acirc;ce &agrave; sa texture, le Baume p&eacute;n&egrave;tre rapidement sans laisser la peau ou le poil gras.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/element-vet-baume-reparateur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/element-vet-baume-reparateur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/element-vet-baume-reparateur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/FilsBAU002FormatMediumTypeIM-1.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/FilsBAU002FormatMediumTypeIM-1.png\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/element-vet-baume-reparateur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Baume r\u00e9parateur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Element Vet\" \/>\n<meta property=\"product:price:amount\" content=\"21.38\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-BAU002\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baume r\u00e9parateur Element Vet - V\u00e9torino","description":"Action protectrice et adoucissante. Gr&acirc;ce &agrave; sa texture, le Baume p&eacute;n&egrave;tre rapidement sans laisser la peau ou le poil gras.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Baume r\u00e9parateur Element Vet - V\u00e9torino","og_description":"Action protectrice et adoucissante. Gr&acirc;ce &agrave; sa texture, le Baume p&eacute;n&egrave;tre rapidement sans laisser la peau ou le poil gras.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/element-vet-baume-reparateur\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-07-14T09:58:52+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/FilsBAU002FormatMediumTypeIM-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"21,38&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/element-vet-baume-reparateur\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/element-vet-baume-reparateur\/","name":"Baume r\u00e9parateur Element Vet - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/element-vet-baume-reparateur\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/element-vet-baume-reparateur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/FilsBAU002FormatMediumTypeIM-1.png","datePublished":"2020-11-25T19:08:04+00:00","dateModified":"2026-07-14T09:58:52+00:00","description":"Action protectrice et adoucissante. Gr&acirc;ce &agrave; sa texture, le Baume p&eacute;n&egrave;tre rapidement sans laisser la peau ou le poil gras.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/element-vet-baume-reparateur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/element-vet-baume-reparateur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/element-vet-baume-reparateur\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/FilsBAU002FormatMediumTypeIM-1.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/FilsBAU002FormatMediumTypeIM-1.png","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/element-vet-baume-reparateur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Baume r\u00e9parateur"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Element Vet","product_price_amount":"21.38","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-BAU002","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product\/130254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/media\/130253"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/media?parent=130254"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product_cat?post=130254"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product_tag?post=130254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}