{"id":98992,"date":"2020-06-30T01:25:44","date_gmt":"2020-06-29T23:25:44","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/"},"modified":"2026-06-20T09:41:19","modified_gmt":"2026-06-20T07:41:19","slug":"laisse-security-2-en-1-promenade-voiture","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/","title":{"rendered":"Laisse Security 2 en 1 : promenade \/ voiture"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Double fonction : permet d&#8217;attacher son chien en voiture et de se promener en toute s\u00e9curit\u00e9.<\/p>\n<ul>\n<li>S\u00e9curit\u00e9 de l&#8217;animal : boucle s\u00e9curit\u00e9 auto int\u00e9gr\u00e9e, sangle munie de fils r\u00e9fl\u00e9chissants.<\/li>\n<li>Confort du ma\u00eetre : poign\u00e9e rembourr\u00e9e, \u00e9quip\u00e9e d&#8217;une pochette (pouvant int\u00e9grer des sacs \u00e0 d\u00e9jection), longueur r\u00e9glable.<\/li>\n<\/ul>\n<p>Conseil : utiliser cette laisse avec un harnais, de mani\u00e8re \u00e0 assurer le confort et la s\u00e9curit\u00e9 de l&#8217;animal en voiture.<\/p>\n","protected":false},"featured_media":624704,"template":"","meta":[],"product_cat":[12550,2698,2777],"product_tag":[],"class_list":{"0":"post-98992","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-du-chien","7":"product_cat-chien","8":"product_cat-colliers-laisses-et-harnais-pour-chien","9":"pa_marque-dynavet","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Laisse Security 2 en 1 : promenade \/ voiture Dynavet - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Double fonction : permet d&#039;attacher son chien en voiture et de se promener en toute s\u00e9curit\u00e9.   S\u00e9curit\u00e9 de l&#039;animal : boucle s\u00e9curit\u00e9 auto int\u00e9gr\u00e9e, sangle munie de fils r\u00e9fl\u00e9chissants.  Confort du ma\u00eetre : poign\u00e9e rembourr\u00e9e, \u00e9quip\u00e9e d&#039;une pochette (pouvant int\u00e9grer des sacs \u00e0 d\u00e9jection), longueur r\u00e9glable.  Conseil : utiliser cette laisse avec un harnais, de mani\u00e8re \u00e0 assurer le confort et la s\u00e9curit\u00e9 de l&#039;animal en voiture.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laisse Security 2 en 1 : promenade \/ voiture Dynavet - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Double fonction : permet d&#039;attacher son chien en voiture et de se promener en toute s\u00e9curit\u00e9.   S\u00e9curit\u00e9 de l&#039;animal : boucle s\u00e9curit\u00e9 auto int\u00e9gr\u00e9e, sangle munie de fils r\u00e9fl\u00e9chissants.  Confort du ma\u00eetre : poign\u00e9e rembourr\u00e9e, \u00e9quip\u00e9e d&#039;une pochette (pouvant int\u00e9grer des sacs \u00e0 d\u00e9jection), longueur r\u00e9glable.  Conseil : utiliser cette laisse avec un harnais, de mani\u00e8re \u00e0 assurer le confort et la s\u00e9curit\u00e9 de l&#039;animal en voiture.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T07:41:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/laisse-security-dynavet-securite-auto-z-908-90814.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"19,00&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/laisse-security-2-en-1-promenade-voiture\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/laisse-security-2-en-1-promenade-voiture\\\/\",\"name\":\"Laisse Security 2 en 1 : promenade \\\/ voiture Dynavet - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/laisse-security-2-en-1-promenade-voiture\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/laisse-security-2-en-1-promenade-voiture\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/laisse-security-dynavet-securite-auto-z-908-90814.webp\",\"datePublished\":\"2020-06-29T23:25:44+00:00\",\"dateModified\":\"2026-06-20T07:41:19+00:00\",\"description\":\"Double fonction : permet d'attacher son chien en voiture et de se promener en toute s\u00e9curit\u00e9. S\u00e9curit\u00e9 de l'animal : boucle s\u00e9curit\u00e9 auto int\u00e9gr\u00e9e, sangle munie de fils r\u00e9fl\u00e9chissants. Confort du ma\u00eetre : poign\u00e9e rembourr\u00e9e, \u00e9quip\u00e9e d'une pochette (pouvant int\u00e9grer des sacs \u00e0 d\u00e9jection), longueur r\u00e9glable. Conseil : utiliser cette laisse avec un harnais, de mani\u00e8re \u00e0 assurer le confort et la s\u00e9curit\u00e9 de l'animal en voiture.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/laisse-security-2-en-1-promenade-voiture\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/laisse-security-2-en-1-promenade-voiture\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/laisse-security-2-en-1-promenade-voiture\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/laisse-security-dynavet-securite-auto-z-908-90814.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/laisse-security-dynavet-securite-auto-z-908-90814.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/laisse-security-2-en-1-promenade-voiture\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Laisse Security 2 en 1 : promenade \\\/ voiture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Dynavet\" \/>\n<meta property=\"product:price:amount\" content=\"19.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-LAI645\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laisse Security 2 en 1 : promenade \/ voiture Dynavet - V\u00e9torino","description":"Double fonction : permet d'attacher son chien en voiture et de se promener en toute s\u00e9curit\u00e9.   S\u00e9curit\u00e9 de l'animal : boucle s\u00e9curit\u00e9 auto int\u00e9gr\u00e9e, sangle munie de fils r\u00e9fl\u00e9chissants.  Confort du ma\u00eetre : poign\u00e9e rembourr\u00e9e, \u00e9quip\u00e9e d'une pochette (pouvant int\u00e9grer des sacs \u00e0 d\u00e9jection), longueur r\u00e9glable.  Conseil : utiliser cette laisse avec un harnais, de mani\u00e8re \u00e0 assurer le confort et la s\u00e9curit\u00e9 de l'animal en voiture.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Laisse Security 2 en 1 : promenade \/ voiture Dynavet - V\u00e9torino","og_description":"Double fonction : permet d'attacher son chien en voiture et de se promener en toute s\u00e9curit\u00e9.   S\u00e9curit\u00e9 de l'animal : boucle s\u00e9curit\u00e9 auto int\u00e9gr\u00e9e, sangle munie de fils r\u00e9fl\u00e9chissants.  Confort du ma\u00eetre : poign\u00e9e rembourr\u00e9e, \u00e9quip\u00e9e d'une pochette (pouvant int\u00e9grer des sacs \u00e0 d\u00e9jection), longueur r\u00e9glable.  Conseil : utiliser cette laisse avec un harnais, de mani\u00e8re \u00e0 assurer le confort et la s\u00e9curit\u00e9 de l'animal en voiture.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-06-20T07:41:19+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/laisse-security-dynavet-securite-auto-z-908-90814.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"19,00&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/","name":"Laisse Security 2 en 1 : promenade \/ voiture Dynavet - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/laisse-security-dynavet-securite-auto-z-908-90814.webp","datePublished":"2020-06-29T23:25:44+00:00","dateModified":"2026-06-20T07:41:19+00:00","description":"Double fonction : permet d'attacher son chien en voiture et de se promener en toute s\u00e9curit\u00e9. S\u00e9curit\u00e9 de l'animal : boucle s\u00e9curit\u00e9 auto int\u00e9gr\u00e9e, sangle munie de fils r\u00e9fl\u00e9chissants. Confort du ma\u00eetre : poign\u00e9e rembourr\u00e9e, \u00e9quip\u00e9e d'une pochette (pouvant int\u00e9grer des sacs \u00e0 d\u00e9jection), longueur r\u00e9glable. Conseil : utiliser cette laisse avec un harnais, de mani\u00e8re \u00e0 assurer le confort et la s\u00e9curit\u00e9 de l'animal en voiture.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/laisse-security-dynavet-securite-auto-z-908-90814.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/laisse-security-dynavet-securite-auto-z-908-90814.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/laisse-security-2-en-1-promenade-voiture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Laisse Security 2 en 1 : promenade \/ voiture"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Dynavet","product_price_amount":"19.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-LAI645","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product\/98992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/media\/624704"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/media?parent=98992"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product_cat?post=98992"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product_tag?post=98992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}