{"id":99738,"date":"2020-06-30T01:35:17","date_gmt":"2020-06-29T23:35:17","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/mouxine-twenty-one\/"},"modified":"2025-11-19T02:42:20","modified_gmt":"2025-11-19T01:42:20","slug":"mouxine-twenty-one","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/mouxine-twenty-one\/","title":{"rendered":"Mouxine Twenty One"},"content":{"rendered":"<div class='hidden'>HUVEPHARMA FRANCE(QALIAN)<\/div>\n<div class='hidden'>Bovins<\/div>\n<p>Poudre insecticide mouillable pour la lutte contre les mouches adultes et les t&eacute;n&eacute;brions (adultes et larves) dans tous les b&acirc;timents d&#039;&eacute;levage.<\/p>\n<p>Dose d&#039;application pour 100 m&sup2; de surface au sol : 250 g pour les traitements contre les mouches et 500 g pour les traitements contre les t&eacute;n&eacute;brions.<br \/>\n&nbsp;<\/p>\n<ul>\n<li>Traitement contre les mouches adultes pour 100 m&sup2; au sol :<\/li>\n<\/ul>\n<p>En pulv&eacute;risation &eacute;paisse : m&eacute;langer 250 g de Mouxine Twenty One dans 2 L d&#039;eau et pulv&eacute;riser la pr&eacute;paration en r&eacute;alisant au moins 60 taches de 30x30cm sur le bas et le haut des murs (sur environ 50 cm), puis dans les angles et aux endroits o&ugrave; les mouches se posent fr&eacute;quemment (encadrements des portes et des fen&ecirc;tres, points d&rsquo;eau, murs clairs, poutres, tuyauteries, etc&hellip;). Pulv&eacute;riser hors de port&eacute;e des animaux. En badigeonnage : m&eacute;langer 250 g de Mouxine Twenty One avec&nbsp; 250 ml d&rsquo;eau ti&egrave;de jusqu&#039;&agrave; l&rsquo;obtention d&#039;une p&acirc;te suffisamment fluide pour &ecirc;tre appliqu&eacute;e. Placer au moins 60 taches de 30x30cm aux m&ecirc;mes endroits que pour la&nbsp;pulv&eacute;risation &eacute;paisse (cf. partie ci-dessus).<br \/>\n&nbsp;<\/p>\n<ul>\n<li>Traitement contre les t&eacute;n&eacute;brions (larves&nbsp;et adultes) pour 100m&sup2; au sol :<\/li>\n<\/ul>\n<p>Utiliser Mouxine Twenty One en pulv&eacute;risation pendant le vide sanitaire, apr&egrave;s mise en place de la nouvelle liti&egrave;re et avant introduction du mat&eacute;riel (abreuvoirs, mangeoires&#8230;).<br \/>\nM&eacute;langer 500 g de Mouxine Twenty One dans 10 L d&#039;eau ti&egrave;de jusqu&#039;&agrave; obtenir une solution suffisamment fluide pour &ecirc;tre pulv&eacute;ris&eacute;e.<br \/>\nPulv&eacute;riser la moiti&eacute; de la solution sous l&#039;emplacement des assiettes, sur les sous-bassement (sur une bande de 50 cm de large). Pulv&eacute;riser l&#039;autre moiti&eacute; sur l&rsquo;ensemble de la liti&egrave;re en remontant sur 50 cm en bas des murs. Ne pas traiter les endroits destin&eacute;s &agrave; recevoir les aliments ou susceptibles d&#039;&ecirc;tre l&eacute;ch&eacute;s.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HUVEPHARMA FRANCE(QALIAN) Bovins Poudre insecticide mouillable pour la lutte contre les mouches adultes et les t&eacute;n&eacute;brions (adultes et larves) dans tous les b&acirc;timents d&#039;&eacute;levage. Dose d&#039;application pour 100 m&sup2; de surface au sol : 250 g pour les traitements contre les mouches et 500 g pour les traitements contre les t&eacute;n&eacute;brions. &nbsp; Traitement contre les [&hellip;]<\/p>\n","protected":false},"featured_media":99737,"template":"","meta":[],"product_cat":[6864,6870],"product_tag":[],"class_list":{"0":"post-99738","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-animaux-delevage","7":"product_cat-bovins","8":"pa_marque-huvepharma-franceqalian","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mouxine Twenty One HUVEPHARMA FRANCE(QALIAN) - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"HUVEPHARMA FRANCE(QALIAN)BovinsPoudre insecticide mouillable pour la lutte contre les mouches adultes et les t&eacute;n&eacute;brions (adultes et larves)\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mouxine Twenty One HUVEPHARMA FRANCE(QALIAN) - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"HUVEPHARMA FRANCE(QALIAN)BovinsPoudre insecticide mouillable pour la lutte contre les mouches adultes et les t&eacute;n&eacute;brions (adultes et larves)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/mouxine-twenty-one\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T01:42:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsMOU003FormatMediumTypeIM.png\" \/>\n\t<meta property=\"og:image:width\" content=\"282\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"87,59&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/mouxine-twenty-one\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/mouxine-twenty-one\\\/\",\"name\":\"Mouxine Twenty One HUVEPHARMA FRANCE(QALIAN) - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/mouxine-twenty-one\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/mouxine-twenty-one\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsMOU003FormatMediumTypeIM.png\",\"datePublished\":\"2020-06-29T23:35:17+00:00\",\"dateModified\":\"2025-11-19T01:42:20+00:00\",\"description\":\"HUVEPHARMA FRANCE(QALIAN)BovinsPoudre insecticide mouillable pour la lutte contre les mouches adultes et les t&eacute;n&eacute;brions (adultes et larves)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/mouxine-twenty-one\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/mouxine-twenty-one\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/mouxine-twenty-one\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsMOU003FormatMediumTypeIM.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsMOU003FormatMediumTypeIM.png\",\"width\":282,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/mouxine-twenty-one\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mouxine Twenty One\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"HUVEPHARMA FRANCE(QALIAN)\" \/>\n<meta property=\"product:price:amount\" content=\"87.59\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-MOU003\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mouxine Twenty One HUVEPHARMA FRANCE(QALIAN) - V\u00e9torino","description":"HUVEPHARMA FRANCE(QALIAN)BovinsPoudre insecticide mouillable pour la lutte contre les mouches adultes et les t&eacute;n&eacute;brions (adultes et larves)","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Mouxine Twenty One HUVEPHARMA FRANCE(QALIAN) - V\u00e9torino","og_description":"HUVEPHARMA FRANCE(QALIAN)BovinsPoudre insecticide mouillable pour la lutte contre les mouches adultes et les t&eacute;n&eacute;brions (adultes et larves)","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/product\/mouxine-twenty-one\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-11-19T01:42:20+00:00","og_image":[{"width":282,"height":400,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsMOU003FormatMediumTypeIM.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"87,59&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/mouxine-twenty-one\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/mouxine-twenty-one\/","name":"Mouxine Twenty One HUVEPHARMA FRANCE(QALIAN) - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/mouxine-twenty-one\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/mouxine-twenty-one\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsMOU003FormatMediumTypeIM.png","datePublished":"2020-06-29T23:35:17+00:00","dateModified":"2025-11-19T01:42:20+00:00","description":"HUVEPHARMA FRANCE(QALIAN)BovinsPoudre insecticide mouillable pour la lutte contre les mouches adultes et les t&eacute;n&eacute;brions (adultes et larves)","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/mouxine-twenty-one\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/mouxine-twenty-one\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/mouxine-twenty-one\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsMOU003FormatMediumTypeIM.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsMOU003FormatMediumTypeIM.png","width":282,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/mouxine-twenty-one\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Mouxine Twenty One"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"HUVEPHARMA FRANCE(QALIAN)","product_price_amount":"87.59","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-MOU003","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product\/99738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/media\/99737"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/media?parent=99738"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product_cat?post=99738"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sarlat-la-caneda-24200\/boutique\/wp-json\/wp\/v2\/product_tag?post=99738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}