{"id":123353,"date":"2020-10-06T14:17:36","date_gmt":"2020-10-06T12:17:36","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/vt-phak-gouttes-oculaires-3\/"},"modified":"2023-04-06T18:32:19","modified_gmt":"2023-04-06T16:32:19","slug":"vt-phak-gouttes-oculaires-3","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/product\/vt-phak-gouttes-oculaires-3\/","title":{"rendered":"Vt Phak Gouttes Oculaires"},"content":{"rendered":"<p>Solution oculaire VT PHAK, pour chien et chat \u00e2g\u00e9, aux propri\u00e9t\u00e9s anti-oxydantes permettant de ralentir le vieillissement oculaire.<\/p>\n<div class=\"product-information\">\n<div id=\"product-description-short-5263\">\n<h5><strong>VT PHAK Gouttes Oculaires apporte \u00e0 l&#8217;oeil de l&#8217;animal \u00e2g\u00e9 les nutriments n\u00e9cessaires \u00e0 son fonctionnement.<\/strong><\/h5>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chiens et chats \u00e2g\u00e9s<\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Solution oculaire VT PHAK, pour chien et chat \u00e2g\u00e9, aux propri\u00e9t\u00e9s anti-oxydantes permettant de ralentir le vieillissement oculaire.<\/p>\n<div class=\"product-information\">\n<div id=\"product-description-short-5263\">\n<h5><strong>VT PHAK Gouttes Oculaires apporte \u00e0 l&#8217;oeil de l&#8217;animal \u00e2g\u00e9 les nutriments n\u00e9cessaires \u00e0 son fonctionnement.<\/strong><\/h5>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chiens et chats \u00e2g\u00e9s<\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"featured_media":896468,"template":"","meta":[],"product_cat":[2698,12616,12561],"product_tag":[],"class_list":{"0":"post-123353","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chien","7":"product_cat-hygiene-des-yeux-du-chien","8":"product_cat-hygiene-du-chien","9":"pa_marque-virbac","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vt Phak Gouttes Oculaires Virbac - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Solution oculaire VT PHAK, pour chien et chat \u00e2g\u00e9, aux propri\u00e9t\u00e9s anti-oxydantes permettant de ralentir le vieillissement oculaire.   VT PHAK Gouttes Oculaires apporte \u00e0 l&#039;oeil de l&#039;animal \u00e2g\u00e9 les nutriments n\u00e9cessaires \u00e0 son fonctionnement. Utilisation :   Chiens et chats \u00e2g\u00e9s\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vt Phak Gouttes Oculaires Virbac - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Solution oculaire VT PHAK, pour chien et chat \u00e2g\u00e9, aux propri\u00e9t\u00e9s anti-oxydantes permettant de ralentir le vieillissement oculaire.   VT PHAK Gouttes Oculaires apporte \u00e0 l&#039;oeil de l&#039;animal \u00e2g\u00e9 les nutriments n\u00e9cessaires \u00e0 son fonctionnement. Utilisation :   Chiens et chats \u00e2g\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/product\/vt-phak-gouttes-oculaires-3\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-06T16:32:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/vt-phak-gouttes-oculaires.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"14,44&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/vt-phak-gouttes-oculaires-3\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/vt-phak-gouttes-oculaires-3\\\/\",\"name\":\"Vt Phak Gouttes Oculaires Virbac - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/vt-phak-gouttes-oculaires-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/vt-phak-gouttes-oculaires-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/vt-phak-gouttes-oculaires.jpg\",\"datePublished\":\"2020-10-06T12:17:36+00:00\",\"dateModified\":\"2023-04-06T16:32:19+00:00\",\"description\":\"Solution oculaire VT PHAK, pour chien et chat \u00e2g\u00e9, aux propri\u00e9t\u00e9s anti-oxydantes permettant de ralentir le vieillissement oculaire. VT PHAK Gouttes Oculaires apporte \u00e0 l'oeil de l'animal \u00e2g\u00e9 les nutriments n\u00e9cessaires \u00e0 son fonctionnement. Utilisation : Chiens et chats \u00e2g\u00e9s\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/vt-phak-gouttes-oculaires-3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/vt-phak-gouttes-oculaires-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/vt-phak-gouttes-oculaires-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/vt-phak-gouttes-oculaires.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/vt-phak-gouttes-oculaires.jpg\",\"width\":540,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/vt-phak-gouttes-oculaires-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vt Phak Gouttes Oculaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Virbac\" \/>\n<meta property=\"product:price:amount\" content=\"14.44\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"O-7647\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vt Phak Gouttes Oculaires Virbac - V\u00e9torino","description":"Solution oculaire VT PHAK, pour chien et chat \u00e2g\u00e9, aux propri\u00e9t\u00e9s anti-oxydantes permettant de ralentir le vieillissement oculaire.   VT PHAK Gouttes Oculaires apporte \u00e0 l'oeil de l'animal \u00e2g\u00e9 les nutriments n\u00e9cessaires \u00e0 son fonctionnement. Utilisation :   Chiens et chats \u00e2g\u00e9s","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Vt Phak Gouttes Oculaires Virbac - V\u00e9torino","og_description":"Solution oculaire VT PHAK, pour chien et chat \u00e2g\u00e9, aux propri\u00e9t\u00e9s anti-oxydantes permettant de ralentir le vieillissement oculaire.   VT PHAK Gouttes Oculaires apporte \u00e0 l'oeil de l'animal \u00e2g\u00e9 les nutriments n\u00e9cessaires \u00e0 son fonctionnement. Utilisation :   Chiens et chats \u00e2g\u00e9s","og_url":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/product\/vt-phak-gouttes-oculaires-3\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2023-04-06T16:32:19+00:00","og_image":[{"width":540,"height":540,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/vt-phak-gouttes-oculaires.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"14,44&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/vt-phak-gouttes-oculaires-3\/","url":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/vt-phak-gouttes-oculaires-3\/","name":"Vt Phak Gouttes Oculaires Virbac - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/vt-phak-gouttes-oculaires-3\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/vt-phak-gouttes-oculaires-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/vt-phak-gouttes-oculaires.jpg","datePublished":"2020-10-06T12:17:36+00:00","dateModified":"2023-04-06T16:32:19+00:00","description":"Solution oculaire VT PHAK, pour chien et chat \u00e2g\u00e9, aux propri\u00e9t\u00e9s anti-oxydantes permettant de ralentir le vieillissement oculaire. VT PHAK Gouttes Oculaires apporte \u00e0 l'oeil de l'animal \u00e2g\u00e9 les nutriments n\u00e9cessaires \u00e0 son fonctionnement. Utilisation : Chiens et chats \u00e2g\u00e9s","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/vt-phak-gouttes-oculaires-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/vt-phak-gouttes-oculaires-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/vt-phak-gouttes-oculaires-3\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/vt-phak-gouttes-oculaires.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/vt-phak-gouttes-oculaires.jpg","width":540,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/vt-phak-gouttes-oculaires-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Vt Phak Gouttes Oculaires"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Virbac","product_price_amount":"14.44","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"O-7647","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/product\/123353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/media\/896468"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/media?parent=123353"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/product_cat?post=123353"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/product_tag?post=123353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}