{"id":509053,"date":"2022-11-19T06:25:48","date_gmt":"2022-11-19T05:25:48","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/"},"modified":"2025-03-05T15:19:36","modified_gmt":"2025-03-05T14:19:36","slug":"dog-puppy-medium-bouchees-en-sauce-2","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/","title":{"rendered":"Dog Puppy Medium Bouch\u00e9es en Sauce"},"content":{"rendered":"<p><strong>L\u2019aliment humide ROYAL CANIN\u00ae Medium Puppy Sauce est sp\u00e9cialement formul\u00e9 pour r\u00e9pondre aux besoins nutritionnels des chiots de races moyennes. Cette formule convient aux chiots \u00e2g\u00e9s de 2 \u00e0 12 mois qui devraient atteindre un poids adulte compris entre 11 et 25 kg.\u00a0<\/strong><b>Cette formule sur mesure est compos\u00e9e de tendres bouch\u00e9es en sauce dont la taille, la texture et le go\u00fbt sont optimaux pour les chiots de races moyennes en pleine croissance.<\/b><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chiot de race moyenne (11 \u00e0 25 kg \u00e0 l&#8217;\u00e2ge adulte)<\/li>\n<li>Chiot de 2 \u00e0 12 mois<\/li>\n<\/ul>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li><strong>Taille, texture et go\u00fbt parfaits<\/strong>\u00a0des bouch\u00e9es pour les chiots de races moyennes en croissance<\/li>\n<li>Aide \u00e0 soutenir le\u00a0<strong>d\u00e9veloppement du syst\u00e8me immunitaire du chiot<\/strong>\u00a0gr\u00e2ce \u00e0 la pr\u00e9sence d\u2019un complexe scientifiquement prouv\u00e9, comprenant les\u00a0<strong>vitamines E et C.<\/strong><\/li>\n<li>Enrichi en\u00a0<strong>acide gras om\u00e9ga-3 (DHA)<\/strong>, qui est scientifiquement prouv\u00e9 pour soutenir le d\u00e9veloppement c\u00e9r\u00e9bral et promouvoir l\u2019apprentissage du chiot lors de son \u00e9ducation pr\u00e9coce.<\/li>\n<li>Une\u00a0<strong>combinaison de pr\u00e9biotiques (MOS) et de prot\u00e9ines hautement digestibles<\/strong>\u00a0pour favoriser l\u2019\u00e9quilibre du\u00a0<strong>microbiote intestinal<\/strong>\u00a0pour une sant\u00e9 digestive optimale.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>L\u2019aliment humide ROYAL CANIN\u00ae Medium Puppy Sauce est sp\u00e9cialement formul\u00e9 pour r\u00e9pondre aux besoins nutritionnels des chiots de races moyennes. Cette formule convient aux chiots \u00e2g\u00e9s de 2 \u00e0 12 mois qui devraient atteindre un poids adulte compris entre 11 et 25 kg.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chiot de race moyenne (11 \u00e0 25 kg \u00e0 l&#8217;\u00e2ge adulte)<\/li>\n<li>Chiot de 2 \u00e0 12 mois<\/li>\n<\/ul>\n","protected":false},"featured_media":1123397,"template":"","meta":[],"product_cat":[12552,12584,2698],"product_tag":[],"class_list":{"0":"post-509053","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chien","7":"product_cat-alimentation-premium-pour-chien","8":"product_cat-chien","9":"pa_marque-royal-canin","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vet Care Nutrition (Royal Canin) Dog Puppy Medium Bouch\u00e9es en Sauce Royal Canin - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"L\u2019aliment humide ROYAL CANIN\u00ae Medium Puppy Sauce est sp\u00e9cialement formul\u00e9 pour r\u00e9pondre aux besoins nutritionnels des chiots de races moyennes. Cette formule convient aux chiots \u00e2g\u00e9s de 2 \u00e0 12 mois qui devraient atteindre un poids adulte compris entre 11 et 25 kg.  &nbsp;  Utilisation :   Chiot de race moyenne (11 \u00e0 25 kg \u00e0 l&#039;\u00e2ge adulte)  Chiot de 2 \u00e0 12 mois\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vet Care Nutrition (Royal Canin) Dog Puppy Medium Bouch\u00e9es en Sauce Royal Canin - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"L\u2019aliment humide ROYAL CANIN\u00ae Medium Puppy Sauce est sp\u00e9cialement formul\u00e9 pour r\u00e9pondre aux besoins nutritionnels des chiots de races moyennes. Cette formule convient aux chiots \u00e2g\u00e9s de 2 \u00e0 12 mois qui devraient atteindre un poids adulte compris entre 11 et 25 kg.  &nbsp;  Utilisation :   Chiot de race moyenne (11 \u00e0 25 kg \u00e0 l&#039;\u00e2ge adulte)  Chiot de 2 \u00e0 12 mois\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-05T14:19:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/dog-puppy-medium-bouchees-en-sauce.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"21,05&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/dog-puppy-medium-bouchees-en-sauce-2\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/dog-puppy-medium-bouchees-en-sauce-2\\\/\",\"name\":\"Vet Care Nutrition (Royal Canin) Dog Puppy Medium Bouch\u00e9es en Sauce Royal Canin - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/dog-puppy-medium-bouchees-en-sauce-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/dog-puppy-medium-bouchees-en-sauce-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/dog-puppy-medium-bouchees-en-sauce.webp\",\"datePublished\":\"2022-11-19T05:25:48+00:00\",\"dateModified\":\"2025-03-05T14:19:36+00:00\",\"description\":\"L\u2019aliment humide ROYAL CANIN\u00ae Medium Puppy Sauce est sp\u00e9cialement formul\u00e9 pour r\u00e9pondre aux besoins nutritionnels des chiots de races moyennes. Cette formule convient aux chiots \u00e2g\u00e9s de 2 \u00e0 12 mois qui devraient atteindre un poids adulte compris entre 11 et 25 kg. &nbsp; Utilisation : Chiot de race moyenne (11 \u00e0 25 kg \u00e0 l'\u00e2ge adulte) Chiot de 2 \u00e0 12 mois\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/dog-puppy-medium-bouchees-en-sauce-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/dog-puppy-medium-bouchees-en-sauce-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/dog-puppy-medium-bouchees-en-sauce-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/dog-puppy-medium-bouchees-en-sauce.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/dog-puppy-medium-bouchees-en-sauce.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/dog-puppy-medium-bouchees-en-sauce-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dog Puppy Medium Bouch\u00e9es en Sauce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Royal Canin\" \/>\n<meta property=\"product:price:amount\" content=\"21.05\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"O-15053\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vet Care Nutrition (Royal Canin) Dog Puppy Medium Bouch\u00e9es en Sauce Royal Canin - V\u00e9torino","description":"L\u2019aliment humide ROYAL CANIN\u00ae Medium Puppy Sauce est sp\u00e9cialement formul\u00e9 pour r\u00e9pondre aux besoins nutritionnels des chiots de races moyennes. Cette formule convient aux chiots \u00e2g\u00e9s de 2 \u00e0 12 mois qui devraient atteindre un poids adulte compris entre 11 et 25 kg.  &nbsp;  Utilisation :   Chiot de race moyenne (11 \u00e0 25 kg \u00e0 l'\u00e2ge adulte)  Chiot de 2 \u00e0 12 mois","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Vet Care Nutrition (Royal Canin) Dog Puppy Medium Bouch\u00e9es en Sauce Royal Canin - V\u00e9torino","og_description":"L\u2019aliment humide ROYAL CANIN\u00ae Medium Puppy Sauce est sp\u00e9cialement formul\u00e9 pour r\u00e9pondre aux besoins nutritionnels des chiots de races moyennes. Cette formule convient aux chiots \u00e2g\u00e9s de 2 \u00e0 12 mois qui devraient atteindre un poids adulte compris entre 11 et 25 kg.  &nbsp;  Utilisation :   Chiot de race moyenne (11 \u00e0 25 kg \u00e0 l'\u00e2ge adulte)  Chiot de 2 \u00e0 12 mois","og_url":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-03-05T14:19:36+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/dog-puppy-medium-bouchees-en-sauce.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"21,05&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/","url":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/","name":"Vet Care Nutrition (Royal Canin) Dog Puppy Medium Bouch\u00e9es en Sauce Royal Canin - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/dog-puppy-medium-bouchees-en-sauce.webp","datePublished":"2022-11-19T05:25:48+00:00","dateModified":"2025-03-05T14:19:36+00:00","description":"L\u2019aliment humide ROYAL CANIN\u00ae Medium Puppy Sauce est sp\u00e9cialement formul\u00e9 pour r\u00e9pondre aux besoins nutritionnels des chiots de races moyennes. Cette formule convient aux chiots \u00e2g\u00e9s de 2 \u00e0 12 mois qui devraient atteindre un poids adulte compris entre 11 et 25 kg. &nbsp; Utilisation : Chiot de race moyenne (11 \u00e0 25 kg \u00e0 l'\u00e2ge adulte) Chiot de 2 \u00e0 12 mois","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/dog-puppy-medium-bouchees-en-sauce.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/dog-puppy-medium-bouchees-en-sauce.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/dog-puppy-medium-bouchees-en-sauce-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Dog Puppy Medium Bouch\u00e9es en Sauce"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Royal Canin","product_price_amount":"21.05","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"O-15053","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/product\/509053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/media\/1123397"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/media?parent=509053"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/product_cat?post=509053"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/st-sulpice-feuilles-87160\/boutique\/wp-json\/wp\/v2\/product_tag?post=509053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}