{"id":681147,"date":"2023-08-24T16:21:25","date_gmt":"2023-08-24T14:21:25","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=681147"},"modified":"2024-08-08T17:21:19","modified_gmt":"2024-08-08T15:21:19","slug":"guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/","title":{"rendered":"Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"681147\" class=\"elementor elementor-681147\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-969daa8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"969daa8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ea5517\" data-id=\"3ea5517\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e10027 elementor-widget elementor-widget-text-editor\" data-id=\"1e10027\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p>\n<p>La rentr\u00e9e n&#8217;est pas seulement un moment de changement pour les humains ; nos fid\u00e8les amis \u00e0 quatre pattes peuvent \u00e9galement \u00eatre sensibles \u00e0 cette transition. Que ce soit le retour des enfants \u00e0 l&#8217;\u00e9cole, la reprise de nos horaires de travail habituels, ou simplement le passage des journ\u00e9es ensoleill\u00e9es de l&#8217;\u00e9t\u00e9 aux jours plus frais de l&#8217;automne, la rentr\u00e9e peut pr\u00e9senter des d\u00e9fis pour nos animaux de compagnie. Pour vous aider \u00e0 rendre cette p\u00e9riode aussi douce que possible pour vos amis \u00e0 poils, nous avons rassembl\u00e9 quelques astuces pour une transition en toute tranquillit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28f3c81 elementor-widget elementor-widget-heading\" data-id=\"28f3c81\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Pr\u00e9parez une routine stable<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ed8bc9 elementor-widget elementor-widget-text-editor\" data-id=\"7ed8bc9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les animaux de compagnie aiment\u00a0<b data-stringify-type=\"bold\">la pr\u00e9visibilit\u00e9<\/b>, donc essayer de maintenir\u00a0<b data-stringify-type=\"bold\">une routine stable<\/b>\u00a0autant que possible est crucial. Avant le d\u00e9but de la rentr\u00e9e,\u00a0<b data-stringify-type=\"bold\">commencez \u00e0 r\u00e9introduire lentement les horaires r\u00e9guliers de repas, de promenades et de jeux<\/b>\u00a0pour que votre animal s&#8217;adapte progressivement \u00e0 la nouvelle routine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2774d0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2774d0e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd40ec9\" data-id=\"cd40ec9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db03522 elementor-widget elementor-widget-heading\" data-id=\"db03522\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Cr\u00e9ez un espace de confort<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2c17ea elementor-widget elementor-widget-text-editor\" data-id=\"d2c17ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b data-stringify-type=\"bold\">Assurez-vous que votre animal a un espace confortable<\/b>\u00a0o\u00f9 il peut se retirer lorsque les choses deviennent un peu chaotiques. Que ce soit un coin douillet dans\u00a0<b data-stringify-type=\"bold\">une pi\u00e8ce calme<\/b>\u00a0ou sa propre caisse, un espace de r\u00e9confort peut aider \u00e0 apaiser le stress.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b6736b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b6736b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a567f79\" data-id=\"a567f79\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cbcb96 elementor-widget elementor-widget-heading\" data-id=\"3cbcb96\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. Stimulez mentalement et physiquement\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-810e64c elementor-widget elementor-widget-text-editor\" data-id=\"810e64c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une rentr\u00e9e bien planifi\u00e9e inclut non seulement\u00a0<b data-stringify-type=\"bold\">la stabilit\u00e9<\/b>, mais aussi\u00a0<b data-stringify-type=\"bold\">l&#8217;enrichissement mental et physique<\/b>. Proposez des\u00a0<b data-stringify-type=\"bold\">jouets interactifs et des exercices de stimulation mentale<\/b>\u00a0pour maintenir votre animal mentalement engag\u00e9 et physiquement actif.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-565b64e elementor-widget elementor-widget-image\" data-id=\"565b64e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"980\" height=\"652\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/gaelle-marcel-YnbJwNXy0YQ-unsplash-1024x681.jpg\" class=\"attachment-large size-large wp-image-681197\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/gaelle-marcel-YnbJwNXy0YQ-unsplash-1024x681.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/gaelle-marcel-YnbJwNXy0YQ-unsplash-300x200.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/gaelle-marcel-YnbJwNXy0YQ-unsplash-768x511.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/gaelle-marcel-YnbJwNXy0YQ-unsplash-1536x1022.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/gaelle-marcel-YnbJwNXy0YQ-unsplash-2048x1363.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/gaelle-marcel-YnbJwNXy0YQ-unsplash-750x500.jpg 750w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/gaelle-marcel-YnbJwNXy0YQ-unsplash-555x369.jpg 555w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b6085a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b6085a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c5ec7a\" data-id=\"3c5ec7a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4001c00 elementor-widget elementor-widget-heading\" data-id=\"4001c00\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. R\u00e9introduisez la s\u00e9paration graduellement\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9a4ad5 elementor-widget elementor-widget-text-editor\" data-id=\"c9a4ad5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si votre animal est habitu\u00e9 \u00e0 votre pr\u00e9sence constante pendant l&#8217;\u00e9t\u00e9,\u00a0<b data-stringify-type=\"bold\">commencez \u00e0 r\u00e9introduire la s\u00e9paration progressivement<\/b>. Laissez-le seul pendant de courtes p\u00e9riodes, puis augmentez progressivement la dur\u00e9e. Assurez-vous qu&#8217;il ait des jouets ou des activit\u00e9s pour s&#8217;occuper en votre absence.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b822f15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b822f15\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d66b5e7\" data-id=\"d66b5e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0aa35ec elementor-widget elementor-widget-heading\" data-id=\"0aa35ec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5. Soyez \u00e0 l'\u00e9coute de leurs besoins\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c9352 elementor-widget elementor-widget-text-editor\" data-id=\"a6c9352\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chaque animal est diff\u00e9rent, alors \u00e9coutez le v\u00f4tre. S&#8217;il semble anxieux ou montre des signes de stress, tels que l&#8217;agitation ou la perte d&#8217;app\u00e9tit,\u00a0<b data-stringify-type=\"bold\">prenez le temps de le rassurer et de l&#8217;apaiser<\/b>. Parfois, un peu d&#8217;amour et d&#8217;attention suppl\u00e9mentaires peuvent faire des merveilles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3767bb5 elementor-widget elementor-widget-image\" data-id=\"3767bb5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/a2963331-a388-4bf5-8ff6-54e3891abb1a.webp\" class=\"attachment-large size-large wp-image-681206\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cda58a7 elementor-widget elementor-widget-heading\" data-id=\"cda58a7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6. Consultez votre v\u00e9t\u00e9rinaire pour des conseils personnalis\u00e9s\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac17d4a elementor-widget elementor-widget-text-editor\" data-id=\"ac17d4a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Enfin, n&#8217;h\u00e9sitez pas \u00e0 consulter l&#8217;\u00e9quipe de votre v\u00e9t\u00e9rinaire pour\u00a0<b data-stringify-type=\"bold\">des conseils personnalis\u00e9s<\/b>\u00a0sur la mani\u00e8re de rendre la rentr\u00e9e plus douce pour votre animal de compagnie. Ils peuvent discuter des besoins sp\u00e9cifiques de votre animal et vous donner des recommandations adapt\u00e9es.<br \/>La rentr\u00e9e peut \u00eatre une p\u00e9riode d\u00e9licate pour nos amis \u00e0 quatre pattes, mais avec un peu de pr\u00e9paration et d&#8217;amour, vous pouvez aider votre animal \u00e0 s&#8217;adapter en douceur \u00e0 cette nouvelle phase de l&#8217;ann\u00e9e.\u00a0<b data-stringify-type=\"bold\">Souvenez-vous que la patience et l&#8217;attention sont les cl\u00e9s pour assurer le bien-\u00eatre de votre compagnon \u00e0 poil pendant cette transition.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee18078 product_alcyon elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee18078\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5746efa\" data-id=\"5746efa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f66d2a9 elementor-widget elementor-widget-image\" data-id=\"f66d2a9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"263\" height=\"300\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14-263x300.jpg\" class=\"attachment-medium size-medium wp-image-688290\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14-263x300.jpg 263w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14-555x634.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14.jpg 700w\" sizes=\"(max-width: 263px) 100vw, 263px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f29198a elementor-widget elementor-widget-heading\" data-id=\"f29198a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Petscool SPRAY<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-522a4ea elementor-widget elementor-widget-text-editor\" data-id=\"522a4ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ce spray \u00e0 base d&#8217;huiles essentielles procure un effet anti-stress. Elle convient aux chiens, chats, lapins, furets, rongeurs, chevaux, et oiseaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee99ec9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ee99ec9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/susmiou-64190\/boutique\/\/product\/petscool-spray\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2e4b412\" data-id=\"2e4b412\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83d5048 elementor-widget elementor-widget-image\" data-id=\"83d5048\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-300x300.jpeg\" class=\"attachment-medium size-medium wp-image-688299\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m.jpeg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d63914f elementor-widget elementor-widget-heading\" data-id=\"d63914f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Virbac LAMELLES VEGGIEDENT ZEN<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6aa0ba7 elementor-widget elementor-widget-text-editor\" data-id=\"6aa0ba7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lamelles \u00e0 m\u00e2cher 2 en 1 qui aident \u00e0 lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 votre compagnon.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd9d70 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3fd9d70\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/susmiou-64190\/boutique\/\/product\/veggiedent-fresh-m-chien-10-30-kg\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-238aa8e\" data-id=\"238aa8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ffe1ea elementor-widget elementor-widget-image\" data-id=\"4ffe1ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-300x300.png\" class=\"attachment-medium size-medium wp-image-688268\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-1024x1024.png 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2309b3 elementor-widget elementor-widget-heading\" data-id=\"f2309b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">V\u00e9toquinol ZYLK\u00c8NE 225 MG<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b104ec1 elementor-widget elementor-widget-text-editor\" data-id=\"b104ec1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un anti-stress 100% naturel pour chiens. Il est recommand\u00e9 dans les cas de troubles du comportement du chien et permet une prise en charge rapide des \u00e9tats de stress install\u00e9s ou dans leur pr\u00e9vision.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c583c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a6c583c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/susmiou-64190\/boutique\/\/product\/zylkene-225-mg\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c35fae product_centravet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c35fae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a446eda\" data-id=\"a446eda\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-948bde3 elementor-widget elementor-widget-image\" data-id=\"948bde3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"263\" height=\"300\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14-263x300.jpg\" class=\"attachment-medium size-medium wp-image-688290\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14-263x300.jpg 263w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14-555x634.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14.jpg 700w\" sizes=\"(max-width: 263px) 100vw, 263px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb03979 elementor-widget elementor-widget-heading\" data-id=\"fb03979\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Petscool SPRAY<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fcaa8a elementor-widget elementor-widget-text-editor\" data-id=\"3fcaa8a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ce spray \u00e0 base d&#8217;huiles essentielles procure un effet anti-stress. Elle convient aux chiens, chats, lapins, furets, rongeurs, chevaux, et oiseaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-302a35e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"302a35e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/susmiou-64190\/boutique\/\/product\/petscool\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8ba1cf0\" data-id=\"8ba1cf0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83cf227 elementor-widget elementor-widget-image\" data-id=\"83cf227\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-300x300.jpeg\" class=\"attachment-medium size-medium wp-image-688299\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m.jpeg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c83860 elementor-widget elementor-widget-heading\" data-id=\"0c83860\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Virbac LAMELLES VEGGIEDENT ZEN<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89db0e0 elementor-widget elementor-widget-text-editor\" data-id=\"89db0e0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lamelles \u00e0 m\u00e2cher 2 en 1 qui aident \u00e0 lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 votre compagnon.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27948b4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"27948b4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/susmiou-64190\/boutique\/\/product\/veggiedent-zen\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f10b76b\" data-id=\"f10b76b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61977f6 elementor-widget elementor-widget-image\" data-id=\"61977f6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-300x300.png\" class=\"attachment-medium size-medium wp-image-688268\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-1024x1024.png 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/Publications-instagram-1.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1fe82e elementor-widget elementor-widget-heading\" data-id=\"e1fe82e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">V\u00e9toquinol ZYLK\u00c8NE 225 MG\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2191274 elementor-widget elementor-widget-text-editor\" data-id=\"2191274\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un anti-stress 100% naturel pour chiens. Il est recommand\u00e9 dans les cas de troubles du comportement du chien et permet une prise en charge rapide des \u00e9tats de stress install\u00e9s ou dans leur pr\u00e9vision.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e815f7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7e815f7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/susmiou-64190\/boutique\/\/product\/zylkene-225-mg-2\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0e8698 product_coveto elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0e8698\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a36cbc3\" data-id=\"a36cbc3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afb05bd elementor-widget elementor-widget-image\" data-id=\"afb05bd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"263\" height=\"300\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14-263x300.jpg\" class=\"attachment-medium size-medium wp-image-688290\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14-263x300.jpg 263w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14-555x634.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/solution-anti-stress-200ml-multi-especes-petscool-14.jpg 700w\" sizes=\"(max-width: 263px) 100vw, 263px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03d1f01 elementor-widget elementor-widget-heading\" data-id=\"03d1f01\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Petscool SPRAY<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87e2805 elementor-widget elementor-widget-text-editor\" data-id=\"87e2805\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ce spray \u00e0 base d&#8217;huiles essentielles procure un effet anti-stress. Elle convient aux chiens, chats, lapins, furets, rongeurs, chevaux, et oiseaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c02923 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9c02923\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/susmiou-64190\/boutique\/\/product\/petscool-2\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1dbb3c0\" data-id=\"1dbb3c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25a2f34 elementor-widget elementor-widget-image\" data-id=\"25a2f34\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-300x300.jpeg\" class=\"attachment-medium size-medium wp-image-688299\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/veggiedent-zen-m.jpeg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85e5237 elementor-widget elementor-widget-heading\" data-id=\"85e5237\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Virbac LAMELLES VEGGIEDENT ZEN<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b53059 elementor-widget elementor-widget-text-editor\" data-id=\"6b53059\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lamelles \u00e0 m\u00e2cher 2 en 1 qui aident \u00e0 lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 votre compagnon.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a8eaf8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2a8eaf8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/susmiou-64190\/boutique\/\/product\/veggiedent-zen-2\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4200da0\" data-id=\"4200da0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd646b2 elementor-widget elementor-widget-image\" data-id=\"bd646b2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/803661_1-585x585-1-removebg-preview-1-300x300.png\" class=\"attachment-medium size-medium wp-image-688359\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/803661_1-585x585-1-removebg-preview-1-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/803661_1-585x585-1-removebg-preview-1-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/803661_1-585x585-1-removebg-preview-1-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/03\/803661_1-585x585-1-removebg-preview-1.png 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab4de01 elementor-widget elementor-widget-heading\" data-id=\"ab4de01\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Doc &amp; Phoebe JEU SOURIS HUNTER FEEDER<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd050fb elementor-widget elementor-widget-text-editor\" data-id=\"cd050fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jouet amusant d&#8217;int\u00e9rieur en forme de souris pour stimuler l&#8217;instinct de chasse de votre chat, \u00e0 cacher dans la maison.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e15ff30 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e15ff30\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/susmiou-64190\/boutique\/\/product\/jeu-souris-hunter-feeder\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La rentr\u00e9e n&#8217;est pas seulement un moment de changement pour les humains ; nos fid\u00e8les amis \u00e0 quatre pattes peuvent \u00e9galement \u00eatre sensibles \u00e0 cette transition. Que ce soit le retour des enfants \u00e0 l&#8217;\u00e9cole, la reprise de nos horaires de travail habituels, ou simplement le passage des journ\u00e9es ensoleill\u00e9es de l&#8217;\u00e9t\u00e9 aux jours plus [&hellip;]<\/p>\n","protected":false},"author":8844,"featured_media":688178,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14086,14087,14091,14090],"tags":[],"class_list":["post-681147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chat","category-chien","category-hygiene-et-bien-etre-chat","category-hygiene-et-bien-etre-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie - V\u00e9torino<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"La rentr\u00e9e n&#8217;est pas seulement un moment de changement pour les humains ; nos fid\u00e8les amis \u00e0 quatre pattes peuvent \u00e9galement \u00eatre sensibles \u00e0 cette transition. Que ce soit le retour des enfants \u00e0 l&#8217;\u00e9cole, la reprise de nos horaires de travail habituels, ou simplement le passage des journ\u00e9es ensoleill\u00e9es de l&#8217;\u00e9t\u00e9 aux jours plus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-24T14:21:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:21:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/La-boutique-en-ligne-de-votre-veterinaire.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"louisa.lecoq\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"louisa.lecoq\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/\"},\"author\":{\"name\":\"louisa.lecoq\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/a78b72e8520cb9d9031ed26a48a2c389\"},\"headline\":\"Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie\",\"datePublished\":\"2023-08-24T14:21:25+00:00\",\"dateModified\":\"2024-08-08T15:21:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/\"},\"wordCount\":797,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/La-boutique-en-ligne-de-votre-veterinaire.png\",\"articleSection\":[\"Chat\",\"Chien\",\"Hygi\u00e8ne et bien-\u00eatre pour chat\",\"Hygi\u00e8ne et bien-\u00eatre pour chien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/\",\"name\":\"Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/La-boutique-en-ligne-de-votre-veterinaire.png\",\"datePublished\":\"2023-08-24T14:21:25+00:00\",\"dateModified\":\"2024-08-08T15:21:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/La-boutique-en-ligne-de-votre-veterinaire.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/La-boutique-en-ligne-de-votre-veterinaire.png\",\"width\":600,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/08\\\/24\\\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/a78b72e8520cb9d9031ed26a48a2c389\",\"name\":\"louisa.lecoq\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g\",\"caption\":\"louisa.lecoq\"},\"sameAs\":[\"louisa@vetorino.com\"],\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/sucyenbrie-centre-94370\\\/boutique\\\/author\\\/louisa-lecoq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie - V\u00e9torino","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie - V\u00e9torino","og_description":"La rentr\u00e9e n&#8217;est pas seulement un moment de changement pour les humains ; nos fid\u00e8les amis \u00e0 quatre pattes peuvent \u00e9galement \u00eatre sensibles \u00e0 cette transition. Que ce soit le retour des enfants \u00e0 l&#8217;\u00e9cole, la reprise de nos horaires de travail habituels, ou simplement le passage des journ\u00e9es ensoleill\u00e9es de l&#8217;\u00e9t\u00e9 aux jours plus [&hellip;]","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2023-08-24T14:21:25+00:00","article_modified_time":"2024-08-08T15:21:19+00:00","og_image":[{"width":600,"height":200,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/La-boutique-en-ligne-de-votre-veterinaire.png","type":"image\/png"}],"author":"louisa.lecoq","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"louisa.lecoq","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/"},"author":{"name":"louisa.lecoq","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/a78b72e8520cb9d9031ed26a48a2c389"},"headline":"Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie","datePublished":"2023-08-24T14:21:25+00:00","dateModified":"2024-08-08T15:21:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/"},"wordCount":797,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/La-boutique-en-ligne-de-votre-veterinaire.png","articleSection":["Chat","Chien","Hygi\u00e8ne et bien-\u00eatre pour chat","Hygi\u00e8ne et bien-\u00eatre pour chien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/","url":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/","name":"Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/La-boutique-en-ligne-de-votre-veterinaire.png","datePublished":"2023-08-24T14:21:25+00:00","dateModified":"2024-08-08T15:21:19+00:00","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/La-boutique-en-ligne-de-votre-veterinaire.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/08\/La-boutique-en-ligne-de-votre-veterinaire.png","width":600,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/08\/24\/guide-pratique-gerer-la-rentree-avec-vos-animaux-de-compagnie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chien","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chien\/"},{"@type":"ListItem","position":3,"name":"Guide pratique : G\u00e9rer la rentr\u00e9e avec vos animaux de compagnie"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/a78b72e8520cb9d9031ed26a48a2c389","name":"louisa.lecoq","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g","caption":"louisa.lecoq"},"sameAs":["louisa@vetorino.com"],"url":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/author\/louisa-lecoq\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/posts\/681147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/users\/8844"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/comments?post=681147"}],"version-history":[{"count":35,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/posts\/681147\/revisions"}],"predecessor-version":[{"id":993036,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/posts\/681147\/revisions\/993036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media\/688178"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media?parent=681147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/categories?post=681147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/tags?post=681147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}