{"id":101090,"date":"2020-06-30T01:54:01","date_gmt":"2020-06-29T23:54:01","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/preference-chien-joueur-2\/"},"modified":"2026-07-15T13:39:21","modified_gmt":"2026-07-15T11:39:21","slug":"preference-chien-joueur-2","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/preference-chien-joueur-2\/","title":{"rendered":"Chien Joueur"},"content":{"rendered":"<p>Alimentation compl\u00e8te au poulet pour\u00a0<strong>chiens adultes actifs, st\u00e9rilis\u00e9s ou non<\/strong>, \u00e9labor\u00e9e pour s&#8217;adapt\u00e9e aux\u00a0<strong>besoins \u00e9nerg\u00e9tiques \u00e9lev\u00e9s\u00a0<\/strong>des chiens dynamiques et soutenir un confort digestif, un pelage brillant et une peau saine.<\/p>\n<ul>\n<li><span data-sheets-root=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;* Apport \u00e9nerg\u00e9tique \u00e9tudi\u00e9 pour un maintien de poids id\u00e9al.n* Formule enrichie en Omega 3 (Graine de lin, huile de poissons) pour un pelage brillant et une peau saine.n* Effet pr\u00e9biotique de la pulpe de betterave et des omega 3 pour le confort digestif.nnFabrication Fran\u00e7aise - Sacherie recyclable.nnProbioactiFAP\u00ae: Sant\u00e9 du Microbiote digestifnDes produits issus de la technologie FAP\u00ae (Facteur d\u2019Assimilation Process) et d\u2019un process exclusif, au service de la sant\u00e9 du microbiote digestif propre \u00e0 chaque animal. nAssociation naturelle de mol\u00e9cules probioactives (pr\u00e9 et postbiotiques), les ProbioactiFAP\u00ae agissent tout au long du tractus digestif pour pr\u00e9venir les d\u00e9s\u00e9quilibres de la flore, renforcer l\u2019int\u00e9grit\u00e9 de la paroi digestive et l\u2019immunit\u00e9.nnCroquettes forme PastillenDiam\u00e8tre\u2009: +\/- 12mmn\u00e9paisseur\u2009: +\/- 5mm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:13249,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:0,&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0,&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:11}\">Apport \u00e9nerg\u00e9tique \u00e9tudi\u00e9 pour un<strong> maintien de poids id\u00e9al.<\/strong><\/span><\/li>\n<li><span data-sheets-root=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;* Apport \u00e9nerg\u00e9tique \u00e9tudi\u00e9 pour un maintien de poids id\u00e9al.n* Formule enrichie en Omega 3 (Graine de lin, huile de poissons) pour un pelage brillant et une peau saine.n* Effet pr\u00e9biotique de la pulpe de betterave et des omega 3 pour le confort digestif.nnFabrication Fran\u00e7aise - Sacherie recyclable.nnProbioactiFAP\u00ae: Sant\u00e9 du Microbiote digestifnDes produits issus de la technologie FAP\u00ae (Facteur d\u2019Assimilation Process) et d\u2019un process exclusif, au service de la sant\u00e9 du microbiote digestif propre \u00e0 chaque animal. nAssociation naturelle de mol\u00e9cules probioactives (pr\u00e9 et postbiotiques), les ProbioactiFAP\u00ae agissent tout au long du tractus digestif pour pr\u00e9venir les d\u00e9s\u00e9quilibres de la flore, renforcer l\u2019int\u00e9grit\u00e9 de la paroi digestive et l\u2019immunit\u00e9.nnCroquettes forme PastillenDiam\u00e8tre\u2009: +\/- 12mmn\u00e9paisseur\u2009: +\/- 5mm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:13249,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:0,&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0,&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:11}\">Formule enrichie en Omega 3 (Graine de lin, huile de poissons) pour un <strong>pelage brillant et une peau saine.<\/strong><\/span><\/li>\n<li><span data-sheets-root=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;* Apport \u00e9nerg\u00e9tique \u00e9tudi\u00e9 pour un maintien de poids id\u00e9al.n* Formule enrichie en Omega 3 (Graine de lin, huile de poissons) pour un pelage brillant et une peau saine.n* Effet pr\u00e9biotique de la pulpe de betterave et des omega 3 pour le confort digestif.nnFabrication Fran\u00e7aise - Sacherie recyclable.nnProbioactiFAP\u00ae: Sant\u00e9 du Microbiote digestifnDes produits issus de la technologie FAP\u00ae (Facteur d\u2019Assimilation Process) et d\u2019un process exclusif, au service de la sant\u00e9 du microbiote digestif propre \u00e0 chaque animal. nAssociation naturelle de mol\u00e9cules probioactives (pr\u00e9 et postbiotiques), les ProbioactiFAP\u00ae agissent tout au long du tractus digestif pour pr\u00e9venir les d\u00e9s\u00e9quilibres de la flore, renforcer l\u2019int\u00e9grit\u00e9 de la paroi digestive et l\u2019immunit\u00e9.nnCroquettes forme PastillenDiam\u00e8tre\u2009: +\/- 12mmn\u00e9paisseur\u2009: +\/- 5mm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:13249,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:0,&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0,&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:11}\">Effet pr\u00e9biotique de la pulpe de betterave et des omega 3 pour le <strong>confort digestif.<\/strong><\/span><\/li>\n<\/ul>\n<p><strong>Fabrication Fran\u00e7aise<\/strong> &#8211; Sacherie recyclable.<\/p>\n<p>ProbioactiFAP\u00ae : Sant\u00e9 du Microbiote digestif<\/p>\n<p>Des produits issus de la technologie FAP\u00ae (Facteur d\u2019Assimilation Process) et d\u2019un process exclusif, au service de la <strong>sant\u00e9 du microbiote digestif<\/strong> propre \u00e0 chaque animal.<\/p>\n<p>Association naturelle de mol\u00e9cules probioactives (pr\u00e9 et postbiotiques), les ProbioactiFAP\u00ae agissent tout au long du tractus digestif <strong>pour pr\u00e9venir les d\u00e9s\u00e9quilibres de la flore, renforcer l\u2019int\u00e9grit\u00e9 de la paroi digestive et l\u2019immunit\u00e9.<\/strong><\/p>\n<p>Croquettes forme Pastille<br \/>\nDiam\u00e8tre\u2009: +\/- 12mm<br \/>\n\u00c9paisseur\u2009: +\/- 5mm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alimentation compl\u00e8te au poulet pour\u00a0<strong>chiens adultes actifs, st\u00e9rilis\u00e9s ou non<\/strong>, \u00e9labor\u00e9e pour s&#8217;adapt\u00e9e aux\u00a0<strong>besoins \u00e9nerg\u00e9tiques \u00e9lev\u00e9s\u00a0<\/strong>des chiens dynamiques et soutenir un confort digestif, un pelage brillant et une peau saine.<\/p>\n<p><strong>Fabrication Fran\u00e7aise.<\/strong><\/p>\n","protected":false},"featured_media":776088,"template":"","meta":[],"product_cat":[12552,12584,2698],"product_tag":[],"class_list":{"0":"post-101090","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chien","7":"product_cat-alimentation-premium-pour-chien","8":"product_cat-chien","9":"pa_marque-preference","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chien Joueur Pr\u00e9f\u00e9rence - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Alimentation compl\u00e8te au poulet pour\u00a0chiens adultes actifs, st\u00e9rilis\u00e9s ou non, \u00e9labor\u00e9e pour s&#039;adapt\u00e9e aux\u00a0besoins \u00e9nerg\u00e9tiques \u00e9lev\u00e9s\u00a0des chiens dynamiques et soutenir un confort digestif, un pelage brillant et une peau saine.  Fabrication Fran\u00e7aise.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chien Joueur Pr\u00e9f\u00e9rence - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Alimentation compl\u00e8te au poulet pour\u00a0chiens adultes actifs, st\u00e9rilis\u00e9s ou non, \u00e9labor\u00e9e pour s&#039;adapt\u00e9e aux\u00a0besoins \u00e9nerg\u00e9tiques \u00e9lev\u00e9s\u00a0des chiens dynamiques et soutenir un confort digestif, un pelage brillant et une peau saine.  Fabrication Fran\u00e7aise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/preference-chien-joueur-2\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T11:39:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-joueur.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/preference-chien-joueur-2\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/preference-chien-joueur-2\\\/\",\"name\":\"Chien Joueur Pr\u00e9f\u00e9rence - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/preference-chien-joueur-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/preference-chien-joueur-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-joueur.webp\",\"datePublished\":\"2020-06-29T23:54:01+00:00\",\"dateModified\":\"2026-07-15T11:39:21+00:00\",\"description\":\"Alimentation compl\u00e8te au poulet pour\u00a0chiens adultes actifs, st\u00e9rilis\u00e9s ou non, \u00e9labor\u00e9e pour s'adapt\u00e9e aux\u00a0besoins \u00e9nerg\u00e9tiques \u00e9lev\u00e9s\u00a0des chiens dynamiques et soutenir un confort digestif, un pelage brillant et une peau saine. Fabrication Fran\u00e7aise.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/preference-chien-joueur-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/preference-chien-joueur-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/preference-chien-joueur-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-joueur.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-joueur.webp\",\"width\":540,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/preference-chien-joueur-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chien Joueur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Pr\u00e9f\u00e9rence\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chien Joueur Pr\u00e9f\u00e9rence - V\u00e9torino","description":"Alimentation compl\u00e8te au poulet pour\u00a0chiens adultes actifs, st\u00e9rilis\u00e9s ou non, \u00e9labor\u00e9e pour s'adapt\u00e9e aux\u00a0besoins \u00e9nerg\u00e9tiques \u00e9lev\u00e9s\u00a0des chiens dynamiques et soutenir un confort digestif, un pelage brillant et une peau saine.  Fabrication Fran\u00e7aise.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Chien Joueur Pr\u00e9f\u00e9rence - V\u00e9torino","og_description":"Alimentation compl\u00e8te au poulet pour\u00a0chiens adultes actifs, st\u00e9rilis\u00e9s ou non, \u00e9labor\u00e9e pour s'adapt\u00e9e aux\u00a0besoins \u00e9nerg\u00e9tiques \u00e9lev\u00e9s\u00a0des chiens dynamiques et soutenir un confort digestif, un pelage brillant et une peau saine.  Fabrication Fran\u00e7aise.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/preference-chien-joueur-2\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-07-15T11:39:21+00:00","og_image":[{"width":540,"height":540,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-joueur.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/preference-chien-joueur-2\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/preference-chien-joueur-2\/","name":"Chien Joueur Pr\u00e9f\u00e9rence - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/preference-chien-joueur-2\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/preference-chien-joueur-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-joueur.webp","datePublished":"2020-06-29T23:54:01+00:00","dateModified":"2026-07-15T11:39:21+00:00","description":"Alimentation compl\u00e8te au poulet pour\u00a0chiens adultes actifs, st\u00e9rilis\u00e9s ou non, \u00e9labor\u00e9e pour s'adapt\u00e9e aux\u00a0besoins \u00e9nerg\u00e9tiques \u00e9lev\u00e9s\u00a0des chiens dynamiques et soutenir un confort digestif, un pelage brillant et une peau saine. Fabrication Fran\u00e7aise.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/preference-chien-joueur-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/preference-chien-joueur-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/preference-chien-joueur-2\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-joueur.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-joueur.webp","width":540,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/preference-chien-joueur-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Chien Joueur"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Pr\u00e9f\u00e9rence","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product\/101090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media\/776088"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media?parent=101090"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_cat?post=101090"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_tag?post=101090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}