{"id":1246520,"date":"2025-03-12T10:49:56","date_gmt":"2025-03-12T09:49:56","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/"},"modified":"2026-01-05T02:42:14","modified_gmt":"2026-01-05T01:42:14","slug":"veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/","title":{"rendered":"Cat Digestive Support Mousse"},"content":{"rendered":"<p><strong>Mousse pour chat pr\u00e9sentant des troubles digestifs \u00e0 tous les stades physiologiques, concentr\u00e9e en \u00e9nergie et en nutriment, tr\u00e8s app\u00e9tente.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Compensations de mal-absorption \/ mal-digestion.<\/li>\n<li>R\u00e9duction des troubles digestifs.<\/li>\n<li>Insuffisance pancr\u00e9atique exocrine chronique.<\/li>\n<li>R\u00e9cup\u00e9ration nutritionnelle.<\/li>\n<li>Convalescence.<\/li>\n<\/ul>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li>Compense les pertes : haute densit\u00e9 \u00e9nerg\u00e9tique, riche en prot\u00e9ines de haute qualit\u00e9.<\/li>\n<li>S\u00e9curise la fonction digestive rapidement : ingr\u00e9dients de qualit\u00e9 tr\u00e8s digestibles, efficacit\u00e9 prouv\u00e9e.<\/li>\n<li>\u00a0Prise alimentaire optimale : haute app\u00e9tance d\u00e9montr\u00e9e, favorise l\u2019hydratation.<\/li>\n<\/ul>\n<p><strong>L\u2019aliment est aussi disponible sous forme de croquettes hautement app\u00e9tentes pour un programme nutritionnel optimal combinant aliments secs et humides.<\/strong><\/p>\n<p><strong>Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Mousse pour chat pr\u00e9sentant des troubles digestifs \u00e0 tous les stades physiologiques, concentr\u00e9e en \u00e9nergie et en nutriment, tr\u00e8s app\u00e9tente.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Compensations de mal-absorption \/ mal-digestion.<\/li>\n<li>R\u00e9duction des troubles digestifs.<\/li>\n<li>Insuffisance pancr\u00e9atique exocrine chronique.<\/li>\n<li>R\u00e9cup\u00e9ration nutritionnelle.<\/li>\n<li>Convalescence.<\/li>\n<\/ul>\n<p><strong>Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire.<\/strong><\/p>\n","protected":false},"featured_media":1248039,"template":"","meta":[],"product_cat":[12551,12581,2697],"product_tag":[],"class_list":{"0":"post-1246520","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chat","7":"product_cat-alimentation-medicalisee-pour-chat","8":"product_cat-chat","9":"pa_marque-virbac","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veterinary HPM (Virbac) Cat Digestive Support Mousse Virbac - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Mousse pour chat pr\u00e9sentant des troubles digestifs \u00e0 tous les stades physiologiques, concentr\u00e9e en \u00e9nergie et en nutriment, tr\u00e8s app\u00e9tente.  Utilisation :   Compensations de mal-absorption \/ mal-digestion.  R\u00e9duction des troubles digestifs.  Insuffisance pancr\u00e9atique exocrine chronique.  R\u00e9cup\u00e9ration nutritionnelle.  Convalescence.  Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veterinary HPM (Virbac) Cat Digestive Support Mousse Virbac - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Mousse pour chat pr\u00e9sentant des troubles digestifs \u00e0 tous les stades physiologiques, concentr\u00e9e en \u00e9nergie et en nutriment, tr\u00e8s app\u00e9tente.  Utilisation :   Compensations de mal-absorption \/ mal-digestion.  R\u00e9duction des troubles digestifs.  Insuffisance pancr\u00e9atique exocrine chronique.  R\u00e9cup\u00e9ration nutritionnelle.  Convalescence.  Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-05T01:42:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/03\/363022_Bag_HPM-Wet-G_cat-85g_face.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"22,80&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\\\/\",\"name\":\"Veterinary HPM (Virbac) Cat Digestive Support Mousse Virbac - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/363022_Bag_HPM-Wet-G_cat-85g_face.png\",\"datePublished\":\"2025-03-12T09:49:56+00:00\",\"dateModified\":\"2026-01-05T01:42:14+00:00\",\"description\":\"Mousse pour chat pr\u00e9sentant des troubles digestifs \u00e0 tous les stades physiologiques, concentr\u00e9e en \u00e9nergie et en nutriment, tr\u00e8s app\u00e9tente. Utilisation : Compensations de mal-absorption \\\/ mal-digestion. R\u00e9duction des troubles digestifs. Insuffisance pancr\u00e9atique exocrine chronique. R\u00e9cup\u00e9ration nutritionnelle. Convalescence. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/363022_Bag_HPM-Wet-G_cat-85g_face.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/363022_Bag_HPM-Wet-G_cat-85g_face.png\",\"width\":640,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cat Digestive Support Mousse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Virbac\" \/>\n<meta property=\"product:price:amount\" content=\"22.80\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-VHC049\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veterinary HPM (Virbac) Cat Digestive Support Mousse Virbac - V\u00e9torino","description":"Mousse pour chat pr\u00e9sentant des troubles digestifs \u00e0 tous les stades physiologiques, concentr\u00e9e en \u00e9nergie et en nutriment, tr\u00e8s app\u00e9tente.  Utilisation :   Compensations de mal-absorption \/ mal-digestion.  R\u00e9duction des troubles digestifs.  Insuffisance pancr\u00e9atique exocrine chronique.  R\u00e9cup\u00e9ration nutritionnelle.  Convalescence.  Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Veterinary HPM (Virbac) Cat Digestive Support Mousse Virbac - V\u00e9torino","og_description":"Mousse pour chat pr\u00e9sentant des troubles digestifs \u00e0 tous les stades physiologiques, concentr\u00e9e en \u00e9nergie et en nutriment, tr\u00e8s app\u00e9tente.  Utilisation :   Compensations de mal-absorption \/ mal-digestion.  R\u00e9duction des troubles digestifs.  Insuffisance pancr\u00e9atique exocrine chronique.  R\u00e9cup\u00e9ration nutritionnelle.  Convalescence.  Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-01-05T01:42:14+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/03\/363022_Bag_HPM-Wet-G_cat-85g_face.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"22,80&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/","name":"Veterinary HPM (Virbac) Cat Digestive Support Mousse Virbac - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/03\/363022_Bag_HPM-Wet-G_cat-85g_face.png","datePublished":"2025-03-12T09:49:56+00:00","dateModified":"2026-01-05T01:42:14+00:00","description":"Mousse pour chat pr\u00e9sentant des troubles digestifs \u00e0 tous les stades physiologiques, concentr\u00e9e en \u00e9nergie et en nutriment, tr\u00e8s app\u00e9tente. Utilisation : Compensations de mal-absorption \/ mal-digestion. R\u00e9duction des troubles digestifs. Insuffisance pancr\u00e9atique exocrine chronique. R\u00e9cup\u00e9ration nutritionnelle. Convalescence. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/03\/363022_Bag_HPM-Wet-G_cat-85g_face.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/03\/363022_Bag_HPM-Wet-G_cat-85g_face.png","width":640,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-cat-g1-digestive-support-mousse-sachet-repas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Cat Digestive Support Mousse"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Virbac","product_price_amount":"22.80","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-VHC049","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product\/1246520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media\/1248039"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media?parent=1246520"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_cat?post=1246520"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_tag?post=1246520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}