{"id":1511061,"date":"2025-10-01T12:25:54","date_gmt":"2025-10-01T10:25:54","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/"},"modified":"2025-11-13T21:58:42","modified_gmt":"2025-11-13T20:58:42","slug":"chat-i-d-digestive-care-kitten-poulet","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/","title":{"rendered":"I\/D Digestive Kitten Poulet &#8211; chaton"},"content":{"rendered":"<p><em>Hill\u2019s Prescription Diet i\/d &#8211; Croquettes pour Chaton au Poulet<\/em> est un aliment savoureux formul\u00e9 pour contribuer \u00e0<strong> r\u00e9duire les troubles digestifs. <\/strong><\/p>\n<p>Cet aliment hautement digestible, enrichi en \u00e9lectrolytes et riche en vitamines B,<strong> facilite l\u2019absorption des nutriments et compense la perte de nutriments.<\/strong><\/p>\n<p>Formul\u00e9 avec la<strong> technologie de Hill\u2019s ActivBiome+ Digestion<\/strong>, un m\u00e9lange exclusif de fibres pr\u00e9biotiques, dont il a \u00e9t\u00e9 cliniquement d\u00e9montr\u00e9 qu\u2019il nourrit rapidement le microbiome intestinal afin de favoriser une qualit\u00e9 optimale des selles et une <strong>bonne sant\u00e9 digestive. <\/strong><\/p>\n<p>Enrichi en acides gras Om\u00e9ga-3 et 6 et en antioxydants dont il a \u00e9t\u00e9 cliniquement d\u00e9montr\u00e9 qu\u2019ils contribuent \u00e0 <strong>renforcer le syst\u00e8me immunitaire. <\/strong><\/p>\n<p>Hill\u2019s Prescription Diet i\/d &#8211; Croquettes pour Chaton est sp\u00e9cialement formul\u00e9 pour contribuer \u00e0 r\u00e9duire les troubles digestifs et r\u00e9pondre aux <strong>besoins nutritionnels particuliers du chaton.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Gastro-ent\u00e9rite aigu\u00eb (diarrh\u00e9e ou vomissements)<\/li>\n<li>Constipation (alt\u00e9ration de la motilit\u00e9)<\/li>\n<li>Insuffisance pancr\u00e9atique exocrine (IPE)<\/li>\n<li>Gastrite (aigu\u00eb ou chronique)<\/li>\n<li>Troubles \u0153sophagiens<\/li>\n<li>Pancr\u00e9atite<\/li>\n<li>R\u00e9cup\u00e9ration apr\u00e8s une chirurgie gastro-intestinale<\/li>\n<li>Croissance<\/li>\n<\/ul>\n<p><strong>Demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><em>Hill\u2019s Prescription Diet i\/d &#8211; Croquettes pour Chaton<\/em> est un aliment di\u00e9t\u00e9tique complet hautement digestible <strong>formul\u00e9 pour r\u00e9duire les troubles de l\u2019absorption intestinale<\/strong>, et<strong> compenser la mauvaise digestion<\/strong> et <strong>l\u2019insuffisance pancr\u00e9atique<\/strong> exocrine chez le chaton.<\/p>\n<p>Cet aliment a une<strong> teneur \u00e9lev\u00e9e en sodium et en potassium<\/strong> ainsi qu\u2019en<strong> ingr\u00e9dients hautement digestibles.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Gastro-ent\u00e9rite aigu\u00eb (diarrh\u00e9e ou vomissements)<\/li>\n<li>Constipation (alt\u00e9ration de la motilit\u00e9)<\/li>\n<li>Insuffisance pancr\u00e9atique exocrine (IPE)<\/li>\n<li>Gastrite (aigu\u00eb ou chronique)<\/li>\n<li>Troubles \u0153sophagiens<\/li>\n<li>Pancr\u00e9atite<\/li>\n<li>R\u00e9cup\u00e9ration apr\u00e8s une chirurgie gastro-intestinale<\/li>\n<li>Croissance<\/li>\n<\/ul>\n<p><strong>Demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.<\/strong><\/p>\n","protected":false},"featured_media":1511224,"template":"","meta":[],"product_cat":[2697],"product_tag":[],"class_list":{"0":"post-1511061","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chat","7":"pa_marque-hills-pet-nutrition","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I\/D Digestive Kitten Poulet - chaton Hill&#039;s - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Hill\u2019s Prescription Diet i\/d - Croquettes pour Chaton est un aliment di\u00e9t\u00e9tique complet hautement digestible formul\u00e9 pour r\u00e9duire les troubles de l\u2019absorption intestinale, et compenser la mauvaise digestion et l\u2019insuffisance pancr\u00e9atique exocrine chez le chaton.  Cet aliment a une teneur \u00e9lev\u00e9e en sodium et en potassium ainsi qu\u2019en ingr\u00e9dients hautement digestibles.  Utilisation :   Gastro-ent\u00e9rite aigu\u00eb (diarrh\u00e9e ou vomissements)  Constipation (alt\u00e9ration de la motilit\u00e9)  Insuffisance pancr\u00e9atique exocrine (IPE)  Gastrite (aigu\u00eb ou chronique)  Troubles \u0153sophagiens  Pancr\u00e9atite  R\u00e9cup\u00e9ration apr\u00e8s une chirurgie gastro-intestinale  Croissance  Demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I\/D Digestive Kitten Poulet - chaton Hill&#039;s - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Hill\u2019s Prescription Diet i\/d - Croquettes pour Chaton est un aliment di\u00e9t\u00e9tique complet hautement digestible formul\u00e9 pour r\u00e9duire les troubles de l\u2019absorption intestinale, et compenser la mauvaise digestion et l\u2019insuffisance pancr\u00e9atique exocrine chez le chaton.  Cet aliment a une teneur \u00e9lev\u00e9e en sodium et en potassium ainsi qu\u2019en ingr\u00e9dients hautement digestibles.  Utilisation :   Gastro-ent\u00e9rite aigu\u00eb (diarrh\u00e9e ou vomissements)  Constipation (alt\u00e9ration de la motilit\u00e9)  Insuffisance pancr\u00e9atique exocrine (IPE)  Gastrite (aigu\u00eb ou chronique)  Troubles \u0153sophagiens  Pancr\u00e9atite  R\u00e9cup\u00e9ration apr\u00e8s une chirurgie gastro-intestinale  Croissance  Demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T20:58:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/09\/digestive-care-kitten-croquettes-hills.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"32,55&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chat-i-d-digestive-care-kitten-poulet\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chat-i-d-digestive-care-kitten-poulet\\\/\",\"name\":\"I\\\/D Digestive Kitten Poulet - chaton Hill's - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chat-i-d-digestive-care-kitten-poulet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chat-i-d-digestive-care-kitten-poulet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/digestive-care-kitten-croquettes-hills.png\",\"datePublished\":\"2025-10-01T10:25:54+00:00\",\"dateModified\":\"2025-11-13T20:58:42+00:00\",\"description\":\"Hill\u2019s Prescription Diet i\\\/d - Croquettes pour Chaton est un aliment di\u00e9t\u00e9tique complet hautement digestible formul\u00e9 pour r\u00e9duire les troubles de l\u2019absorption intestinale, et compenser la mauvaise digestion et l\u2019insuffisance pancr\u00e9atique exocrine chez le chaton. Cet aliment a une teneur \u00e9lev\u00e9e en sodium et en potassium ainsi qu\u2019en ingr\u00e9dients hautement digestibles. Utilisation : Gastro-ent\u00e9rite aigu\u00eb (diarrh\u00e9e ou vomissements) Constipation (alt\u00e9ration de la motilit\u00e9) Insuffisance pancr\u00e9atique exocrine (IPE) Gastrite (aigu\u00eb ou chronique) Troubles \u0153sophagiens Pancr\u00e9atite R\u00e9cup\u00e9ration apr\u00e8s une chirurgie gastro-intestinale Croissance Demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chat-i-d-digestive-care-kitten-poulet\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chat-i-d-digestive-care-kitten-poulet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chat-i-d-digestive-care-kitten-poulet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/digestive-care-kitten-croquettes-hills.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/digestive-care-kitten-croquettes-hills.png\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chat-i-d-digestive-care-kitten-poulet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"I\\\/D Digestive Kitten Poulet &#8211; chaton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Hill&#039;s\" \/>\n<meta property=\"product:price:amount\" content=\"32.55\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-HCT072\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I\/D Digestive Kitten Poulet - chaton Hill's - V\u00e9torino","description":"Hill\u2019s Prescription Diet i\/d - Croquettes pour Chaton est un aliment di\u00e9t\u00e9tique complet hautement digestible formul\u00e9 pour r\u00e9duire les troubles de l\u2019absorption intestinale, et compenser la mauvaise digestion et l\u2019insuffisance pancr\u00e9atique exocrine chez le chaton.  Cet aliment a une teneur \u00e9lev\u00e9e en sodium et en potassium ainsi qu\u2019en ingr\u00e9dients hautement digestibles.  Utilisation :   Gastro-ent\u00e9rite aigu\u00eb (diarrh\u00e9e ou vomissements)  Constipation (alt\u00e9ration de la motilit\u00e9)  Insuffisance pancr\u00e9atique exocrine (IPE)  Gastrite (aigu\u00eb ou chronique)  Troubles \u0153sophagiens  Pancr\u00e9atite  R\u00e9cup\u00e9ration apr\u00e8s une chirurgie gastro-intestinale  Croissance  Demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"I\/D Digestive Kitten Poulet - chaton Hill's - V\u00e9torino","og_description":"Hill\u2019s Prescription Diet i\/d - Croquettes pour Chaton est un aliment di\u00e9t\u00e9tique complet hautement digestible formul\u00e9 pour r\u00e9duire les troubles de l\u2019absorption intestinale, et compenser la mauvaise digestion et l\u2019insuffisance pancr\u00e9atique exocrine chez le chaton.  Cet aliment a une teneur \u00e9lev\u00e9e en sodium et en potassium ainsi qu\u2019en ingr\u00e9dients hautement digestibles.  Utilisation :   Gastro-ent\u00e9rite aigu\u00eb (diarrh\u00e9e ou vomissements)  Constipation (alt\u00e9ration de la motilit\u00e9)  Insuffisance pancr\u00e9atique exocrine (IPE)  Gastrite (aigu\u00eb ou chronique)  Troubles \u0153sophagiens  Pancr\u00e9atite  R\u00e9cup\u00e9ration apr\u00e8s une chirurgie gastro-intestinale  Croissance  Demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-11-13T20:58:42+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/09\/digestive-care-kitten-croquettes-hills.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"32,55&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/","url":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/","name":"I\/D Digestive Kitten Poulet - chaton Hill's - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/09\/digestive-care-kitten-croquettes-hills.png","datePublished":"2025-10-01T10:25:54+00:00","dateModified":"2025-11-13T20:58:42+00:00","description":"Hill\u2019s Prescription Diet i\/d - Croquettes pour Chaton est un aliment di\u00e9t\u00e9tique complet hautement digestible formul\u00e9 pour r\u00e9duire les troubles de l\u2019absorption intestinale, et compenser la mauvaise digestion et l\u2019insuffisance pancr\u00e9atique exocrine chez le chaton. Cet aliment a une teneur \u00e9lev\u00e9e en sodium et en potassium ainsi qu\u2019en ingr\u00e9dients hautement digestibles. Utilisation : Gastro-ent\u00e9rite aigu\u00eb (diarrh\u00e9e ou vomissements) Constipation (alt\u00e9ration de la motilit\u00e9) Insuffisance pancr\u00e9atique exocrine (IPE) Gastrite (aigu\u00eb ou chronique) Troubles \u0153sophagiens Pancr\u00e9atite R\u00e9cup\u00e9ration apr\u00e8s une chirurgie gastro-intestinale Croissance Demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/09\/digestive-care-kitten-croquettes-hills.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/09\/digestive-care-kitten-croquettes-hills.png","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chat-i-d-digestive-care-kitten-poulet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"I\/D Digestive Kitten Poulet &#8211; chaton"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Hill's","product_price_amount":"32.55","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-HCT072","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product\/1511061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media\/1511224"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media?parent=1511061"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_cat?post=1511061"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_tag?post=1511061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}