{"id":872955,"date":"2024-03-20T15:33:36","date_gmt":"2024-03-20T14:33:36","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/"},"modified":"2026-06-08T07:06:16","modified_gmt":"2026-06-08T05:06:16","slug":"chien-chat-a-d-urgent-poulet-boite","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/","title":{"rendered":"Chien Chat a\/d Urgent Care"},"content":{"rendered":"<p><strong>Hill&#8217;s Prescription Diet a\/d Canine\/Feline est un aliment\u00a0\u00a0facilement digestible et \u00e0 la consistance molle pour rendre ce produit plus facilement administrable.<br \/>\n<\/strong><\/p>\n<p><strong>Utilisation :<br \/>\n<\/strong><\/p>\n<ul>\n<li>Chien\u00a0ou chat<\/li>\n<li>Convalescence<\/li>\n<\/ul>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li>Une teneur \u00e9lev\u00e9e en prot\u00e9ines sp\u00e9cifiques pour<strong> favoriser la cicatrisation et pr\u00e9server le syst\u00e8me immunitaire<\/strong>.<\/li>\n<li>Des ingr\u00e9dients<strong> facilement digestibles et des calories suppl\u00e9mentaires<\/strong> pour les animaux en phase de convalescence suite \u00e0 une chirurgie ou une maladie grave.<\/li>\n<li>Un go\u00fbt excellent et une<strong> consistance molle<\/strong> pour rendre ce produit plus facilement administrable, notamment si il est n\u00e9cessaire d&#8217;aider votre animal \u00e0 manger (\u00e0 la main ou utilisant une seringue).<\/li>\n<\/ul>\n<p><strong>Ce produit est destin\u00e9 \u00e0 la prise en charge d&#8217;une maladie. Il est conseill\u00e9 de demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Hill&#8217;s\u00a0Prescription Diet a\/d Canine\/Feline\u00a0est un aliment\u00a0\u00a0facilement digestible et \u00e0 la\u00a0consistance molle pour rendre ce produit plus facilement administrable.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chien\u00a0ou chat<\/li>\n<li>Convalescence<\/li>\n<\/ul>\n<p><strong>Ce produit est destin\u00e9 \u00e0 la prise en charge d&#8217;une maladie. Il est conseill\u00e9 de demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.<\/strong><\/p>\n","protected":false},"featured_media":1184460,"template":"","meta":[],"product_cat":[12551,12552,12581,12582,2697,2698],"product_tag":[],"class_list":{"0":"post-872955","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chat","7":"product_cat-alimentation-du-chien","8":"product_cat-alimentation-medicalisee-pour-chat","9":"product_cat-alimentation-medicalisee-pour-chien","10":"product_cat-chat","11":"product_cat-chien","12":"pa_marque-hills-pet-nutrition","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prescription Diet (Hill&#039;s) Chien Chat a\/d Urgent Care Hill&#039;s - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Hill&#039;s\u00a0Prescription Diet a\/d Canine\/Feline\u00a0est un aliment\u00a0\u00a0facilement digestible et \u00e0 la\u00a0consistance molle pour rendre ce produit plus facilement administrable.  Utilisation :   Chien\u00a0ou chat  Convalescence  Ce produit est destin\u00e9 \u00e0 la prise en charge d&#039;une maladie. Il est conseill\u00e9 de demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prescription Diet (Hill&#039;s) Chien Chat a\/d Urgent Care Hill&#039;s - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Hill&#039;s\u00a0Prescription Diet a\/d Canine\/Feline\u00a0est un aliment\u00a0\u00a0facilement digestible et \u00e0 la\u00a0consistance molle pour rendre ce produit plus facilement administrable.  Utilisation :   Chien\u00a0ou chat  Convalescence  Ce produit est destin\u00e9 \u00e0 la prise en charge d&#039;une maladie. Il est conseill\u00e9 de demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T05:06:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/03\/chien-chat-ad-urgent-care-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-chat-a-d-urgent-poulet-boite\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-chat-a-d-urgent-poulet-boite\\\/\",\"name\":\"Prescription Diet (Hill's) Chien Chat a\\\/d Urgent Care Hill's - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-chat-a-d-urgent-poulet-boite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-chat-a-d-urgent-poulet-boite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/chien-chat-ad-urgent-care-2.webp\",\"datePublished\":\"2024-03-20T14:33:36+00:00\",\"dateModified\":\"2026-06-08T05:06:16+00:00\",\"description\":\"Hill's\u00a0Prescription Diet a\\\/d Canine\\\/Feline\u00a0est un aliment\u00a0\u00a0facilement digestible et \u00e0 la\u00a0consistance molle pour rendre ce produit plus facilement administrable. Utilisation : Chien\u00a0ou chat Convalescence Ce produit est destin\u00e9 \u00e0 la prise en charge d'une maladie. Il est conseill\u00e9 de demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-chat-a-d-urgent-poulet-boite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-chat-a-d-urgent-poulet-boite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-chat-a-d-urgent-poulet-boite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/chien-chat-ad-urgent-care-2.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/chien-chat-ad-urgent-care-2.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-chat-a-d-urgent-poulet-boite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chien Chat a\\\/d Urgent Care\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Hill&#039;s\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prescription Diet (Hill's) Chien Chat a\/d Urgent Care Hill's - V\u00e9torino","description":"Hill's\u00a0Prescription Diet a\/d Canine\/Feline\u00a0est un aliment\u00a0\u00a0facilement digestible et \u00e0 la\u00a0consistance molle pour rendre ce produit plus facilement administrable.  Utilisation :   Chien\u00a0ou chat  Convalescence  Ce produit est destin\u00e9 \u00e0 la prise en charge d'une maladie. Il est conseill\u00e9 de demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Prescription Diet (Hill's) Chien Chat a\/d Urgent Care Hill's - V\u00e9torino","og_description":"Hill's\u00a0Prescription Diet a\/d Canine\/Feline\u00a0est un aliment\u00a0\u00a0facilement digestible et \u00e0 la\u00a0consistance molle pour rendre ce produit plus facilement administrable.  Utilisation :   Chien\u00a0ou chat  Convalescence  Ce produit est destin\u00e9 \u00e0 la prise en charge d'une maladie. Il est conseill\u00e9 de demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-06-08T05:06:16+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/03\/chien-chat-ad-urgent-care-2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/","url":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/","name":"Prescription Diet (Hill's) Chien Chat a\/d Urgent Care Hill's - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/03\/chien-chat-ad-urgent-care-2.webp","datePublished":"2024-03-20T14:33:36+00:00","dateModified":"2026-06-08T05:06:16+00:00","description":"Hill's\u00a0Prescription Diet a\/d Canine\/Feline\u00a0est un aliment\u00a0\u00a0facilement digestible et \u00e0 la\u00a0consistance molle pour rendre ce produit plus facilement administrable. Utilisation : Chien\u00a0ou chat Convalescence Ce produit est destin\u00e9 \u00e0 la prise en charge d'une maladie. Il est conseill\u00e9 de demander conseil \u00e0 votre v\u00e9t\u00e9rinaire avant utilisation.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/03\/chien-chat-ad-urgent-care-2.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/03\/chien-chat-ad-urgent-care-2.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-chat-a-d-urgent-poulet-boite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Chien Chat a\/d Urgent Care"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Hill's","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product\/872955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media\/1184460"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media?parent=872955"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_cat?post=872955"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_tag?post=872955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}