{"id":89107,"date":"2020-06-26T02:59:49","date_gmt":"2020-06-26T00:59:49","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/activita-veau-gel\/"},"modified":"2026-07-15T09:41:16","modified_gmt":"2026-07-15T07:41:16","slug":"activita-veau-gel","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/activita-veau-gel\/","title":{"rendered":"Activita Veau Gel"},"content":{"rendered":"<p><strong>Activita Veau est un suppl\u00e9ment nutritionnel en oligo-\u00e9l\u00e9ments sous forme de gel, pour les veaux en p\u00e9riode critique comme lors de la mise \u00e0 l&#8217;herbe ou en convalescence.\u00a0<\/strong><\/p>\n<p>Formule 3 en 1 (vitamines, oligo-\u00e9l\u00e9ments et acides amin\u00e9s) permettant de corriger les d\u00e9ficits du colostrum maternel :<\/p>\n<ul>\n<li>Stimule l&#8217;app\u00e9tit et le r\u00e9flexe de succion.<\/li>\n<li>Stimule le m\u00e9tabolisme \u00e9nerg\u00e9tique et l&#8217;activit\u00e9 musculaire.<\/li>\n<li>Aide \u00e0 compenser les pertes en p\u00e9riode critique.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Activita Veau est un suppl\u00e9ment nutritionnel en oligo-\u00e9l\u00e9ments sous forme de gel, pour les veaux en p\u00e9riode critique comme lors de la mise \u00e0 l&#8217;herbe ou en convalescence.\u00a0<\/strong><\/p>\n<p>Formule 3 en 1 (vitamines, oligo-\u00e9l\u00e9ments et acides amin\u00e9s) permettant de corriger les d\u00e9ficits du colostrum maternel :<\/p>\n<ul>\n<li>Stimule l&#8217;app\u00e9tit et le r\u00e9flexe de succion.<\/li>\n<li>Stimule le m\u00e9tabolisme \u00e9nerg\u00e9tique et l&#8217;activit\u00e9 musculaire.<\/li>\n<li>Aide \u00e0 compenser les pertes en p\u00e9riode critique.<\/li>\n<\/ul>\n","protected":false},"featured_media":1423948,"template":"","meta":[],"product_cat":[6864,6870],"product_tag":[],"class_list":{"0":"post-89107","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-animaux-delevage","7":"product_cat-bovins","8":"pa_marque-vetalis","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Activita Veau Gel Vetalis - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Activita Veau est un suppl\u00e9ment nutritionnel en oligo-\u00e9l\u00e9ments sous forme de gel, pour les veaux en p\u00e9riode critique comme lors de la mise \u00e0 l&#039;herbe ou en convalescence.\u00a0  Formule 3 en 1 (vitamines, oligo-\u00e9l\u00e9ments et acides amin\u00e9s) permettant de corriger les d\u00e9ficits du colostrum maternel :   Stimule l&#039;app\u00e9tit et le r\u00e9flexe de succion.  Stimule le m\u00e9tabolisme \u00e9nerg\u00e9tique et l&#039;activit\u00e9 musculaire.  Aide \u00e0 compenser les pertes en p\u00e9riode critique.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Activita Veau Gel Vetalis - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Activita Veau est un suppl\u00e9ment nutritionnel en oligo-\u00e9l\u00e9ments sous forme de gel, pour les veaux en p\u00e9riode critique comme lors de la mise \u00e0 l&#039;herbe ou en convalescence.\u00a0  Formule 3 en 1 (vitamines, oligo-\u00e9l\u00e9ments et acides amin\u00e9s) permettant de corriger les d\u00e9ficits du colostrum maternel :   Stimule l&#039;app\u00e9tit et le r\u00e9flexe de succion.  Stimule le m\u00e9tabolisme \u00e9nerg\u00e9tique et l&#039;activit\u00e9 musculaire.  Aide \u00e0 compenser les pertes en p\u00e9riode critique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/activita-veau-gel\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T07:41:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/07\/activita-veau-gel-seringue.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"561\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"173,94&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"Rupture de stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/activita-veau-gel\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/activita-veau-gel\\\/\",\"name\":\"Activita Veau Gel Vetalis - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/activita-veau-gel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/activita-veau-gel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/activita-veau-gel-seringue.png\",\"datePublished\":\"2020-06-26T00:59:49+00:00\",\"dateModified\":\"2026-07-15T07:41:16+00:00\",\"description\":\"Activita Veau est un suppl\u00e9ment nutritionnel en oligo-\u00e9l\u00e9ments sous forme de gel, pour les veaux en p\u00e9riode critique comme lors de la mise \u00e0 l'herbe ou en convalescence.\u00a0 Formule 3 en 1 (vitamines, oligo-\u00e9l\u00e9ments et acides amin\u00e9s) permettant de corriger les d\u00e9ficits du colostrum maternel : Stimule l'app\u00e9tit et le r\u00e9flexe de succion. Stimule le m\u00e9tabolisme \u00e9nerg\u00e9tique et l'activit\u00e9 musculaire. Aide \u00e0 compenser les pertes en p\u00e9riode critique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/activita-veau-gel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/activita-veau-gel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/activita-veau-gel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/activita-veau-gel-seringue.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/activita-veau-gel-seringue.png\",\"width\":600,\"height\":561},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/activita-veau-gel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Activita Veau Gel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Vetalis\" \/>\n<meta property=\"product:price:amount\" content=\"173.94\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-ACT043\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Activita Veau Gel Vetalis - V\u00e9torino","description":"Activita Veau est un suppl\u00e9ment nutritionnel en oligo-\u00e9l\u00e9ments sous forme de gel, pour les veaux en p\u00e9riode critique comme lors de la mise \u00e0 l'herbe ou en convalescence.\u00a0  Formule 3 en 1 (vitamines, oligo-\u00e9l\u00e9ments et acides amin\u00e9s) permettant de corriger les d\u00e9ficits du colostrum maternel :   Stimule l'app\u00e9tit et le r\u00e9flexe de succion.  Stimule le m\u00e9tabolisme \u00e9nerg\u00e9tique et l'activit\u00e9 musculaire.  Aide \u00e0 compenser les pertes en p\u00e9riode critique.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Activita Veau Gel Vetalis - V\u00e9torino","og_description":"Activita Veau est un suppl\u00e9ment nutritionnel en oligo-\u00e9l\u00e9ments sous forme de gel, pour les veaux en p\u00e9riode critique comme lors de la mise \u00e0 l'herbe ou en convalescence.\u00a0  Formule 3 en 1 (vitamines, oligo-\u00e9l\u00e9ments et acides amin\u00e9s) permettant de corriger les d\u00e9ficits du colostrum maternel :   Stimule l'app\u00e9tit et le r\u00e9flexe de succion.  Stimule le m\u00e9tabolisme \u00e9nerg\u00e9tique et l'activit\u00e9 musculaire.  Aide \u00e0 compenser les pertes en p\u00e9riode critique.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/activita-veau-gel\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-07-15T07:41:16+00:00","og_image":[{"width":600,"height":561,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/07\/activita-veau-gel-seringue.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"173,94&euro;","Disponibilit\u00e9":"Rupture de stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/activita-veau-gel\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/activita-veau-gel\/","name":"Activita Veau Gel Vetalis - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/activita-veau-gel\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/activita-veau-gel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/07\/activita-veau-gel-seringue.png","datePublished":"2020-06-26T00:59:49+00:00","dateModified":"2026-07-15T07:41:16+00:00","description":"Activita Veau est un suppl\u00e9ment nutritionnel en oligo-\u00e9l\u00e9ments sous forme de gel, pour les veaux en p\u00e9riode critique comme lors de la mise \u00e0 l'herbe ou en convalescence.\u00a0 Formule 3 en 1 (vitamines, oligo-\u00e9l\u00e9ments et acides amin\u00e9s) permettant de corriger les d\u00e9ficits du colostrum maternel : Stimule l'app\u00e9tit et le r\u00e9flexe de succion. Stimule le m\u00e9tabolisme \u00e9nerg\u00e9tique et l'activit\u00e9 musculaire. Aide \u00e0 compenser les pertes en p\u00e9riode critique.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/activita-veau-gel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/activita-veau-gel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/activita-veau-gel\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/07\/activita-veau-gel-seringue.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/07\/activita-veau-gel-seringue.png","width":600,"height":561},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/activita-veau-gel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Activita Veau Gel"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Vetalis","product_price_amount":"173.94","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"C-ACT043","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product\/89107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media\/1423948"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media?parent=89107"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_cat?post=89107"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_tag?post=89107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}