{"id":98055,"date":"2020-06-29T22:57:49","date_gmt":"2020-06-29T20:57:49","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/"},"modified":"2026-07-07T09:41:22","modified_gmt":"2026-07-07T07:41:22","slug":"jouet-chat-canne-a-peche-plumes-et-cuir","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/","title":{"rendered":"Jouet chat Trixie : Canne \u00e0 p\u00eache plumes et cuir"},"content":{"rendered":"<div class='hidden'>MATERIEL<\/div>\n<div class='hidden'>Chats<\/div>\n<p>Rien de mieux pour faire courir votre chat ! Ce jouet interactif est assur\u00e9ment celui qu&#8217;il vous faut si vous voulez vous amusez avec votre chat. Aucun ne r\u00e9siste, ils courent tous apr\u00e8s les souris, plumes, lani\u00e8res ou autres fanfreluches que vous agitez sous leur nez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MATERIEL Chats Rien de mieux pour faire courir votre chat ! Ce jouet interactif est assur\u00e9ment celui qu&#8217;il vous faut si vous voulez vous amusez avec votre chat. Aucun ne r\u00e9siste, ils courent tous apr\u00e8s les souris, plumes, lani\u00e8res ou autres fanfreluches que vous agitez sous leur nez.<\/p>\n","protected":false},"featured_media":98054,"template":"","meta":[],"product_cat":[12548,2697,12620],"product_tag":[],"class_list":{"0":"post-98055","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoire-du-chat","7":"product_cat-chat","8":"product_cat-jeux-educatifs-pour-chat","9":"pa_marque-trixie","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jouet chat Trixie : Canne \u00e0 p\u00eache plumes et cuir Trixie - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"MATERIELChatsRien de mieux pour faire courir votre chat ! Ce jouet interactif est assur\u00e9ment celui qu&#039;il vous faut si vous voulez vous amusez avec votre\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jouet chat Trixie : Canne \u00e0 p\u00eache plumes et cuir Trixie - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"MATERIELChatsRien de mieux pour faire courir votre chat ! Ce jouet interactif est assur\u00e9ment celui qu&#039;il vous faut si vous voulez vous amusez avec votre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T07:41:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsJOU741FormatMediumTypeIM.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"2,58&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/marseille-13009\\\/boutique\\\/product\\\/jouet-chat-canne-a-peche-plumes-et-cuir\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/marseille-13009\\\/boutique\\\/product\\\/jouet-chat-canne-a-peche-plumes-et-cuir\\\/\",\"name\":\"Jouet chat Trixie : Canne \u00e0 p\u00eache plumes et cuir Trixie - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/marseille-13009\\\/boutique\\\/product\\\/jouet-chat-canne-a-peche-plumes-et-cuir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/marseille-13009\\\/boutique\\\/product\\\/jouet-chat-canne-a-peche-plumes-et-cuir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsJOU741FormatMediumTypeIM.png\",\"datePublished\":\"2020-06-29T20:57:49+00:00\",\"dateModified\":\"2026-07-07T07:41:22+00:00\",\"description\":\"MATERIELChatsRien de mieux pour faire courir votre chat ! Ce jouet interactif est assur\u00e9ment celui qu'il vous faut si vous voulez vous amusez avec votre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/marseille-13009\\\/boutique\\\/product\\\/jouet-chat-canne-a-peche-plumes-et-cuir\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/marseille-13009\\\/boutique\\\/product\\\/jouet-chat-canne-a-peche-plumes-et-cuir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/marseille-13009\\\/boutique\\\/product\\\/jouet-chat-canne-a-peche-plumes-et-cuir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsJOU741FormatMediumTypeIM.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsJOU741FormatMediumTypeIM.png\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/marseille-13009\\\/boutique\\\/product\\\/jouet-chat-canne-a-peche-plumes-et-cuir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jouet chat Trixie : Canne \u00e0 p\u00eache plumes et cuir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Trixie\" \/>\n<meta property=\"product:price:amount\" content=\"2.58\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-JOU741\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jouet chat Trixie : Canne \u00e0 p\u00eache plumes et cuir Trixie - V\u00e9torino","description":"MATERIELChatsRien de mieux pour faire courir votre chat ! Ce jouet interactif est assur\u00e9ment celui qu'il vous faut si vous voulez vous amusez avec votre","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Jouet chat Trixie : Canne \u00e0 p\u00eache plumes et cuir Trixie - V\u00e9torino","og_description":"MATERIELChatsRien de mieux pour faire courir votre chat ! Ce jouet interactif est assur\u00e9ment celui qu'il vous faut si vous voulez vous amusez avec votre","og_url":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-07-07T07:41:22+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsJOU741FormatMediumTypeIM.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"2,58&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/marseille-13009\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/","url":"https:\/\/www.vetorino.com\/veterinaire\/marseille-13009\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/","name":"Jouet chat Trixie : Canne \u00e0 p\u00eache plumes et cuir Trixie - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/marseille-13009\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/marseille-13009\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsJOU741FormatMediumTypeIM.png","datePublished":"2020-06-29T20:57:49+00:00","dateModified":"2026-07-07T07:41:22+00:00","description":"MATERIELChatsRien de mieux pour faire courir votre chat ! Ce jouet interactif est assur\u00e9ment celui qu'il vous faut si vous voulez vous amusez avec votre","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/marseille-13009\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/marseille-13009\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/marseille-13009\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsJOU741FormatMediumTypeIM.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsJOU741FormatMediumTypeIM.png","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/marseille-13009\/boutique\/product\/jouet-chat-canne-a-peche-plumes-et-cuir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Jouet chat Trixie : Canne \u00e0 p\u00eache plumes et cuir"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Trixie","product_price_amount":"2.58","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-JOU741","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product\/98055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media\/98054"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/media?parent=98055"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_cat?post=98055"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/sucyenbrie-centre-94370\/boutique\/wp-json\/wp\/v2\/product_tag?post=98055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}