{"id":101681,"date":"2020-06-30T11:54:39","date_gmt":"2020-06-30T09:54:39","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/sac-de-pansage-oster\/"},"modified":"2023-05-05T02:42:13","modified_gmt":"2023-05-05T00:42:13","slug":"sac-de-pansage-oster","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/tignieujameyzieu-38230\/boutique\/product\/sac-de-pansage-oster\/","title":{"rendered":"Sac de pansage Oster"},"content":{"rendered":"<p>Pratique et l\u00e9ger, ce sac comprend l&#8217;essentiel n\u00e9cessaire au toilettage de votre cheval ou poney&#8230;<br \/>\nVous y trouverez une \u00e9trille en caoutchouc, une brosse de nettoyage, une brosse de lustrage, une brosse pour la crini\u00e8re et la queue, un peigne et un cure-pied. Bien entendu avec l&#8217;assurance de la qualit\u00e9 Oster !<br \/>\nPossibilit\u00e9 de le compl\u00e9ter par les autres r\u00e9f\u00e9rences de cette gamme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Sac de pansage Oster<\/strong>. Pratique et l\u00e9ger, ce sac comprend l&#8217;essentiel n\u00e9cessaire au toilettage de votre cheval ou poney<\/p>\n","protected":false},"featured_media":188940,"template":"","meta":[],"product_cat":[12549,12547,12760],"product_tag":[],"class_list":{"0":"post-101681","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-du-cheval","7":"product_cat-cheval","8":"product_cat-materiel-et-equipement-du-cheval","9":"pa_marque-materiel","11":"first","12":"outofstock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sac de pansage Oster Mat\u00e9riel - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Sac de pansage Oster. Pratique et l\u00e9ger, ce sac comprend l&#039;essentiel n\u00e9cessaire au toilettage de votre cheval ou poney\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sac de pansage Oster Mat\u00e9riel - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Sac de pansage Oster. Pratique et l\u00e9ger, ce sac comprend l&#039;essentiel n\u00e9cessaire au toilettage de votre cheval ou poney\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/tignieujameyzieu-38230\/boutique\/product\/sac-de-pansage-oster\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-05T00:42:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/kit-de-pansage-equitation-oster.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"99,53&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"Rupture de stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/sac-de-pansage-oster\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/sac-de-pansage-oster\\\/\",\"name\":\"Sac de pansage Oster Mat\u00e9riel - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/sac-de-pansage-oster\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/sac-de-pansage-oster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/kit-de-pansage-equitation-oster.jpeg\",\"datePublished\":\"2020-06-30T09:54:39+00:00\",\"dateModified\":\"2023-05-05T00:42:13+00:00\",\"description\":\"Sac de pansage Oster. Pratique et l\u00e9ger, ce sac comprend l'essentiel n\u00e9cessaire au toilettage de votre cheval ou poney\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/sac-de-pansage-oster\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/sac-de-pansage-oster\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/sac-de-pansage-oster\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/kit-de-pansage-equitation-oster.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/kit-de-pansage-equitation-oster.jpeg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/sac-de-pansage-oster\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sac de pansage Oster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Mat\u00e9riel\" \/>\n<meta property=\"product:price:amount\" content=\"99.53\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-SAC722\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sac de pansage Oster Mat\u00e9riel - V\u00e9torino","description":"Sac de pansage Oster. Pratique et l\u00e9ger, ce sac comprend l'essentiel n\u00e9cessaire au toilettage de votre cheval ou poney","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Sac de pansage Oster Mat\u00e9riel - V\u00e9torino","og_description":"Sac de pansage Oster. Pratique et l\u00e9ger, ce sac comprend l'essentiel n\u00e9cessaire au toilettage de votre cheval ou poney","og_url":"https:\/\/www.vetorino.com\/veterinaire\/tignieujameyzieu-38230\/boutique\/product\/sac-de-pansage-oster\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2023-05-05T00:42:13+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/kit-de-pansage-equitation-oster.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"99,53&euro;","Disponibilit\u00e9":"Rupture de stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/sac-de-pansage-oster\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/sac-de-pansage-oster\/","name":"Sac de pansage Oster Mat\u00e9riel - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/sac-de-pansage-oster\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/sac-de-pansage-oster\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/kit-de-pansage-equitation-oster.jpeg","datePublished":"2020-06-30T09:54:39+00:00","dateModified":"2023-05-05T00:42:13+00:00","description":"Sac de pansage Oster. Pratique et l\u00e9ger, ce sac comprend l'essentiel n\u00e9cessaire au toilettage de votre cheval ou poney","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/sac-de-pansage-oster\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/sac-de-pansage-oster\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/sac-de-pansage-oster\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/kit-de-pansage-equitation-oster.jpeg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/kit-de-pansage-equitation-oster.jpeg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/sac-de-pansage-oster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Sac de pansage Oster"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Mat\u00e9riel","product_price_amount":"99.53","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"C-SAC722","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tignieujameyzieu-38230\/boutique\/wp-json\/wp\/v2\/product\/101681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tignieujameyzieu-38230\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tignieujameyzieu-38230\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tignieujameyzieu-38230\/boutique\/wp-json\/wp\/v2\/media\/188940"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tignieujameyzieu-38230\/boutique\/wp-json\/wp\/v2\/media?parent=101681"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tignieujameyzieu-38230\/boutique\/wp-json\/wp\/v2\/product_cat?post=101681"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tignieujameyzieu-38230\/boutique\/wp-json\/wp\/v2\/product_tag?post=101681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}