{"id":295644,"date":"2022-03-05T16:52:29","date_gmt":"2022-03-05T15:52:29","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=295644"},"modified":"2024-08-08T17:21:57","modified_gmt":"2024-08-08T15:21:57","slug":"mon-chien-est-trop-gros-obesite-du-chien","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/","title":{"rendered":"Mon chien est trop gros &#8211; Ob\u00e9sit\u00e9 du chien"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"295644\" class=\"elementor elementor-295644\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79ba1c4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79ba1c4b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45714528\" data-id=\"45714528\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33daeb24 elementor-widget elementor-widget-text-editor\" data-id=\"33daeb24\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<h2 class=\"wp-block-heading\">L&#8217;ob\u00e9sit\u00e9 des chiens<\/h2>\n<p><\/p>\n<p><\/p>\n<p><strong>L\u2019ob\u00e9sit\u00e9<\/strong> est un v\u00e9ritable fl\u00e9au chez les hommes comme chez les animaux\u2026 ! C\u2019est une <strong>maladie grave<\/strong> qui touche pr\u00e8s de 40% des animaux de compagnie \u00e0 l\u2019\u00e9chelle europ\u00e9enne. Pour les <strong>chiens<\/strong> qui sont touch\u00e9s, c\u2019est une pathologie qui alt\u00e8re plusieurs de leurs organes et qui a des cons\u00e9quences importantes sur leur <strong>sant\u00e9<\/strong> et leur organisme. L\u2019ob\u00e9sit\u00e9 des animaux peut se traiter mais il est pr\u00e9f\u00e9rable de ne pas en arriver l\u00e0&#8230; Pour ce faire, il faut adopter une <strong>bonne alimentation<\/strong> et des principes di\u00e9t\u00e9tiques pr\u00e9cis.<\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"has-text-align-left wp-block-heading\">L&#8217;ob\u00e9sit\u00e9 en quelques mots<\/h2>\n<p><\/p>\n<p><\/p>\n<p>Un chien est consid\u00e9r\u00e9 comme <strong>ob\u00e8se<\/strong> lorsque son surpoids est bien au-dessus de 25% de son poids dit id\u00e9al. En plus du poids corporel \u00e0 proprement dit, il faut \u00e9galement prendre en compte le <strong>score corporel<\/strong> de votre animal. Un <strong>chien<\/strong> avec un score de 1 est tr\u00e8s mince, tandis qu\u2019un chien avec un score de 9 est dit tr\u00e8s \u00e9pais. Ce score corporel sera d\u00e9termin\u00e9 par votre <strong>v\u00e9t\u00e9rinaire<\/strong> qui conna\u00eet les crit\u00e8res et a une grille \u00e0 laquelle se r\u00e9f\u00e9rer. Pour constater d\u2019une <strong>masse de graisse<\/strong> trop importante, vous et\/ou votre v\u00e9t\u00e9rinaire pouvez palper les c\u00f4tes de votre chien. En outre, pensez \u00e9galement \u00e0 surveiller la silhouette de votre chien sur le c\u00f4t\u00e9 et au-dessus.<\/p>\n<p>En tant que pathologie grave, <strong>l\u2019ob\u00e9sit\u00e9<\/strong> peut \u00eatre particuli\u00e8rement dangereuse pour votre <strong>chien<\/strong>. Cela peut lui d\u00e9velopper des douleurs articulaires, faire baisser petit \u00e0 petit ses d\u00e9fenses immunitaires et le rendre plus sujet \u00e0 diff\u00e9rentes infections. En outre, l\u2019ob\u00e9sit\u00e9 entraine chez les hommes comme chez les chiens, des <strong>probl\u00e8mes cardio-vasculaires<\/strong>, de la constipation, voire de l\u2019infertilit\u00e9 et des probl\u00e8mes de mises-bas pour les chiennes\u2026 De surcro\u00eet, l\u2019ob\u00e9sit\u00e9 pour les chiens r\u00e9duit \u00e9galement consid\u00e9rablement leur esp\u00e9rance de vie.<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"has-text-align-left wp-block-heading\">Les causes de l&#8217;ob\u00e9sit\u00e9 pour un chien\u00a0<\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-295650 alignright\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dalmatian-g319d1dfcc_1920-202x300.jpg\" alt=\"Les causes de l'ob\u00e9sit\u00e9 pour un chien\u00a0\" width=\"202\" height=\"300\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dalmatian-g319d1dfcc_1920-202x300.jpg 202w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dalmatian-g319d1dfcc_1920-689x1024.jpg 689w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dalmatian-g319d1dfcc_1920-768x1141.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dalmatian-g319d1dfcc_1920-1034x1536.jpg 1034w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dalmatian-g319d1dfcc_1920-555x825.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dalmatian-g319d1dfcc_1920-64x95.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dalmatian-g319d1dfcc_1920.jpg 1292w\" sizes=\"(max-width: 202px) 100vw, 202px\" \/><\/p>\n<p><\/p>\n<p><\/p>\n<p>Plusieurs causes, terrains connus peuvent entra\u00eener une ob\u00e9sit\u00e9 pour un chien. Parmi eux : une <strong>alimentation trop importante<\/strong>, la st\u00e9rilisation, le manque d\u2019activit\u00e9 physique ; mais aussi la <strong>g\u00e9n\u00e9tique<\/strong>, d\u2019autres maladies m\u00e9taboliques comme la thyro\u00efde, le syndrome de Cushing\u2026<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">Comment traiter l&#8217;ob\u00e9sit\u00e9 de mon chien<\/h2>\n<p><\/p>\n<p><\/p>\n<p><strong>Traiter l\u2019ob\u00e9sit\u00e9 de votre chien<\/strong> ne sera pas une mince affaire mais il existe des solutions\u2026 D\u2019abord, commencez \u00e0 diminuez l\u2019apport de mati\u00e8res grasses alimentaires pour votre chien. Remplacez par des <strong>apports en prot\u00e9ines<\/strong> qui lui feront gagner de la masse musculaire, plut\u00f4t que graisseuse.<\/p>\n<p>Ensuite, veillez \u00e0 ce que votre <strong>chien<\/strong> pratique une <strong>activit\u00e9 physique r\u00e9guli\u00e8re<\/strong>, adapt\u00e9e \u00e0 son poids et son \u00e2ge\u2026. Ce ne sera pas facile mais cela permettra de r\u00e9duire une \u00e9volution n\u00e9gative\u2026 Votre chien perdra lentement du poids, il aura faim et vous demandera plus de croquettes\u2026\u00a0! N\u2019h\u00e9sitez pas ainsi, en accord avec votre v\u00e9t\u00e9rinaire, \u00e0 lui offrir des <strong>aliments pour lutter contre son ob\u00e9sit\u00e9<\/strong>. Des croquettes all\u00e9g\u00e9es qui l\u2019aideront \u00e0 retrouver la forme, \u00e0 perdre du poids.<\/p>\n<p>Dans son ob\u00e9sit\u00e9, votre chien doit \u00eatre bien suivi et pes\u00e9 r\u00e9guli\u00e8rement.<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">Pr\u00e9venir la prise de poids de mon chien\u00a0<\/h2>\n<p><img decoding=\"async\" class=\"size-medium wp-image-295649 alignleft\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-300x200.jpg\" alt=\"Pr\u00e9venir l'ob\u00e9sit\u00e9 de son chien\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-300x200.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-1024x683.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-768x512.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-1536x1024.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-2048x1365.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-750x500.jpg 750w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-555x370.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-64x43.jpg 64w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><\/p>\n<p><\/p>\n<p>Vous l\u2019aurez compris, <strong>l\u2019ob\u00e9sit\u00e9<\/strong>, m\u00eame pour un chien, se pr\u00e9vient, s\u2019anticipe autant que possible\u2026 D\u00e8s son plus jeune \u00e2ge, il faut veiller \u00e0 <strong>l\u2019\u00e9quilibre de votre chien<\/strong> en lui donnant la bonne quantit\u00e9 de croquette, en ajustant ce que vous lui donnez \u00e0 ses besoins. En outre, il faut \u00e9valuer r\u00e9guli\u00e8rement son score corporel afin d\u2019ajuster si besoin et d\u2019anticiper les mauvaises surprises\u2026 Ne vous inqui\u00e9tez pas, vous ne privez pas votre animal ! Tout ce que vous faites en contr\u00f4lant son alimentation et en veillant \u00e0 ce qu\u2019il fasse de l\u2019exercice, est de <strong>prendre soin de lui<\/strong> !<\/p>\n<p>De plus, lorsque votre chien est <strong>st\u00e9rilis\u00e9<\/strong>, son m\u00e9tabolisme est plus faible et il faut donc diminuer d\u2019autant plus sa portion. En plus des prot\u00e9ines et fibres essentielles \u00e0 son \u00e9quilibre, n\u2019h\u00e9sitez pas \u00e0 lui apporter des min\u00e9raux, des acides gras et des vitamines\u00a0! Cela compensera largement et le <strong>surpoids<\/strong> ne sera plus qu\u2019un mauvais r\u00eave pour vous et votre <strong>compagnon \u00e0 4 pattes\u00a0<\/strong>!<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-585399e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"585399e3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d008fb7\" data-id=\"7d008fb7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-102fe47f elementor-widget elementor-widget-heading\" data-id=\"102fe47f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"line-height: 1.4;margin-top: 20px;margin-bottom: 10px;font-size: 18px;text-align: center\">S\u00e9lections de produits v\u00e9t\u00e9rinaire contre l'ob\u00e9sit\u00e9 du chien<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dee794d product_alcyon elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dee794d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-26e02824\" data-id=\"26e02824\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f552ef0 elementor-widget elementor-widget-image\" data-id=\"1f552ef0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298975\" alt=\"hill&#039;s-neutered-dog-adult-medium-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16fb2f1a elementor-widget elementor-widget-heading\" data-id=\"16fb2f1a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hill's NEUTERED DOG ADULT MEDIUM <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18ccd7fc elementor-widget elementor-widget-text-editor\" data-id=\"18ccd7fc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nutrition r\u00e9volutionnaire prouv\u00e9e pour aider les chiens \u00e0 maintenir un poids id\u00e9al et \u00e0 rester en pleine forme apr\u00e8s la st\u00e9rilisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6693cdb1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6693cdb1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/vetessentials-canine-adult-neutered-medium\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6613e985\" data-id=\"6613e985\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1087aab2 elementor-widget elementor-widget-image\" data-id=\"1087aab2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298976\" alt=\"specifics-chien-crd-1-weight-reduction-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22e54110 elementor-widget elementor-widget-heading\" data-id=\"22e54110\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Specific CHIEN CRD-1 WEIGHT REDUCTION<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1949f7d9 elementor-widget elementor-widget-text-editor\" data-id=\"1949f7d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CRD-1 Weight R\u00e9duction chien apportent une alimentation qui aident \u00e0 la perte de poids pour toutes races confondues.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da450ca elementor-align-center elementor-widget elementor-widget-button\" data-id=\"da450ca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/specific-chien-crd-1-weight-reduction\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-12eca6d5\" data-id=\"12eca6d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c479cfb elementor-widget elementor-widget-image\" data-id=\"3c479cfb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298977\" alt=\"Virbac VET HPM DOG WEIGHT L ET D\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39756e71 elementor-widget elementor-widget-heading\" data-id=\"39756e71\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Virbac VET HPM DOG WEIGHT L ET D <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a48ae38 elementor-widget elementor-widget-text-editor\" data-id=\"3a48ae38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;aliment Veterinary HMP &#8211; Weight Loss &amp; Diabetes Dog est un aliment di\u00e9t\u00e9tique pour chien r\u00e9duisant le surpoids lorsqu&#8217;il est sup\u00e9rieur \u00e0 30%.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-140c2c0b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"140c2c0b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/vet-hpm-dog-weight-ld\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1cefb420\" data-id=\"1cefb420\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d7f4a01 elementor-widget elementor-widget-image\" data-id=\"3d7f4a01\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299210\" alt=\"hills-canine-adult-medium-light-poulet-vetorino.jpg\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino.jpg 458w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22596e4f elementor-widget elementor-widget-heading\" data-id=\"22596e4f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hill's CANINE ADULT LIGHT MEDIUM<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75c75c38 elementor-widget elementor-widget-text-editor\" data-id=\"75c75c38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Canine Adult Light Medium au poulet est sp\u00e9cialement con\u00e7u pour aider les chiens de moyenne race \u00e0 maintenir un poids id\u00e9al.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c5fa56c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5c5fa56c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/canine-adult-light-medium-poulet\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20b5cf2 product_centravet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20b5cf2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-dc02ef7\" data-id=\"dc02ef7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef26e22 elementor-widget elementor-widget-image\" data-id=\"ef26e22\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298975\" alt=\"hill&#039;s-neutered-dog-adult-medium-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee4607b elementor-widget elementor-widget-heading\" data-id=\"ee4607b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hill's NEUTERED DOG ADULT MEDIUM <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a840f3 elementor-widget elementor-widget-text-editor\" data-id=\"9a840f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nutrition r\u00e9volutionnaire prouv\u00e9e pour aider les chiens \u00e0 maintenir un poids id\u00e9al et \u00e0 rester en pleine forme apr\u00e8s la st\u00e9rilisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0690f8e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0690f8e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/hills-neutered-dog-adult-medium\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-eb6830e\" data-id=\"eb6830e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-927888f elementor-widget elementor-widget-image\" data-id=\"927888f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298976\" alt=\"specifics-chien-crd-1-weight-reduction-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e0845e elementor-widget elementor-widget-heading\" data-id=\"8e0845e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Specific CHIEN CRD-1 WEIGHT REDUCTION<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dd33e6 elementor-widget elementor-widget-text-editor\" data-id=\"2dd33e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CRD-1 Weight R\u00e9duction chien apportent une alimentation qui aident \u00e0 la perte de poids pour toutes races confondues.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fb4ec4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4fb4ec4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/specific-crd-1-weight-reduction\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c46418f\" data-id=\"c46418f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c7a694 elementor-widget elementor-widget-image\" data-id=\"2c7a694\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298977\" alt=\"Virbac VET HPM DOG WEIGHT L ET D\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b6255a elementor-widget elementor-widget-heading\" data-id=\"3b6255a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Virbac VET HPM DOG WEIGHT L ET D <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e312f3 elementor-widget elementor-widget-text-editor\" data-id=\"8e312f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;aliment Veterinary HMP &#8211; Weight Loss &amp; Diabetes Dog est un aliment di\u00e9t\u00e9tique pour chien r\u00e9duisant le surpoids lorsqu&#8217;il est sup\u00e9rieur \u00e0 30%.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-beec0a1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"beec0a1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/veterinary-hpm-dog-w1-weight-loss-diabetes\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8aeed77\" data-id=\"8aeed77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7c58d8 elementor-widget elementor-widget-image\" data-id=\"f7c58d8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299210\" alt=\"hills-canine-adult-medium-light-poulet-vetorino.jpg\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino.jpg 458w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9657e3d elementor-widget elementor-widget-heading\" data-id=\"9657e3d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hill's CANINE ADULT LIGHT MEDIUM<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1eb2c0f elementor-widget elementor-widget-text-editor\" data-id=\"1eb2c0f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Canine Adult Light Large\u00a0 au poulet est sp\u00e9cialement con\u00e7u pour aider les chiens de moyenne race \u00e0 maintenir un poids id\u00e9al.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a58f1e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7a58f1e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/canine-adult-light-medium-poulet-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ff9b53 product_coveto elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ff9b53\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b641330\" data-id=\"b641330\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a67614 elementor-widget elementor-widget-image\" data-id=\"8a67614\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298975\" alt=\"hill&#039;s-neutered-dog-adult-medium-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64b22eb elementor-widget elementor-widget-heading\" data-id=\"64b22eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hill's NEUTERED DOG ADULT MEDIUM <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-465e0d5 elementor-widget elementor-widget-text-editor\" data-id=\"465e0d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nutrition r\u00e9volutionnaire prouv\u00e9e pour aider les chiens \u00e0 maintenir un poids id\u00e9al et \u00e0 rester en pleine forme apr\u00e8s la st\u00e9rilisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce3a45d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ce3a45d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/vetessentials-neutered-dog-adult-medium-sac-de-10-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f23b64f\" data-id=\"f23b64f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a6e88e elementor-widget elementor-widget-image\" data-id=\"4a6e88e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298976\" alt=\"specifics-chien-crd-1-weight-reduction-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/specifics-chien-crd-1-weight-reduction-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2e0b6b elementor-widget elementor-widget-heading\" data-id=\"e2e0b6b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Specific CHIEN CRD-1 WEIGHT REDUCTION<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a385441 elementor-widget elementor-widget-text-editor\" data-id=\"a385441\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CRD-1 Weight R\u00e9duction chien apportent une alimentation qui aident \u00e0 la perte de poids pour toutes races confondues.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-608e1c4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"608e1c4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/specific-crd-1-weight-reduction-sac-de-12-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c99ba81\" data-id=\"c99ba81\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-408db1d elementor-widget elementor-widget-image\" data-id=\"408db1d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298977\" alt=\"Virbac VET HPM DOG WEIGHT L ET D\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w1-weight-loss-diabetes-dog-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e924bcc elementor-widget elementor-widget-heading\" data-id=\"e924bcc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Virbac VET HPM DOG WEIGHT L ET D <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d75c1a elementor-widget elementor-widget-text-editor\" data-id=\"7d75c1a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;aliment Veterinary HMP &#8211; Weight Loss &amp; Diabetes Dog est un aliment di\u00e9t\u00e9tique pour chien r\u00e9duisant le surpoids lorsqu&#8217;il est sup\u00e9rieur \u00e0 30%.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-063a212 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"063a212\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/veterinary-hpm-dog-w1-weight-loss-diabetes-sac-de-12-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8a07dde\" data-id=\"8a07dde\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35e4a97 elementor-widget elementor-widget-image\" data-id=\"35e4a97\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299210\" alt=\"hills-canine-adult-medium-light-poulet-vetorino.jpg\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-canine-adult-medium-light-poulet-vetorino.jpg 458w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87f3f67 elementor-widget elementor-widget-heading\" data-id=\"87f3f67\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hill's CANINE ADULT LIGHT MEDIUM<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b64e7c0 elementor-widget elementor-widget-text-editor\" data-id=\"b64e7c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Canine Adult Light Large\u00a0 au poulet est sp\u00e9cialement con\u00e7u pour aider les chiens de moyenne race \u00e0 maintenir un poids id\u00e9al.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53b818c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"53b818c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pontlabbe-29120\/boutique\/product\/canine-adult-light-medium-poulet-sac-de-14-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54653227 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54653227\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27b6648f\" data-id=\"27b6648f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74908d0a elementor-widget elementor-widget-text-editor\" data-id=\"74908d0a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"color: #078ed2;text-align: center\"><a href=\"https:\/\/www.vetorino.com\/boutique\/page\/1\/?categorie=chien&amp;s=weight&amp;post_type=product\">D\u00e9couvrez notre s\u00e9lection de produits pour lutter contre l&#8217;ob\u00e9sit\u00e9 de votre chien<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>L&#8217;ob\u00e9sit\u00e9 des chiens L\u2019ob\u00e9sit\u00e9 est un v\u00e9ritable fl\u00e9au chez les hommes comme chez les animaux\u2026 ! C\u2019est une maladie grave qui touche pr\u00e8s de 40% des animaux de compagnie \u00e0 l\u2019\u00e9chelle europ\u00e9enne. Pour les chiens qui sont touch\u00e9s, c\u2019est une pathologie qui alt\u00e8re plusieurs de leurs organes et qui a des cons\u00e9quences importantes sur leur [&hellip;]<\/p>\n","protected":false},"author":10426,"featured_media":295649,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14088,14087,14094],"tags":[],"class_list":["post-295644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentation-chien","category-chien","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mon chien est trop gros - Ob\u00e9sit\u00e9 du chien - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Cliquez ici pour d\u00e9couvrir que faire lorsque votre chien est trop gros, comment pr\u00e9venir, traiter l&#039;ob\u00e9sit\u00e9 du chien. Tout compte en surpoids\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mon chien est trop gros - Ob\u00e9sit\u00e9 du chien - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Cliquez ici pour d\u00e9couvrir que faire lorsque votre chien est trop gros, comment pr\u00e9venir, traiter l&#039;ob\u00e9sit\u00e9 du chien. Tout compte en surpoids\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-05T15:52:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:21:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe V\u00e9torino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe V\u00e9torino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/\"},\"author\":{\"name\":\"Equipe V\u00e9torino\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/6c2a6631b1dafb889300d67266761861\"},\"headline\":\"Mon chien est trop gros &#8211; Ob\u00e9sit\u00e9 du chien\",\"datePublished\":\"2022-03-05T15:52:29+00:00\",\"dateModified\":\"2024-08-08T15:21:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/\"},\"wordCount\":1163,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pikwizard-dog-chihuahua-canine-scaled.jpg\",\"articleSection\":[\"Alimentation pour chien\",\"Chien\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/\",\"name\":\"Mon chien est trop gros - Ob\u00e9sit\u00e9 du chien - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pikwizard-dog-chihuahua-canine-scaled.jpg\",\"datePublished\":\"2022-03-05T15:52:29+00:00\",\"dateModified\":\"2024-08-08T15:21:57+00:00\",\"description\":\"Cliquez ici pour d\u00e9couvrir que faire lorsque votre chien est trop gros, comment pr\u00e9venir, traiter l'ob\u00e9sit\u00e9 du chien. Tout compte en surpoids\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pikwizard-dog-chihuahua-canine-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pikwizard-dog-chihuahua-canine-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Pr\u00e9venir l'ob\u00e9sit\u00e9 de son chien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/03\\\/05\\\/mon-chien-est-trop-gros-obesite-du-chien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mon chien est trop gros &#8211; Ob\u00e9sit\u00e9 du chien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/6c2a6631b1dafb889300d67266761861\",\"name\":\"Equipe V\u00e9torino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"caption\":\"Equipe V\u00e9torino\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/tocanesaintapre-24350\\\/boutique\\\/author\\\/equipe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mon chien est trop gros - Ob\u00e9sit\u00e9 du chien - V\u00e9torino","description":"Cliquez ici pour d\u00e9couvrir que faire lorsque votre chien est trop gros, comment pr\u00e9venir, traiter l'ob\u00e9sit\u00e9 du chien. Tout compte en surpoids","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Mon chien est trop gros - Ob\u00e9sit\u00e9 du chien - V\u00e9torino","og_description":"Cliquez ici pour d\u00e9couvrir que faire lorsque votre chien est trop gros, comment pr\u00e9venir, traiter l'ob\u00e9sit\u00e9 du chien. Tout compte en surpoids","og_url":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2022-03-05T15:52:29+00:00","article_modified_time":"2024-08-08T15:21:57+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-scaled.jpg","type":"image\/jpeg"}],"author":"Equipe V\u00e9torino","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Equipe V\u00e9torino","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/"},"author":{"name":"Equipe V\u00e9torino","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/6c2a6631b1dafb889300d67266761861"},"headline":"Mon chien est trop gros &#8211; Ob\u00e9sit\u00e9 du chien","datePublished":"2022-03-05T15:52:29+00:00","dateModified":"2024-08-08T15:21:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/"},"wordCount":1163,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-scaled.jpg","articleSection":["Alimentation pour chien","Chien","Sant\u00e9 pour chien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/","url":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/","name":"Mon chien est trop gros - Ob\u00e9sit\u00e9 du chien - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-scaled.jpg","datePublished":"2022-03-05T15:52:29+00:00","dateModified":"2024-08-08T15:21:57+00:00","description":"Cliquez ici pour d\u00e9couvrir que faire lorsque votre chien est trop gros, comment pr\u00e9venir, traiter l'ob\u00e9sit\u00e9 du chien. Tout compte en surpoids","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-scaled.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pikwizard-dog-chihuahua-canine-scaled.jpg","width":2560,"height":1707,"caption":"Pr\u00e9venir l'ob\u00e9sit\u00e9 de son chien"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/03\/05\/mon-chien-est-trop-gros-obesite-du-chien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chien","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chien\/"},{"@type":"ListItem","position":3,"name":"Mon chien est trop gros &#8211; Ob\u00e9sit\u00e9 du chien"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/6c2a6631b1dafb889300d67266761861","name":"Equipe V\u00e9torino","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","caption":"Equipe V\u00e9torino"},"url":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/author\/equipe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/posts\/295644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/users\/10426"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/comments?post=295644"}],"version-history":[{"count":45,"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/posts\/295644\/revisions"}],"predecessor-version":[{"id":303413,"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/posts\/295644\/revisions\/303413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/media\/295649"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/media?parent=295644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/categories?post=295644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/tags?post=295644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}