{"id":187130,"date":"2021-05-31T20:32:06","date_gmt":"2021-05-31T18:32:06","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/boviferm-plus-poudre-orale\/"},"modified":"2025-07-24T16:57:50","modified_gmt":"2025-07-24T14:57:50","slug":"boviferm-plus-poudre-orale","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/product\/boviferm-plus-poudre-orale\/","title":{"rendered":"Boviferm Plus Poudre"},"content":{"rendered":"<div id=\"description-short-section\" class=\"lg:mb-8\">\n<div class=\"product-section-content hidden lg:block\"><strong>R\u00e9gulateur digestif biologique pour veaux,<\/strong> permet la stabilisation du bilan \u00e9lectrolytes et de l&#8217;eau, a<strong>u moment du sevrage ou en phases critiques de croissance.<\/strong><\/div>\n<\/div>\n<p><\/p>\n<div id=\"description-section\" class=\"lg:mb-8\"><\/div>\n<div>Boviferm Plus <strong>regorge d&#8217;ingr\u00e9dients b\u00e9n\u00e9fiques<\/strong> : \u00e9lectrolytes, dextrose, tampons (citrate), bact\u00e9ries productrices d&#8217;acide lactique (oraline), mucus et pectines v\u00e9g\u00e9tales, et substances d&#8217;absorption min\u00e9rales et v\u00e9g\u00e9tales.<\/div>\n<div><\/div>\n<p><\/p>\n<div><strong>Recommandations :\u00a0<\/strong><\/div>\n<div><em>M\u00e9langer 1 sachet de 115 g deux fois par jour dans 2 litres d&#8217;eau et 0,5 \u00e0 4 litres de lait ou d&#8217;aliment d&#8217;allaitement.<\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<div id=\"description-short-section\" class=\"lg:mb-8\">\n<div class=\"product-section-content hidden lg:block\"><strong>R\u00e9gulateur digestif biologique pour veaux,<\/strong> permet la stabilisation du bilan \u00e9lectrolytes et de l&#8217;eau, a<strong>u moment du sevrage ou en phases critiques de croissance.<\/strong><\/div>\n<\/div>\n<p><\/p>\n<div id=\"description-section\" class=\"lg:mb-8\"><\/div>\n<div>Boviferm Plus <strong>regorge d&#8217;ingr\u00e9dients b\u00e9n\u00e9fiques<\/strong> : <em>\u00e9lectrolytes, dextrose, tampons (citrate), bact\u00e9ries productrices d&#8217;acide lactique (oraline), mucus et pectines v\u00e9g\u00e9tales, et substances d&#8217;absorption min\u00e9rales et v\u00e9g\u00e9tales.<\/em><\/div>\n","protected":false},"featured_media":1426475,"template":"","meta":[],"product_cat":[6864,6870],"product_tag":[],"class_list":{"0":"post-187130","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-animaux-delevage","7":"product_cat-bovins","8":"pa_marque-biove","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boviferm Plus Poudre Biove - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"R\u00e9gulateur digestif biologique pour veaux, permet la stabilisation du bilan \u00e9lectrolytes et de l&#039;eau, au moment du sevrage ou en phases critiques de croissance.    Boviferm Plus regorge d&#039;ingr\u00e9dients b\u00e9n\u00e9fiques : \u00e9lectrolytes, dextrose, tampons (citrate), bact\u00e9ries productrices d&#039;acide lactique (oraline), mucus et pectines v\u00e9g\u00e9tales, et substances d&#039;absorption min\u00e9rales et v\u00e9g\u00e9tales.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boviferm Plus Poudre Biove - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"R\u00e9gulateur digestif biologique pour veaux, permet la stabilisation du bilan \u00e9lectrolytes et de l&#039;eau, au moment du sevrage ou en phases critiques de croissance.    Boviferm Plus regorge d&#039;ingr\u00e9dients b\u00e9n\u00e9fiques : \u00e9lectrolytes, dextrose, tampons (citrate), bact\u00e9ries productrices d&#039;acide lactique (oraline), mucus et pectines v\u00e9g\u00e9tales, et substances d&#039;absorption min\u00e9rales et v\u00e9g\u00e9tales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/product\/boviferm-plus-poudre-orale\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T14:57:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/boviferm-plus-veaux-poudre.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/boviferm-plus-poudre-orale\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/boviferm-plus-poudre-orale\\\/\",\"name\":\"Boviferm Plus Poudre Biove - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/boviferm-plus-poudre-orale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/boviferm-plus-poudre-orale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/boviferm-plus-veaux-poudre.webp\",\"datePublished\":\"2021-05-31T18:32:06+00:00\",\"dateModified\":\"2025-07-24T14:57:50+00:00\",\"description\":\"R\u00e9gulateur digestif biologique pour veaux, permet la stabilisation du bilan \u00e9lectrolytes et de l'eau, au moment du sevrage ou en phases critiques de croissance. Boviferm Plus regorge d'ingr\u00e9dients b\u00e9n\u00e9fiques : \u00e9lectrolytes, dextrose, tampons (citrate), bact\u00e9ries productrices d'acide lactique (oraline), mucus et pectines v\u00e9g\u00e9tales, et substances d'absorption min\u00e9rales et v\u00e9g\u00e9tales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/boviferm-plus-poudre-orale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/boviferm-plus-poudre-orale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/boviferm-plus-poudre-orale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/boviferm-plus-veaux-poudre.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/boviferm-plus-veaux-poudre.webp\",\"width\":425,\"height\":425},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/boviferm-plus-poudre-orale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Boviferm Plus Poudre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Biove\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boviferm Plus Poudre Biove - V\u00e9torino","description":"R\u00e9gulateur digestif biologique pour veaux, permet la stabilisation du bilan \u00e9lectrolytes et de l'eau, au moment du sevrage ou en phases critiques de croissance.    Boviferm Plus regorge d'ingr\u00e9dients b\u00e9n\u00e9fiques : \u00e9lectrolytes, dextrose, tampons (citrate), bact\u00e9ries productrices d'acide lactique (oraline), mucus et pectines v\u00e9g\u00e9tales, et substances d'absorption min\u00e9rales et v\u00e9g\u00e9tales.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Boviferm Plus Poudre Biove - V\u00e9torino","og_description":"R\u00e9gulateur digestif biologique pour veaux, permet la stabilisation du bilan \u00e9lectrolytes et de l'eau, au moment du sevrage ou en phases critiques de croissance.    Boviferm Plus regorge d'ingr\u00e9dients b\u00e9n\u00e9fiques : \u00e9lectrolytes, dextrose, tampons (citrate), bact\u00e9ries productrices d'acide lactique (oraline), mucus et pectines v\u00e9g\u00e9tales, et substances d'absorption min\u00e9rales et v\u00e9g\u00e9tales.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/product\/boviferm-plus-poudre-orale\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-07-24T14:57:50+00:00","og_image":[{"width":425,"height":425,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/boviferm-plus-veaux-poudre.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/boviferm-plus-poudre-orale\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/boviferm-plus-poudre-orale\/","name":"Boviferm Plus Poudre Biove - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/boviferm-plus-poudre-orale\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/boviferm-plus-poudre-orale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/boviferm-plus-veaux-poudre.webp","datePublished":"2021-05-31T18:32:06+00:00","dateModified":"2025-07-24T14:57:50+00:00","description":"R\u00e9gulateur digestif biologique pour veaux, permet la stabilisation du bilan \u00e9lectrolytes et de l'eau, au moment du sevrage ou en phases critiques de croissance. Boviferm Plus regorge d'ingr\u00e9dients b\u00e9n\u00e9fiques : \u00e9lectrolytes, dextrose, tampons (citrate), bact\u00e9ries productrices d'acide lactique (oraline), mucus et pectines v\u00e9g\u00e9tales, et substances d'absorption min\u00e9rales et v\u00e9g\u00e9tales.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/boviferm-plus-poudre-orale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/boviferm-plus-poudre-orale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/boviferm-plus-poudre-orale\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/boviferm-plus-veaux-poudre.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/boviferm-plus-veaux-poudre.webp","width":425,"height":425},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/boviferm-plus-poudre-orale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Boviferm Plus Poudre"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Biove","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/product\/187130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/media\/1426475"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/media?parent=187130"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/product_cat?post=187130"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/tocanesaintapre-24350\/boutique\/wp-json\/wp\/v2\/product_tag?post=187130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}