{"id":1338454,"date":"2025-05-21T12:00:00","date_gmt":"2025-05-21T10:00:00","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=1338454"},"modified":"2025-08-05T15:13:30","modified_gmt":"2025-08-05T13:13:30","slug":"deuil-animal","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/2025\/05\/21\/deuil-animal\/","title":{"rendered":"Deuil animalier : nos conseils pour vivre cette \u00e9tape difficile"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1338454\" class=\"elementor elementor-1338454\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4747b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4747b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-230af50\" data-id=\"230af50\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab4035a elementor-widget elementor-widget-post-info\" data-id=\"ab4035a\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-b8ca39c elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tPubli\u00e9 le\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-bbe24d6 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/2025\/05\/21\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-calendar\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>mai 21, 2025<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-6bff815 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-time\">\n\t\t\t\t\t\t\t\t\t\t<time>12:00<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2521aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2521aa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-745624e\" data-id=\"745624e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a95edd elementor-widget elementor-widget-text-editor\" data-id=\"3a95edd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section data-id=\"8j8qvkr\" data-element_type=\"section\"><div data-id=\"tcv8rwn\" data-element_type=\"heading.default\">Deuil animalier : nos conseils pour vivre cette \u00e9tape difficile<br \/><!-- notionvc: 3b4d4ca9-e767-4365-9375-bf8f4630222f --><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b51a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86b51a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca49f12\" data-id=\"ca49f12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d92d7f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d92d7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Perdre un animal de compagnie, c\u2019est vivre un chagrin tr\u00e8s profond : un membre de la famille s\u2019en va et laisse un vide immense. Nous souhaitons vous apporter quelques rep\u00e8res et conseils pour vous accompagner dans cette p\u00e9riode difficile.<br \/><!-- notionvc: cf924426-d00a-40d4-a0b4-4f5d0cafb449 --><\/p><p><!-- notionvc: f3365c80-e02e-467b-b5ae-31b62867bbca --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37f3744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37f3744\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5abeb12\" data-id=\"5abeb12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48e3ba0 elementor-widget elementor-widget-heading\" data-id=\"48e3ba0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comprendre et accepter votre peine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-448f199 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"448f199\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La tristesse est normale. Reconna\u00eetre votre douleur est la premi\u00e8re \u00e9tape. Les \u00e9motions (tristesse, col\u00e8re, culpabilit\u00e9\u2026) font partie du processus de gu\u00e9rison.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b291e elementor-widget elementor-widget-heading\" data-id=\"c5b291e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Exprimer votre tristesse<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5245d3d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5245d3d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Trouvez des personnes qui vous \u00e9coutent<\/strong> sans vous juger pour exprimer votre peine. Cela soulage. En parall\u00e8le, tenez un journal ou un carnet de souvenirs. \u00c9crire ce que vous ressentez, coller des photos, noter vos moments pr\u00e9f\u00e9r\u00e9s peut vous aider \u00e0 mettre des mots sur votre chagrin, \u00e0 cheminer. Vous pouvez aussi organiser une c\u00e9r\u00e9monie ou cr\u00e9er un hommage (bougie, plantation d&#8217;un arbre, cadre souvenir, &#8230;) en l&#8217;honneur de votre animal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aee3fc elementor-widget elementor-widget-heading\" data-id=\"7aee3fc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prenez soin de vous<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c131e18 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c131e18\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Accordez-vous des pauses<\/strong>. Une promenade au grand air, du sport, un bain chaud ou une activit\u00e9 douce comme la lecture peuvent apaiser l\u2019esprit. Bien manger, dormir suffisamment et rester hydrat\u00e9 soutiennent aussi votre moral. Donnez vous du temps.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e442a3b elementor-widget elementor-widget-image\" data-id=\"e442a3b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"864\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animalier-1536x864.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-1338464\" alt=\"deuil animalier\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animalier-1536x864.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animalier-300x169.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animalier-1024x576.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animalier-768x432.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animalier-2048x1152.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animalier-555x312.jpg 555w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-631c1c1 elementor-widget elementor-widget-heading\" data-id=\"631c1c1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trouver du soutien<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7046eb2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7046eb2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Des professionnels du deuil animalier peuvent vous aider<\/strong> \u00e0 cheminer au cours de cette \u00e9tape difficile. Vous pouvez aussi \u00e9changer avec d&#8217;autres propri\u00e9taires en deuil sur des groupes de parole en ligne. Cela fait parfois du bien de parler \u00e0 d&#8217;autres personnes endeuill\u00e9es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d9b184 elementor-widget elementor-widget-heading\" data-id=\"9d9b184\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Se souvenir et c\u00e9l\u00e9brer les moments partag\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50e8476 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"50e8476\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cr\u00e9er un album photo ou un montage vid\u00e9o. <strong>Repenser les instants heureux aide \u00e0 remplacer la douleur<\/strong> par la gratitude. Entourez-vous d\u2019objets symboliques si vous en ressentez le besoin. Un collier, un jouet ou une empreinte de patte encadr\u00e9e pour honorer sa m\u00e9moire et se rappeler des moments heureux. Faire un don \u00e0 un refuge ou parrainer un animal en son nom peut \u00e9galement transformer votre tristesse en acte positif.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Deuil animalier : nos conseils pour vivre cette \u00e9tape difficile Perdre un animal de compagnie, c\u2019est vivre un chagrin tr\u00e8s profond : un membre de la famille s\u2019en va et laisse un vide immense. Nous souhaitons vous apporter quelques rep\u00e8res et conseils pour vous accompagner dans cette p\u00e9riode difficile. Comprendre et accepter votre peine La [&hellip;]<\/p>\n","protected":false},"author":68707,"featured_media":1338463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14086,14087],"tags":[],"class_list":["post-1338454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chat","category-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deuil animal : nos conseils pour traverser ce moment difficile<\/title>\n<meta name=\"description\" content=\"Perdre un animal de compagnie est une \u00e9preuve douloureuse. D\u00e9couvrez nos conseils pour trouver du soutien et rendre hommage \u00e0 votre animal.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deuil animal : nos conseils pour traverser ce moment difficile\" \/>\n<meta property=\"og:description\" content=\"Perdre un animal de compagnie est une \u00e9preuve douloureuse. D\u00e9couvrez nos conseils pour trouver du soutien et rendre hommage \u00e0 votre animal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/2025\/05\/21\/deuil-animal\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-21T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T13:13:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Clemence Sully\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clemence Sully\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/\"},\"author\":{\"name\":\"Clemence Sully\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\"},\"headline\":\"Deuil animalier : nos conseils pour vivre cette \u00e9tape difficile\",\"datePublished\":\"2025-05-21T10:00:00+00:00\",\"dateModified\":\"2025-08-05T13:13:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/\"},\"wordCount\":346,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/deuil-animal.jpg\",\"articleSection\":[\"Chat\",\"Chien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/\",\"name\":\"Deuil animal : nos conseils pour traverser ce moment difficile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/deuil-animal.jpg\",\"datePublished\":\"2025-05-21T10:00:00+00:00\",\"dateModified\":\"2025-08-05T13:13:30+00:00\",\"description\":\"Perdre un animal de compagnie est une \u00e9preuve douloureuse. D\u00e9couvrez nos conseils pour trouver du soutien et rendre hommage \u00e0 votre animal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/deuil-animal.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/deuil-animal.jpg\",\"width\":1905,\"height\":450,\"caption\":\"deuil animal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/05\\\/21\\\/deuil-animal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Deuil animalier : nos conseils pour vivre cette \u00e9tape difficile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\",\"name\":\"Clemence Sully\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"caption\":\"Clemence Sully\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/toulonsurarroux-71320\\\/boutique\\\/author\\\/clemence-sully\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deuil animal : nos conseils pour traverser ce moment difficile","description":"Perdre un animal de compagnie est une \u00e9preuve douloureuse. D\u00e9couvrez nos conseils pour trouver du soutien et rendre hommage \u00e0 votre animal.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Deuil animal : nos conseils pour traverser ce moment difficile","og_description":"Perdre un animal de compagnie est une \u00e9preuve douloureuse. D\u00e9couvrez nos conseils pour trouver du soutien et rendre hommage \u00e0 votre animal.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/2025\/05\/21\/deuil-animal\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2025-05-21T10:00:00+00:00","article_modified_time":"2025-08-05T13:13:30+00:00","og_image":[{"width":1905,"height":450,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animal.jpg","type":"image\/jpeg"}],"author":"Clemence Sully","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Clemence Sully","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/"},"author":{"name":"Clemence Sully","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a"},"headline":"Deuil animalier : nos conseils pour vivre cette \u00e9tape difficile","datePublished":"2025-05-21T10:00:00+00:00","dateModified":"2025-08-05T13:13:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/"},"wordCount":346,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animal.jpg","articleSection":["Chat","Chien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/","url":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/","name":"Deuil animal : nos conseils pour traverser ce moment difficile","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animal.jpg","datePublished":"2025-05-21T10:00:00+00:00","dateModified":"2025-08-05T13:13:30+00:00","description":"Perdre un animal de compagnie est une \u00e9preuve douloureuse. D\u00e9couvrez nos conseils pour trouver du soutien et rendre hommage \u00e0 votre animal.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animal.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/deuil-animal.jpg","width":1905,"height":450,"caption":"deuil animal"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/05\/21\/deuil-animal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chien","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chien\/"},{"@type":"ListItem","position":3,"name":"Deuil animalier : nos conseils pour vivre cette \u00e9tape difficile"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a","name":"Clemence Sully","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","caption":"Clemence Sully"},"url":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/author\/clemence-sully\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/posts\/1338454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/users\/68707"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/comments?post=1338454"}],"version-history":[{"count":11,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/posts\/1338454\/revisions"}],"predecessor-version":[{"id":1441260,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/posts\/1338454\/revisions\/1441260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/media\/1338463"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/media?parent=1338454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/categories?post=1338454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/tags?post=1338454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}