{"id":102346,"date":"2020-06-30T14:30:35","date_gmt":"2020-06-30T12:30:35","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/"},"modified":"2026-05-12T02:42:11","modified_gmt":"2026-05-12T00:42:11","slug":"specific-cpd-m-puppy-medium-breed","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/","title":{"rendered":"CPD-M Puppy Medium &#8211; chien"},"content":{"rendered":"<p><strong>Aliment complet et \u00e9quilibr\u00e9 pour le chiot de race moyenne (poids adulte de 10 \u00e0\u00a025 kg) et la chienne gestante et en lactation de moyenne et grande race.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Croissance du chiot de race moyenne (poids adulte de 10 \u00e0\u00a025 kg)<\/li>\n<li>Aliment id\u00e9al entre le sevrage (5 \u00e0 6 semaines) et le moment o\u00f9 le chiot atteint 80 % de son\u00a0poids adulte.<\/li>\n<li>Gestation, lactation dans toutes les races<\/li>\n<li>Anorexie<\/li>\n<li>Convalescence<\/li>\n<\/ul>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li>Les teneurs accrues en \u00e9nergie, prot\u00e9ines, vitamines et min\u00e9raux <strong>couvrent les besoins des chiots de races moyennes en croissance et soutiennent leur d\u00e9veloppement osseux et musculaire.<\/strong><\/li>\n<li>Le DHA est un acide gras Om\u00e9ga-3 qui<strong> favorise le d\u00e9veloppement c\u00e9r\u00e9bral et visuel.<\/strong><\/li>\n<li>Les acides gras Om\u00e9ga-3 EPA et DHA (issus d\u2019huile de poisson) ont un <strong>effet b\u00e9n\u00e9fique sur la sant\u00e9 des articulations, de la peau et du pelage<\/strong>.<\/li>\n<li>Contient des \u00df-1,3\/1,6-glucanes issus de levure boulang\u00e8re, qui peuvent se lier aux r\u00e9cepteurs des macrophages et ainsi <strong>stimuler le syst\u00e8me immunitaire et favoriser la r\u00e9ponse immunitaire<\/strong>.<\/li>\n<li>Le psyllium est une fibre soluble mucilagineuse qui a la capacit\u00e9 d\u2019absorber plusieurs fois son poids en eau. Il est connu pour son <strong>effet b\u00e9n\u00e9fique sur la r\u00e9gulation du transit intestinal<\/strong>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<div><strong>Aliment complet et \u00e9quilibr\u00e9 pour le chiot de race moyenne (poids adulte de 10 \u00e0 25 kg) et la chienne gestante et en lactation de moyenne et grande race.<\/strong><\/p>\n<\/div>\n<p>\n<strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Croissance du chiot de race moyenne (poids adulte de 10 \u00e0\u00a025 kg)<\/li>\n<li>Aliment id\u00e9al entre le sevrage (5 \u00e0 6 semaines) et le moment o\u00f9 les chiots atteignent 80 % de leur poids adulte.<\/li>\n<li>Gestation, lactation dans toutes les races<\/li>\n<li>Anorexie<\/li>\n<li>Convalescence<\/li>\n<\/ul>\n","protected":false},"featured_media":694623,"template":"","meta":[],"product_cat":[12552,12584,2698],"product_tag":[],"class_list":{"0":"post-102346","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chien","7":"product_cat-alimentation-premium-pour-chien","8":"product_cat-chien","9":"pa_marque-specific","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CPD-M Puppy Medium - chien Specific - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Aliment complet et \u00e9quilibr\u00e9 pour le chiot de race moyenne (poids adulte de 10 \u00e0 25 kg) et la chienne gestante et en lactation de moyenne et grande race.    Utilisation :   Croissance du chiot de race moyenne (poids adulte de 10 \u00e0\u00a025 kg)  Aliment id\u00e9al entre le sevrage (5 \u00e0 6 semaines) et le moment o\u00f9 les chiots atteignent 80 % de leur poids adulte.  Gestation, lactation dans toutes les races  Anorexie  Convalescence\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CPD-M Puppy Medium - chien Specific - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Aliment complet et \u00e9quilibr\u00e9 pour le chiot de race moyenne (poids adulte de 10 \u00e0 25 kg) et la chienne gestante et en lactation de moyenne et grande race.    Utilisation :   Croissance du chiot de race moyenne (poids adulte de 10 \u00e0\u00a025 kg)  Aliment id\u00e9al entre le sevrage (5 \u00e0 6 semaines) et le moment o\u00f9 les chiots atteignent 80 % de leur poids adulte.  Gestation, lactation dans toutes les races  Anorexie  Convalescence\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T00:42:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-cpd-m-puppy-medium.jpg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"458\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cpd-m-puppy-medium-breed\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cpd-m-puppy-medium-breed\\\/\",\"name\":\"CPD-M Puppy Medium - chien Specific - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cpd-m-puppy-medium-breed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cpd-m-puppy-medium-breed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-cpd-m-puppy-medium.jpg.png\",\"datePublished\":\"2020-06-30T12:30:35+00:00\",\"dateModified\":\"2026-05-12T00:42:11+00:00\",\"description\":\"Aliment complet et \u00e9quilibr\u00e9 pour le chiot de race moyenne (poids adulte de 10 \u00e0 25 kg) et la chienne gestante et en lactation de moyenne et grande race. Utilisation : Croissance du chiot de race moyenne (poids adulte de 10 \u00e0\u00a025 kg) Aliment id\u00e9al entre le sevrage (5 \u00e0 6 semaines) et le moment o\u00f9 les chiots atteignent 80 % de leur poids adulte. Gestation, lactation dans toutes les races Anorexie Convalescence\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cpd-m-puppy-medium-breed\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cpd-m-puppy-medium-breed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cpd-m-puppy-medium-breed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-cpd-m-puppy-medium.jpg.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-cpd-m-puppy-medium.jpg.png\",\"width\":458,\"height\":458},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cpd-m-puppy-medium-breed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CPD-M Puppy Medium &#8211; chien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Specific\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CPD-M Puppy Medium - chien Specific - V\u00e9torino","description":"Aliment complet et \u00e9quilibr\u00e9 pour le chiot de race moyenne (poids adulte de 10 \u00e0 25 kg) et la chienne gestante et en lactation de moyenne et grande race.    Utilisation :   Croissance du chiot de race moyenne (poids adulte de 10 \u00e0\u00a025 kg)  Aliment id\u00e9al entre le sevrage (5 \u00e0 6 semaines) et le moment o\u00f9 les chiots atteignent 80 % de leur poids adulte.  Gestation, lactation dans toutes les races  Anorexie  Convalescence","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"CPD-M Puppy Medium - chien Specific - V\u00e9torino","og_description":"Aliment complet et \u00e9quilibr\u00e9 pour le chiot de race moyenne (poids adulte de 10 \u00e0 25 kg) et la chienne gestante et en lactation de moyenne et grande race.    Utilisation :   Croissance du chiot de race moyenne (poids adulte de 10 \u00e0\u00a025 kg)  Aliment id\u00e9al entre le sevrage (5 \u00e0 6 semaines) et le moment o\u00f9 les chiots atteignent 80 % de leur poids adulte.  Gestation, lactation dans toutes les races  Anorexie  Convalescence","og_url":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-05-12T00:42:11+00:00","og_image":[{"width":458,"height":458,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-cpd-m-puppy-medium.jpg.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/","name":"CPD-M Puppy Medium - chien Specific - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-cpd-m-puppy-medium.jpg.png","datePublished":"2020-06-30T12:30:35+00:00","dateModified":"2026-05-12T00:42:11+00:00","description":"Aliment complet et \u00e9quilibr\u00e9 pour le chiot de race moyenne (poids adulte de 10 \u00e0 25 kg) et la chienne gestante et en lactation de moyenne et grande race. Utilisation : Croissance du chiot de race moyenne (poids adulte de 10 \u00e0\u00a025 kg) Aliment id\u00e9al entre le sevrage (5 \u00e0 6 semaines) et le moment o\u00f9 les chiots atteignent 80 % de leur poids adulte. Gestation, lactation dans toutes les races Anorexie Convalescence","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-cpd-m-puppy-medium.jpg.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-cpd-m-puppy-medium.jpg.png","width":458,"height":458},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cpd-m-puppy-medium-breed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"CPD-M Puppy Medium &#8211; chien"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Specific","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/product\/102346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/media\/694623"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/media?parent=102346"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/product_cat?post=102346"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/product_tag?post=102346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}