{"id":743977,"date":"2023-11-15T16:44:01","date_gmt":"2023-11-15T15:44:01","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/bo-yeas-act-ultra-3\/"},"modified":"2026-04-10T02:42:11","modified_gmt":"2026-04-10T00:42:11","slug":"bo-yeas-act-ultra-3","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/product\/bo-yeas-act-ultra-3\/","title":{"rendered":"Bo Yeas Act Ultra"},"content":{"rendered":"<p><b>L\u2019importance de l\u2019\u00e9quilibre de la flore bact\u00e9rienne dans la digestion et l\u2019utilisation de pr\u00e9- et probiotiques s\u2019est largement r\u00e9pandue chez le cheval.<\/b><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Aide \u00e0 stabiliser la digestion physiologique chez les chevaux.<\/li>\n<li>Peut \u00e9galement \u00eatre utilis\u00e9 en cas de risque de troubles digestifs, pendant et apr\u00e8s ceux-ci.<\/li>\n<\/ul>\n<p><strong>Mode d&#8217;emploi :<\/strong><\/p>\n<p>Aliment compl\u00e9mentaire di\u00e9t\u00e9tique pour chevaux<\/p>\n<p>1 mesure = 10 g<\/p>\n<ul>\n<li>Poulain : 1\/2 mesure\/jour.<\/li>\n<li>Yearling : 1 mesure\/jour.<\/li>\n<li>Adulte :\u00a0 2 mesures\/jour.<\/li>\n<\/ul>\n<p>P\u00e9riode d&#8217;effort intensif (adultes) : 4 mesures\/jour.<\/p>\n<p>Dur\u00e9e d&#8217;utilisation : 3 \u00e0 4 semaines, m\u00e9lang\u00e9 \u00e0 la ration<\/p>\n<p><strong>Avantages :<\/strong><\/p>\n<ul>\n<li>Les utilisateurs appr\u00e9cient la facilit\u00e9 d\u2019utilisation de Bo Yeas Act Ultra. En un geste, ils optimisent la ration alimentaire de leurs chevaux.<\/li>\n<li>La formulation de Bo Yeas Act Ultra int\u00e8gre un ingr\u00e9dient innovant : le Mycosorb A+\u00ae.<\/li>\n<li>La formulation unique contient \u00e9galement du Actisaf, levure probiotique qui aide \u00e0 mieux valoriser la ration alimentaire, ainsi que des pr\u00e9biotiques (FOS, ou fructooligosaccharides) qui viennent renforcer l\u2019int\u00e9r\u00eat de la levure.<\/li>\n<li>Sans ingr\u00e9dient d&#8217;origine animale.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><b>L\u2019importance de l\u2019\u00e9quilibre de la flore bact\u00e9rienne dans la digestion et l\u2019utilisation de pr\u00e9- et probiotiques s\u2019est largement r\u00e9pandue chez le cheval.<\/b><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Aide \u00e0 stabiliser la digestion physiologique chez les chevaux.<\/li>\n<li>Peut \u00e9galement \u00eatre utilis\u00e9 en cas de risque de troubles digestifs, pendant et apr\u00e8s ceux-ci.<\/li>\n<\/ul>\n","protected":false},"featured_media":1219682,"template":"","meta":[],"product_cat":[12556,12547,14072],"product_tag":[],"class_list":{"0":"post-743977","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-digestion-du-cheval","7":"product_cat-cheval","8":"product_cat-dietetique-et-complements-alimentaires-du-cheval","9":"pa_marque-audevard","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bo Yeas Act Ultra Audevard - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"L\u2019importance de l\u2019\u00e9quilibre de la flore bact\u00e9rienne dans la digestion et l\u2019utilisation de pr\u00e9- et probiotiques s\u2019est largement r\u00e9pandue chez le cheval.  Utilisation :   Aide \u00e0 stabiliser la digestion physiologique chez les chevaux.  Peut \u00e9galement \u00eatre utilis\u00e9 en cas de risque de troubles digestifs, pendant et apr\u00e8s ceux-ci.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bo Yeas Act Ultra Audevard - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"L\u2019importance de l\u2019\u00e9quilibre de la flore bact\u00e9rienne dans la digestion et l\u2019utilisation de pr\u00e9- et probiotiques s\u2019est largement r\u00e9pandue chez le cheval.  Utilisation :   Aide \u00e0 stabiliser la digestion physiologique chez les chevaux.  Peut \u00e9galement \u00eatre utilis\u00e9 en cas de risque de troubles digestifs, pendant et apr\u00e8s ceux-ci.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/product\/bo-yeas-act-ultra-3\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T00:42:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/bo-yeas-act-ultra.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/bo-yeas-act-ultra-3\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/bo-yeas-act-ultra-3\\\/\",\"name\":\"Bo Yeas Act Ultra Audevard - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/bo-yeas-act-ultra-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/bo-yeas-act-ultra-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/bo-yeas-act-ultra.webp\",\"datePublished\":\"2023-11-15T15:44:01+00:00\",\"dateModified\":\"2026-04-10T00:42:11+00:00\",\"description\":\"L\u2019importance de l\u2019\u00e9quilibre de la flore bact\u00e9rienne dans la digestion et l\u2019utilisation de pr\u00e9- et probiotiques s\u2019est largement r\u00e9pandue chez le cheval. Utilisation : Aide \u00e0 stabiliser la digestion physiologique chez les chevaux. Peut \u00e9galement \u00eatre utilis\u00e9 en cas de risque de troubles digestifs, pendant et apr\u00e8s ceux-ci.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/bo-yeas-act-ultra-3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/bo-yeas-act-ultra-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/bo-yeas-act-ultra-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/bo-yeas-act-ultra.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/bo-yeas-act-ultra.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/bo-yeas-act-ultra-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bo Yeas Act Ultra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Audevard\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bo Yeas Act Ultra Audevard - V\u00e9torino","description":"L\u2019importance de l\u2019\u00e9quilibre de la flore bact\u00e9rienne dans la digestion et l\u2019utilisation de pr\u00e9- et probiotiques s\u2019est largement r\u00e9pandue chez le cheval.  Utilisation :   Aide \u00e0 stabiliser la digestion physiologique chez les chevaux.  Peut \u00e9galement \u00eatre utilis\u00e9 en cas de risque de troubles digestifs, pendant et apr\u00e8s ceux-ci.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Bo Yeas Act Ultra Audevard - V\u00e9torino","og_description":"L\u2019importance de l\u2019\u00e9quilibre de la flore bact\u00e9rienne dans la digestion et l\u2019utilisation de pr\u00e9- et probiotiques s\u2019est largement r\u00e9pandue chez le cheval.  Utilisation :   Aide \u00e0 stabiliser la digestion physiologique chez les chevaux.  Peut \u00e9galement \u00eatre utilis\u00e9 en cas de risque de troubles digestifs, pendant et apr\u00e8s ceux-ci.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/product\/bo-yeas-act-ultra-3\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-04-10T00:42:11+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/bo-yeas-act-ultra.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/bo-yeas-act-ultra-3\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/bo-yeas-act-ultra-3\/","name":"Bo Yeas Act Ultra Audevard - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/bo-yeas-act-ultra-3\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/bo-yeas-act-ultra-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/bo-yeas-act-ultra.webp","datePublished":"2023-11-15T15:44:01+00:00","dateModified":"2026-04-10T00:42:11+00:00","description":"L\u2019importance de l\u2019\u00e9quilibre de la flore bact\u00e9rienne dans la digestion et l\u2019utilisation de pr\u00e9- et probiotiques s\u2019est largement r\u00e9pandue chez le cheval. Utilisation : Aide \u00e0 stabiliser la digestion physiologique chez les chevaux. Peut \u00e9galement \u00eatre utilis\u00e9 en cas de risque de troubles digestifs, pendant et apr\u00e8s ceux-ci.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/bo-yeas-act-ultra-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/bo-yeas-act-ultra-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/bo-yeas-act-ultra-3\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/bo-yeas-act-ultra.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/bo-yeas-act-ultra.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/bo-yeas-act-ultra-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Bo Yeas Act Ultra"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Audevard","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/product\/743977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/media\/1219682"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/media?parent=743977"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/product_cat?post=743977"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulonsurarroux-71320\/boutique\/wp-json\/wp\/v2\/product_tag?post=743977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}