{"id":297194,"date":"2022-02-24T15:02:58","date_gmt":"2022-02-24T14:02:58","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=297194"},"modified":"2024-08-08T17:22:07","modified_gmt":"2024-08-08T15:22:07","slug":"les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/","title":{"rendered":"Les parasites chez le chien et le chat, les dangers des tiques et des puces"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"297194\" class=\"elementor elementor-297194\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e43940f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e43940f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24e2cf81\" data-id=\"24e2cf81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6052994c elementor-widget elementor-widget-text-editor\" data-id=\"6052994c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><h2 class=\"wp-block-heading\">Parasites du chien et du chat : attention \u00e0 ces nuisibles quasi invisibles !<\/h2><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Les <strong>parasites pour le chien et le chat<\/strong> sont nombreux. Nous vous recommandons vivement de faire attention \u00e0 ces <strong>nuisibles<\/strong> quasi-invisibles\u2026\u00a0! En effet, seul 5% des nuisibles comme les <strong>puces<\/strong> sont visibles \u00e0 l\u2019\u0153il nu sur <strong>votre animal de compagnie\u00a0<\/strong>! Les 95% restants sont des <strong>puces<\/strong>, des <strong>\u0153ufs<\/strong>, des <strong>larves cach\u00e9es<\/strong> dans l\u2019environnement et dans la <strong>peau de votre animal<\/strong>. Puces, tiques, vers, moustiques, phl\u00e9botomes, sont autant de <strong>nuisibles dangereux<\/strong> pour votre chien ou votre chat.<\/p><p><\/p><p><\/p><h2 class=\"has-text-align-left wp-block-heading\">Les puces sont des parasites coriaces pour votre animal<\/h2><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Les <strong>puces<\/strong> peuvent se cacher dans votre jardin, au chenil, au parc\u2026 De plus, les puces vivent sur le corps m\u00eame d\u2019animaux sauvages, de <strong>rongeurs<\/strong>, de <strong>chats errants<\/strong>\u2026 Ces nuisibles d\u00e9posent des \u0153ufs partout. Ces <strong>\u0153ufs<\/strong> se d\u00e9veloppent ensuite en puce qui peuvent <strong>contaminer votre chien ou votre chat<\/strong>.<\/p><p>Les puces sont <strong>coriaces<\/strong>\u00a0! En effet, lorsqu\u2019une puce s\u2019installe sur un animal, c\u2019est pour la dur\u00e9e. Et contrairement aux id\u00e9es re\u00e7ues, ce n\u2019est pas par un contact direct avec un autre chien ou un autre chat que celles-ci s\u2019attrapent\u2026 Concr\u00e8tement, les puces viennent d\u2019elles-m\u00eames, \u00e0 partir d\u2019un <strong>environnement infest\u00e9<\/strong>. Fais donc bien attention \u00e0 celui-ci\u00a0!<\/p><p><\/p><p><\/p><h2 class=\"has-text-align-left wp-block-heading\">Les puces : ces nuisibles quasi invisibles<\/h2><p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-297203 alignleft\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920-300x201.jpg\" alt=\"Les puces : ces nuisibles quasi invisibles\" width=\"300\" height=\"201\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920-300x201.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920-1024x685.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920-768x514.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920-1536x1028.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920-750x500.jpg 750w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920-555x371.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920-64x43.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p><\/p><p><\/p><p class=\"wp-block-paragraph\"><strong>Les puces sont des nuisibles quasi invisibles<\/strong>, tr\u00e8s difficiles \u00e0 trouver lorsque votre c<strong>hien ou votre chat<\/strong> est dans un environnement o\u00f9 l\u2019infestation est encore peu avanc\u00e9e\u2026 Soyez donc attentifs \u00e0 la moindre petite <strong>boule noire<\/strong> qui pourrait correspondre \u00e0 une d\u00e9jection de puce sur le pelage de votre fid\u00e8le compagnon. Cela peut <strong>se propager<\/strong> ensuite tr\u00e8s vite\u00a0! Les puces femelles sont en mesure de pondre pr\u00e8s de 50 \u0153ufs par jour\u00a0! Lorsque vous constatez la pr\u00e9sence de puces, il s\u2019agir de <strong>traiter l\u2019environnement<\/strong>, votre <strong>habitat<\/strong> et votre <strong>animal<\/strong>. Une fois pondus, les \u0153ufs peuvent \u00e9clore et <strong>\u00e9tendre la pr\u00e9sence de nuisibles<\/strong> pendant encore <strong>plusieurs mois<\/strong>.<\/p><p><\/p><p><\/p><h2 class=\"wp-block-heading\">Les puces r\u00e9pandent des maladies pour votre chien et chat<\/h2><p><img decoding=\"async\" class=\"size-medium wp-image-297204 alignright\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-g3312e05f7_1920-300x200.jpg\" alt=\"Les puces r\u00e9pandent des maladies pour votre chien et chat\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-g3312e05f7_1920-300x200.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-g3312e05f7_1920-1024x683.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-g3312e05f7_1920-768x512.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-g3312e05f7_1920-1536x1024.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-g3312e05f7_1920-750x500.jpg 750w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-g3312e05f7_1920-555x370.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-g3312e05f7_1920-64x43.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dog-g3312e05f7_1920.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Les <strong>puces<\/strong> sont un r\u00e9el danger car elles peuvent r\u00e9pandre des maladies pour votre <strong>animal de compagnie<\/strong>. Elles peuvent transmettre la bartonellose pour votre <strong>chat<\/strong> ou encore des vers. Par exemple, le taenia.<\/p><p><\/p><p><\/p><h2 class=\"wp-block-heading\">Les tiques : ces nuisibles qui g\u00e2chent la vie de votre chien ou votre chat<\/h2><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Les <strong>tiques sont des nuisibles fr\u00e9quents<\/strong> qui g\u00e2chent la vie de votre animal. Pr\u00e9sentes dans les <strong>herbes hautes<\/strong>, elles s\u2019impr\u00e8gnent dans votre animal et se nourrissent de leur sang. Ces nuisibles peuvent vivre et se reproduire \u00e0 l\u2019int\u00e9rieur comme \u00e0 l\u2019ext\u00e9rieur\u2026 En outre, tout comme les puces, les <strong>tiques propagent de nombreuses maladies<\/strong> graves comme la <strong>Bab\u00e9siose<\/strong> et la <strong>maladie de Lyme<\/strong>\u2026 Cela peut \u00eatre non seulement tr\u00e8s dangereux, <strong>mortel pour votre chien ou chat<\/strong>, mais aussi <strong>pour vous\u00a0<\/strong>!<\/p><h2>Les vers : ces nuisibles sournois<\/h2><p>Les <strong>vers<\/strong> sont \u00e9galement partout\u00a0! Vous pouvez trouver des \u0153ufs, des larves de vers dans l\u2019herbe, dans la terre. De plus, certains <strong>insectes<\/strong>, <strong>animaux contamin\u00e9s<\/strong> peuvent \u00e9galement en avoir. Ainsi, votre chien ou chat peut \u00eatre contamin\u00e9 n\u2019importe o\u00f9 en ext\u00e9rieur. Il faut \u00eatre tr\u00e8s vigilant car il peut <strong>ing\u00e9rer directement<\/strong> des \u0153ufs, des larves de vers ou alors en attraper via des souris, des puces.<\/p><p>Les <strong>vers sont des nuisibles sournois<\/strong> car ils sont difficilement d\u00e9tectables. En fait, votre animal de compagnie peut <strong>ne pr\u00e9senter aucun sympt\u00f4me jusqu\u2019\u00e0 que l\u2019infestation devienne trop importante<\/strong>. Les chiens et chats peuvent \u00e9galement transmettre ces vers \u00e0 leur(s) propri\u00e9taire(s). Il s\u2019agit donc de se rendre r\u00e9guli\u00e8rement chez un v\u00e9t\u00e9rinaire pour une <strong>vermifugation<\/strong>.<\/p><h2>Moustiques et phl\u00e9botomes : ces nuisibles redoutables<\/h2><p>Comme pour l\u2019Homme, les <strong>moustiques<\/strong> et <strong>phl\u00e9botomes<\/strong> sont des nuisibles redoutables pour votre <strong>chien ou votre chat<\/strong>. Les phl\u00e9botomes sont des moucherons, semblables aux moustiques, mais <strong>velus<\/strong>. Ils propagent en buvant le sang, la Leishmaniose. C\u2019est une maladie extr\u00eamement fr\u00e9quente dans le bassin m\u00e9diterran\u00e9en et le <strong>sud de la France<\/strong>. Les <strong>phl\u00e9botomes<\/strong> sont particuli\u00e8rement actifs d\u2019avril \u00e0 novembre, tout particuli\u00e8rement lorsque le soleil se couche. Cette <strong>maladie mortelle<\/strong> doit \u00eatre absolument trait\u00e9e.<\/p><h2>Comment prot\u00e9ger mon animal de compagnie contre ces parasites ?<\/h2><p>Afin de <strong>prot\u00e9ger votre animal de compagnie contre tous ces, parasites<\/strong>, ces <strong>nuisibles plus ou moins invisibles<\/strong>, vous pouvez acheter certains <strong>produits<\/strong> et en parler \u00e0 votre v\u00e9t\u00e9rinaire.<\/p><p><strong>Soyez tr\u00e8s vigilants<\/strong> et n&#8217;attendez pas pour lutter ces nuisibles.<\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b894d90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b894d90\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71862070\" data-id=\"71862070\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22124d6a elementor-widget elementor-widget-heading\" data-id=\"22124d6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"line-height: 1.4;margin-top: 20px;margin-bottom: 10px;font-size: 18px;text-align: center\">S\u00e9lections de produits v\u00e9t\u00e9rinaire contre les puces, tiques, parasites pour le chien et le chat<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-609c8cf7 product_alcyon elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"609c8cf7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f5adf4d\" data-id=\"f5adf4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64da76f9 elementor-widget elementor-widget-image\" data-id=\"64da76f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-299238\" alt=\"seresto-chat-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-64x64.jpeg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino.jpeg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1667dc5 elementor-widget elementor-widget-heading\" data-id=\"1667dc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u200bSeresto\nANTIPARASITAIRE CHAT<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a1022f elementor-widget elementor-widget-text-editor\" data-id=\"1a1022f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Seresto est un collier qui prot\u00e8ge l\u2019animal et son environnement imm\u00e9diat des parasites.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2899d5b6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2899d5b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/seresto-chat\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-427dc676\" data-id=\"427dc676\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e5e233 elementor-widget elementor-widget-image\" data-id=\"7e5e233\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299572\" alt=\"Advantix chien moyen vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bc9d0b4 elementor-widget elementor-widget-heading\" data-id=\"7bc9d0b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Advantix SOLUTION ANTIPARASITAIRE CHIEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-382c0a9c elementor-widget elementor-widget-text-editor\" data-id=\"382c0a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Advantix chien moyen 10-15kg est une solution cutan\u00e9e antiparasitaire externe pour chien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8297703 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8297703\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/advantix-chien-moyen-10-25-kg-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-109ac1ab\" data-id=\"109ac1ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3feeaf17 elementor-widget elementor-widget-image\" data-id=\"3feeaf17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299575\" alt=\"scalibor grand chien vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c93c41b elementor-widget elementor-widget-heading\" data-id=\"c93c41b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scalibor COLLIER REPULSIF GRAND CHIEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-787c782a elementor-widget elementor-widget-text-editor\" data-id=\"787c782a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Scalibor est un collier antiparasitaire externe pour chiens. Il prot\u00e8ge votre chien entre 6 \u00e0 12 mois.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1846e78c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1846e78c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/scalibor-collier-antitique-65-cm\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1c8d4088\" data-id=\"1c8d4088\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-470a60de elementor-widget elementor-widget-image\" data-id=\"470a60de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-299243\" alt=\"frontline-spot-on-chat-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-64x64.jpeg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino.jpeg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-762a233e elementor-widget elementor-widget-heading\" data-id=\"762a233e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Merial PIPETTES FRONTLINE SPOT-ON CHAT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d8bfac3 elementor-widget elementor-widget-text-editor\" data-id=\"2d8bfac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>FRONTLINE Spot-On permet de lutter contre les parasites du chat. Efficace contre puces, poux et tiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a5119c3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3a5119c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/frontline-spot-on-chat\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45cdf7c product_centravet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45cdf7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-49708ae\" data-id=\"49708ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd6ed54 elementor-widget elementor-widget-image\" data-id=\"dd6ed54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-299238\" alt=\"seresto-chat-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-64x64.jpeg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino.jpeg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ef3e07 elementor-widget elementor-widget-heading\" data-id=\"7ef3e07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u200bSeresto\nANTIPARASITAIRE CHAT<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2f8e4e elementor-widget elementor-widget-text-editor\" data-id=\"d2f8e4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Seresto est un collier qui prot\u00e8ge l\u2019animal et son environnement imm\u00e9diat des parasites.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1ba3c3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b1ba3c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/seresto-collier-chat\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d2d6556\" data-id=\"d2d6556\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-520cf66 elementor-widget elementor-widget-image\" data-id=\"520cf66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299572\" alt=\"Advantix chien moyen vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e6bf13 elementor-widget elementor-widget-heading\" data-id=\"1e6bf13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Advantix SOLUTION ANTIPARASITAIRE CHIEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1f6795 elementor-widget elementor-widget-text-editor\" data-id=\"e1f6795\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Advantix chien moyen 10-15kg est une solution cutan\u00e9e antiparasitaire externe pour chien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-806d56f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"806d56f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/advantix-chien-moyen-10-25-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2ff8de9\" data-id=\"2ff8de9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cfd4c4 elementor-widget elementor-widget-image\" data-id=\"8cfd4c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299575\" alt=\"scalibor grand chien vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb3ee63 elementor-widget elementor-widget-heading\" data-id=\"bb3ee63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scalibor COLLIER REPULSIF GRAND CHIEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9b1f5b elementor-widget elementor-widget-text-editor\" data-id=\"e9b1f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Scalibor est un collier antiparasitaire externe pour chiens. Il prot\u00e8ge votre chien entre 6 \u00e0 12 mois.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fafd195 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"fafd195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/scalibor-collier-grand-chien\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-77ebfcc\" data-id=\"77ebfcc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2821254 elementor-widget elementor-widget-image\" data-id=\"2821254\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-299243\" alt=\"frontline-spot-on-chat-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-64x64.jpeg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino.jpeg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b7b962 elementor-widget elementor-widget-heading\" data-id=\"4b7b962\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Merial PIPETTES FRONTLINE SPOT-ON CHAT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fde2213 elementor-widget elementor-widget-text-editor\" data-id=\"fde2213\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>FRONTLINE Spot-On permet de lutter contre les parasites du chat. Efficace contre puces, poux et tiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b74e320 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b74e320\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/frontline-spot-on-chat-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e63dceb product_coveto elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e63dceb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8a05e5d\" data-id=\"8a05e5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83b891d elementor-widget elementor-widget-image\" data-id=\"83b891d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-299238\" alt=\"seresto-chat-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino-64x64.jpeg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/seresto-chat-vetorino.jpeg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe2e8fe elementor-widget elementor-widget-heading\" data-id=\"fe2e8fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u200bSeresto\nANTIPARASITAIRE CHAT<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd7fb38 elementor-widget elementor-widget-text-editor\" data-id=\"bd7fb38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Seresto est un collier qui prot\u00e8ge l\u2019animal et son environnement imm\u00e9diat des parasites.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84fa7d8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"84fa7d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/seresto-collier-chat-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ac16d52\" data-id=\"ac16d52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3a83fb elementor-widget elementor-widget-image\" data-id=\"f3a83fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299572\" alt=\"Advantix chien moyen vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/advantix-chien-moyen-de-10-a-25-kg-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bd9998 elementor-widget elementor-widget-heading\" data-id=\"9bd9998\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Advantix SOLUTION ANTIPARASITAIRE CHIEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-337db6b elementor-widget elementor-widget-text-editor\" data-id=\"337db6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Advantix chien moyen 10-15kg est une solution cutan\u00e9e antiparasitaire externe pour chien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-451eadd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"451eadd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/advantix-chien-moyen-10-25-kg-boite-de-24-pipettes-de-25-ml\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2cd4d4b\" data-id=\"2cd4d4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c264555 elementor-widget elementor-widget-image\" data-id=\"c264555\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299575\" alt=\"scalibor grand chien vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/scalibor-grand-chien-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b35cf2b elementor-widget elementor-widget-heading\" data-id=\"b35cf2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scalibor COLLIER REPULSIF GRAND CHIEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04300ae elementor-widget elementor-widget-text-editor\" data-id=\"04300ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Scalibor est un collier antiparasitaire externe pour chiens. Il prot\u00e8ge votre chien entre 6 \u00e0 12 mois.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb9f8a9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"fb9f8a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/scalibor-collier-grand-chien-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a21354b\" data-id=\"a21354b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d72ea91 elementor-widget elementor-widget-image\" data-id=\"d72ea91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-299243\" alt=\"frontline-spot-on-chat-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino-64x64.jpeg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/frontline-spot-on-chat-vetorino.jpeg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b882e19 elementor-widget elementor-widget-heading\" data-id=\"b882e19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Merial PIPETTES FRONTLINE SPOT-ON CHAT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae10018 elementor-widget elementor-widget-text-editor\" data-id=\"ae10018\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>FRONTLINE Spot-On permet de lutter contre les parasites du chat. Efficace contre puces, poux et tiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8a42d9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d8a42d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/product\/frontline-spot-on-chat-4-pipettes-de-05-ml\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57a8621f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57a8621f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2bdd5641\" data-id=\"2bdd5641\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b363e8c elementor-widget elementor-widget-text-editor\" data-id=\"7b363e8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"color: #078ed2;text-align: center\"><a href=\"https:\/\/www.vetorino.com\/boutique\/product-category\/chat\/produit-veterinaire-du-chat\/antiparasitaire-du-chat\/\">D\u00e9couvrez notre s\u00e9lection de produits anti parasitaires pour votre chien et votre chat<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Parasites du chien et du chat : attention \u00e0 ces nuisibles quasi invisibles ! Les parasites pour le chien et le chat sont nombreux. Nous vous recommandons vivement de faire attention \u00e0 ces nuisibles quasi-invisibles\u2026\u00a0! En effet, seul 5% des nuisibles comme les puces sont visibles \u00e0 l\u2019\u0153il nu sur votre animal de compagnie\u00a0! Les [&hellip;]<\/p>\n","protected":false},"author":10426,"featured_media":297203,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14086,14087,14095,14094],"tags":[],"class_list":["post-297194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chat","category-chien","category-sante-et-prevention-chat","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les parasites chez le chien et le chat, les dangers des tiques et des puces - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Cliquez ici pour d\u00e9couvrir comment g\u00e9rer les parasites chez le chien et le chat ! Quels sont les dangers des tiques et des puces et bien plus\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les parasites chez le chien et le chat, les dangers des tiques et des puces - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Cliquez ici pour d\u00e9couvrir comment g\u00e9rer les parasites chez le chien et le chat ! Quels sont les dangers des tiques et des puces et bien plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-24T14:02:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:22:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1285\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe V\u00e9torino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe V\u00e9torino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/\"},\"author\":{\"name\":\"Equipe V\u00e9torino\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/8f60afb04d773f2295479f6eb9cd43e4\"},\"headline\":\"Les parasites chez le chien et le chat, les dangers des tiques et des puces\",\"datePublished\":\"2022-02-24T14:02:58+00:00\",\"dateModified\":\"2024-08-08T15:22:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/\"},\"wordCount\":1084,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/christmas-beetle-gc3014372f_1920.jpg\",\"articleSection\":[\"Chat\",\"Chien\",\"Sant\u00e9 et pr\u00e9vention pour chat\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/\",\"name\":\"Les parasites chez le chien et le chat, les dangers des tiques et des puces - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/christmas-beetle-gc3014372f_1920.jpg\",\"datePublished\":\"2022-02-24T14:02:58+00:00\",\"dateModified\":\"2024-08-08T15:22:07+00:00\",\"description\":\"Cliquez ici pour d\u00e9couvrir comment g\u00e9rer les parasites chez le chien et le chat ! Quels sont les dangers des tiques et des puces et bien plus\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/christmas-beetle-gc3014372f_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/christmas-beetle-gc3014372f_1920.jpg\",\"width\":1920,\"height\":1285,\"caption\":\"Les puces : ces nuisibles quasi invisibles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sant\u00e9 et pr\u00e9vention pour chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/category\\\/chat\\\/sante-et-prevention-chat\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Les parasites chez le chien et le chat, les dangers des tiques et des puces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/8f60afb04d773f2295479f6eb9cd43e4\",\"name\":\"Equipe V\u00e9torino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"caption\":\"Equipe V\u00e9torino\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/toulouse-st-cyprien-31300\\\/boutique\\\/author\\\/equipe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les parasites chez le chien et le chat, les dangers des tiques et des puces - V\u00e9torino","description":"Cliquez ici pour d\u00e9couvrir comment g\u00e9rer les parasites chez le chien et le chat ! Quels sont les dangers des tiques et des puces et bien plus","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Les parasites chez le chien et le chat, les dangers des tiques et des puces - V\u00e9torino","og_description":"Cliquez ici pour d\u00e9couvrir comment g\u00e9rer les parasites chez le chien et le chat ! Quels sont les dangers des tiques et des puces et bien plus","og_url":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2022-02-24T14:02:58+00:00","article_modified_time":"2024-08-08T15:22:07+00:00","og_image":[{"width":1920,"height":1285,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920.jpg","type":"image\/jpeg"}],"author":"Equipe V\u00e9torino","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Equipe V\u00e9torino","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/"},"author":{"name":"Equipe V\u00e9torino","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/8f60afb04d773f2295479f6eb9cd43e4"},"headline":"Les parasites chez le chien et le chat, les dangers des tiques et des puces","datePublished":"2022-02-24T14:02:58+00:00","dateModified":"2024-08-08T15:22:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/"},"wordCount":1084,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920.jpg","articleSection":["Chat","Chien","Sant\u00e9 et pr\u00e9vention pour chat","Sant\u00e9 pour chien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/","url":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/","name":"Les parasites chez le chien et le chat, les dangers des tiques et des puces - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920.jpg","datePublished":"2022-02-24T14:02:58+00:00","dateModified":"2024-08-08T15:22:07+00:00","description":"Cliquez ici pour d\u00e9couvrir comment g\u00e9rer les parasites chez le chien et le chat ! Quels sont les dangers des tiques et des puces et bien plus","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/christmas-beetle-gc3014372f_1920.jpg","width":1920,"height":1285,"caption":"Les puces : ces nuisibles quasi invisibles"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/les-parasites-chez-le-chien-et-le-chat-les-dangers-des-tiques-et-des-puces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"Sant\u00e9 et pr\u00e9vention pour chat","item":"https:\/\/www.vetorino.com\/boutique\/category\/chat\/sante-et-prevention-chat\/"},{"@type":"ListItem","position":4,"name":"Les parasites chez le chien et le chat, les dangers des tiques et des puces"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/8f60afb04d773f2295479f6eb9cd43e4","name":"Equipe V\u00e9torino","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","caption":"Equipe V\u00e9torino"},"url":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/author\/equipe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/posts\/297194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/users\/10426"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/comments?post=297194"}],"version-history":[{"count":34,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/posts\/297194\/revisions"}],"predecessor-version":[{"id":578214,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/posts\/297194\/revisions\/578214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/media\/297203"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/media?parent=297194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/categories?post=297194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-st-cyprien-31300\/boutique\/wp-json\/wp\/v2\/tags?post=297194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}