{"id":1359897,"date":"2025-06-25T12:00:00","date_gmt":"2025-06-25T10:00:00","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=1359897"},"modified":"2025-08-05T15:29:44","modified_gmt":"2025-08-05T13:29:44","slug":"chat-peu-actif-alimentation","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/","title":{"rendered":"Gros dormeur, petit mangeur : comment bien nourrir un chat peu actif ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1359897\" class=\"elementor elementor-1359897\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4747b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4747b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85eaa64\" data-id=\"85eaa64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a41696e elementor-widget elementor-widget-post-info\" data-id=\"a41696e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-b8ca39c elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tPubli\u00e9 le\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-bbe24d6 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/2025\/06\/25\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-calendar\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>juin 25, 2025<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-6bff815 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-time\">\n\t\t\t\t\t\t\t\t\t\t<time>12:00<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d4bbca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d4bbca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-879fec8\" data-id=\"879fec8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95df0a5 elementor-widget elementor-widget-text-editor\" data-id=\"95df0a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section data-id=\"8j8qvkr\" data-element_type=\"section\"><div data-id=\"tcv8rwn\" data-element_type=\"heading.default\">Gros dormeur, petit mangeur : comment bien nourrir un chat peu actif ?<br \/><!-- notionvc: 3b4d4ca9-e767-4365-9375-bf8f4630222f --><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b51a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86b51a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca49f12\" data-id=\"ca49f12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d92d7f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d92d7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Votre chat passe la majeure partie de ses journ\u00e9es \u00e0 dormir et montre peu d\u2019enthousiasme \u00e0 l\u2019heure des repas ? C\u2019est une situation fr\u00e9quente, surtout chez les chats d\u2019int\u00e9rieur, st\u00e9rilis\u00e9s ou \u00e2g\u00e9s. Pour autant, bien nourrir un chat peu actif reste essentiel pour pr\u00e9server sa sant\u00e9.<\/p><p>L\u2019objectif : lui fournir une <strong>alimentation adapt\u00e9e \u00e0 son rythme de vie<\/strong>, sans exc\u00e8s de calories, mais riche en nutriments essentiels.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37f3744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37f3744\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5abeb12\" data-id=\"5abeb12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48e3ba0 elementor-widget elementor-widget-heading\" data-id=\"48e3ba0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une alimentation all\u00e9g\u00e9e, mais pas vide<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-448f199 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"448f199\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un chat au m\u00e9tabolisme ralenti a besoin :<\/p><p>&#8211; d\u2019un apport r\u00e9duit en mati\u00e8res grasses,<br \/>&#8211; d\u2019une teneur \u00e9lev\u00e9e en prot\u00e9ines pour entretenir sa masse musculaire,<br \/>&#8211; et de fibres pour favoriser la sati\u00e9t\u00e9 sans surcharger son estomac.<\/p><p>Privil\u00e9giez les croquettes v\u00e9t\u00e9rinaires sp\u00e9ciales chats st\u00e9rilis\u00e9s, ou des p\u00e2t\u00e9es all\u00e9g\u00e9es. Elles sont formul\u00e9es pour limiter la prise de poids tout en couvrant tous ses besoins.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e442a3b elementor-widget elementor-widget-image\" data-id=\"e442a3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"864\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-peu-actif-1536x864.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-1359910\" alt=\"chat d&apos;int\u00e9rieur\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-peu-actif-1536x864.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-peu-actif-300x169.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-peu-actif-1024x576.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-peu-actif-768x432.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-peu-actif-2048x1152.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-peu-actif-555x312.jpg 555w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b291e elementor-widget elementor-widget-heading\" data-id=\"c5b291e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos conseils pour stimuler son app\u00e9tit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5245d3d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5245d3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un chat peu actif peut aussi \u00eatre un petit mangeur. Voici quelques astuces pour l\u2019inciter \u00e0 manger :<\/p><p>&#8211; fractionnez les repas : <strong>4 \u00e0 5 petites portions par jour<\/strong><br \/>&#8211; proposez-lui <strong>une texture qu\u2019il appr\u00e9cie<\/strong> (croquettes, bouch\u00e9es, p\u00e2t\u00e9e ou mix)<br \/>&#8211; utilisez une gamelle anti-glouton ou des jouets distributeurs pour stimuler sa curiosit\u00e9.<\/p><p>Sur vetorino.com, vous trouverez des croquettes v\u00e9t\u00e9rinaires sp\u00e9cialement pens\u00e9es pour les chats d\u2019int\u00e9rieur, ainsi que des compl\u00e9ments pour booster leur app\u00e9tit de fa\u00e7on naturelle.<\/p><p>Si votre chat boude totalement sa gamelle ou perd du poids, n\u2019attendez pas : parlez-en \u00e0 votre v\u00e9t\u00e9rinaire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1570360 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1570360\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/boulogne-billancourt-92100\/boutique\/product-category\/chat\/?s&#038;maladie=sterilise&#038;swcfpc=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir tous les produits pour les chats peu actifs<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gros dormeur, petit mangeur : comment bien nourrir un chat peu actif ? Votre chat passe la majeure partie de ses journ\u00e9es \u00e0 dormir et montre peu d\u2019enthousiasme \u00e0 l\u2019heure des repas ? C\u2019est une situation fr\u00e9quente, surtout chez les chats d\u2019int\u00e9rieur, st\u00e9rilis\u00e9s ou \u00e2g\u00e9s. Pour autant, bien nourrir un chat peu actif reste essentiel [&hellip;]<\/p>\n","protected":false},"author":68707,"featured_media":1359904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14089,14086,14095],"tags":[],"class_list":["post-1359897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentation-chat","category-chat","category-sante-et-prevention-chat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chat peu actif : comment le nourrir ?<\/title>\n<meta name=\"description\" content=\"Votre chat passe la majeure partie de ses journ\u00e9es \u00e0 dormir et montre peu d\u2019enthousiasme \u00e0 l\u2019heure des repas ? On a la solution pour vous !\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chat peu actif : comment le nourrir ?\" \/>\n<meta property=\"og:description\" content=\"Votre chat passe la majeure partie de ses journ\u00e9es \u00e0 dormir et montre peu d\u2019enthousiasme \u00e0 l\u2019heure des repas ? On a la solution pour vous !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-25T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T13:29:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-interieur.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Clemence Sully\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clemence Sully\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/\"},\"author\":{\"name\":\"Clemence Sully\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/dd1a92ffc9c104bc7eabde668f90847a\"},\"headline\":\"Gros dormeur, petit mangeur : comment bien nourrir un chat peu actif ?\",\"datePublished\":\"2025-06-25T10:00:00+00:00\",\"dateModified\":\"2025-08-05T13:29:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/\"},\"wordCount\":311,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/chat-interieur.jpg\",\"articleSection\":[\"Alimentation pour chat\",\"Chat\",\"Sant\u00e9 et pr\u00e9vention pour chat\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/\",\"name\":\"Chat peu actif : comment le nourrir ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/chat-interieur.jpg\",\"datePublished\":\"2025-06-25T10:00:00+00:00\",\"dateModified\":\"2025-08-05T13:29:44+00:00\",\"description\":\"Votre chat passe la majeure partie de ses journ\u00e9es \u00e0 dormir et montre peu d\u2019enthousiasme \u00e0 l\u2019heure des repas ? On a la solution pour vous !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/chat-interieur.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/chat-interieur.jpg\",\"width\":1905,\"height\":450,\"caption\":\"chat peu actif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/06\\\/25\\\/chat-peu-actif-alimentation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gros dormeur, petit mangeur : comment bien nourrir un chat peu actif ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/dd1a92ffc9c104bc7eabde668f90847a\",\"name\":\"Clemence Sully\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"caption\":\"Clemence Sully\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vaulxenvelin-69120\\\/boutique\\\/author\\\/clemence-sully\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chat peu actif : comment le nourrir ?","description":"Votre chat passe la majeure partie de ses journ\u00e9es \u00e0 dormir et montre peu d\u2019enthousiasme \u00e0 l\u2019heure des repas ? On a la solution pour vous !","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Chat peu actif : comment le nourrir ?","og_description":"Votre chat passe la majeure partie de ses journ\u00e9es \u00e0 dormir et montre peu d\u2019enthousiasme \u00e0 l\u2019heure des repas ? On a la solution pour vous !","og_url":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2025-06-25T10:00:00+00:00","article_modified_time":"2025-08-05T13:29:44+00:00","og_image":[{"width":1905,"height":450,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-interieur.jpg","type":"image\/jpeg"}],"author":"Clemence Sully","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Clemence Sully","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/"},"author":{"name":"Clemence Sully","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/dd1a92ffc9c104bc7eabde668f90847a"},"headline":"Gros dormeur, petit mangeur : comment bien nourrir un chat peu actif ?","datePublished":"2025-06-25T10:00:00+00:00","dateModified":"2025-08-05T13:29:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/"},"wordCount":311,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-interieur.jpg","articleSection":["Alimentation pour chat","Chat","Sant\u00e9 et pr\u00e9vention pour chat"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/","url":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/","name":"Chat peu actif : comment le nourrir ?","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-interieur.jpg","datePublished":"2025-06-25T10:00:00+00:00","dateModified":"2025-08-05T13:29:44+00:00","description":"Votre chat passe la majeure partie de ses journ\u00e9es \u00e0 dormir et montre peu d\u2019enthousiasme \u00e0 l\u2019heure des repas ? On a la solution pour vous !","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-interieur.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chat-interieur.jpg","width":1905,"height":450,"caption":"chat peu actif"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/06\/25\/chat-peu-actif-alimentation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"Gros dormeur, petit mangeur : comment bien nourrir un chat peu actif ?"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/dd1a92ffc9c104bc7eabde668f90847a","name":"Clemence Sully","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","caption":"Clemence Sully"},"url":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/author\/clemence-sully\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/posts\/1359897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/users\/68707"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/comments?post=1359897"}],"version-history":[{"count":8,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/posts\/1359897\/revisions"}],"predecessor-version":[{"id":1441276,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/posts\/1359897\/revisions\/1441276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/media\/1359904"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/media?parent=1359897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/categories?post=1359897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/tags?post=1359897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}