{"id":585967,"date":"2023-04-03T12:13:05","date_gmt":"2023-04-03T10:13:05","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=585967"},"modified":"2024-08-08T17:21:32","modified_gmt":"2024-08-08T15:21:32","slug":"mission-amis-pour-la-vie-2023","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/","title":{"rendered":"Hill&#8217;s : Mission Amis Pour La Vie \ud83d\udc99"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"585967\" class=\"elementor elementor-585967\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b69029 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b69029\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8897d87\" data-id=\"8897d87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe4dafa product_alcyon elementor-widget elementor-widget-image\" data-id=\"fe4dafa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"512\" height=\"156\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.jpg\" class=\"attachment-large size-large wp-image-592937\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.jpg 512w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3-300x91.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cf2d2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cf2d2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b49d9fa\" data-id=\"b49d9fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8ad44a product_centravet elementor-widget elementor-widget-image\" data-id=\"c8ad44a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"512\" height=\"156\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.jpg\" class=\"attachment-large size-large wp-image-592937\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.jpg 512w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3-300x91.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7bf7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7bf7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4db9751\" data-id=\"4db9751\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-358f636 product_coveto elementor-widget elementor-widget-image\" data-id=\"358f636\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"512\" height=\"156\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.jpg\" class=\"attachment-large size-large wp-image-592937\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.jpg 512w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3-300x91.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4896022 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4896022\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84a3286\" data-id=\"84a3286\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a55efad elementor-widget elementor-widget-text-editor\" data-id=\"a55efad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Parce que nous sommes convaincus que TOUS les animaux m\u00e9ritent une seconde chance, nous nous associons cette ann\u00e9e encore au laboratoire Hill\u2019s afin de soutenir son action solidaire <\/span><b>#MissionAmisPourLaVie<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7ed82c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7ed82c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c4f9096\" data-id=\"c4f9096\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dff569 product_alcyon elementor-widget elementor-widget-image\" data-id=\"5dff569\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"96\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed.png\" class=\"attachment-large size-large wp-image-592938\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed.png 512w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-300x56.png 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a472dc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a472dc7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87400d1\" data-id=\"87400d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e424918 product_centravet elementor-widget elementor-widget-image\" data-id=\"e424918\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"96\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed.png\" class=\"attachment-large size-large wp-image-592938\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed.png 512w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-300x56.png 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d22823b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d22823b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cab937a\" data-id=\"cab937a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-355c225 product_coveto elementor-widget elementor-widget-image\" data-id=\"355c225\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"96\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed.png\" class=\"attachment-large size-large wp-image-592938\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed.png 512w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-300x56.png 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-111de9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"111de9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e926695\" data-id=\"e926695\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64820a9 elementor-widget elementor-widget-spacer\" data-id=\"64820a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0a711f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0a711f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-580de08\" data-id=\"580de08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04ff363 elementor-widget elementor-widget-heading\" data-id=\"04ff363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\ud83d\udc99 Mission Amis Pour La Vie, c\u2019est quoi ? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8cfd05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8cfd05\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e513f0\" data-id=\"2e513f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb1d826 elementor-widget elementor-widget-text-editor\" data-id=\"cb1d826\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">C\u2019est une op\u00e9ration solidaire organis\u00e9e par Hill\u2019s pour la 3<\/span><span style=\"font-weight: 400;\">\u00e8me<\/span><span style=\"font-weight: 400;\"> ann\u00e9e cons\u00e9cutive qui vient en aide aux animaux des refuges \u00e0 travers l\u2019Europe.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e107bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e107bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb5fda7\" data-id=\"bb5fda7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc82685 elementor-widget elementor-widget-spacer\" data-id=\"cc82685\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99e3f05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99e3f05\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a6244cd\" data-id=\"a6244cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb7fbb0 elementor-widget elementor-widget-heading\" data-id=\"bb7fbb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\ud83d\udc99 Comment ? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb0bca2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb0bca2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5666bd7\" data-id=\"5666bd7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbf8eea elementor-widget elementor-widget-text-editor\" data-id=\"fbf8eea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Au travers de dons d\u2019aliments Hill\u2019s &#8211; des aliments de haute qualit\u00e9 \u00e9labor\u00e9s par des nutritionnistes et des v\u00e9t\u00e9rinaires \u2013 <\/span><b>Mission Amis Pour La Vie<\/b><span style=\"font-weight: 400;\"> soutient l\u2019action des refuges et aide les animaux \u00e0 retrouver un nouveau foyer aimant pour la vie.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-010d5f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"010d5f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a5db0c\" data-id=\"2a5db0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49cd0ac elementor-widget elementor-widget-spacer\" data-id=\"49cd0ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b61dc9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b61dc9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c393339\" data-id=\"c393339\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7408af7 elementor-widget elementor-widget-heading\" data-id=\"7408af7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">D\u00e9couvrez la Mission Amis Pour La Vie en vid\u00e9o<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09b7878 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09b7878\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c6c8ad\" data-id=\"7c6c8ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7184b9 elementor-widget elementor-widget-image\" data-id=\"d7184b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/Vetorino\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-592951\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1-1-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1-1-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1-1-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1-1-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1-1.jpg 507w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3eac188 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3eac188\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac4e52a\" data-id=\"ac4e52a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af70da7 elementor-widget elementor-widget-video\" data-id=\"af70da7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=eqDmsl2p9Xw&amp;ab_channel=Hill%27sPetNutritionFrance &quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-694284d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"694284d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd55e8c\" data-id=\"dd55e8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f8ee73 elementor-widget elementor-widget-heading\" data-id=\"6f8ee73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Rejoignez-nous et aidez-nous \u00e0 atteindre un nouvel objectif<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11962cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11962cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9c27e8\" data-id=\"b9c27e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c1be9e elementor-widget elementor-widget-heading\" data-id=\"5c1be9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\ud83d\udc31 Offrir 200 000 repas aux animaux des refuges \ud83d\udc36 <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d43c9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d43c9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-277ca1d\" data-id=\"277ca1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d104cdf elementor-widget elementor-widget-spacer\" data-id=\"d104cdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a63454 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a63454\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-30a07c0\" data-id=\"30a07c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-111c4c2 elementor-widget elementor-widget-text-editor\" data-id=\"111c4c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>2021<\/b><\/p><p><span style=\"font-weight: 400;\">100\u00a0000 repas offerts\u00a0<\/span><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-95315ff\" data-id=\"95315ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7eb8e0 elementor-widget elementor-widget-text-editor\" data-id=\"a7eb8e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>2022<\/b><\/p><p><span style=\"font-weight: 400;\">150\u00a0000 repas offerts <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-651a8b8\" data-id=\"651a8b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dddb3af elementor-widget elementor-widget-text-editor\" data-id=\"dddb3af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>2023<\/strong><\/p><p><span style=\"font-weight: 400;\">Objectif <\/span><span style=\"font-weight: 400;\">\ud83e\udc6a<\/span><span style=\"font-weight: 400;\"> 200\u00a0000 <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e7888d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e7888d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6a93c32\" data-id=\"6a93c32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e179f9e elementor-widget elementor-widget-image\" data-id=\"e179f9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"201\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-1.jpg\" class=\"attachment-large size-large wp-image-592950\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-1.jpg 306w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-1-300x197.jpg 300w\" sizes=\"(max-width: 306px) 100vw, 306px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a2d3f4a\" data-id=\"a2d3f4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-522ddca elementor-widget elementor-widget-image\" data-id=\"522ddca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"201\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-1.jpg\" class=\"attachment-large size-large wp-image-592950\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-1.jpg 306w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-1-300x197.jpg 300w\" sizes=\"(max-width: 306px) 100vw, 306px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ca84f40\" data-id=\"ca84f40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbb9cf8 elementor-widget elementor-widget-image\" data-id=\"bbb9cf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"201\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-1.jpg\" class=\"attachment-large size-large wp-image-592950\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-1.jpg 306w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-1-300x197.jpg 300w\" sizes=\"(max-width: 306px) 100vw, 306px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ceb29d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ceb29d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-adb9ac6\" data-id=\"adb9ac6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2fc03a elementor-widget elementor-widget-spacer\" data-id=\"b2fc03a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-375d64b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"375d64b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0afde3e\" data-id=\"0afde3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9752c3a elementor-widget elementor-widget-text-editor\" data-id=\"9752c3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Pour participer \u00e0 cette belle action solidaire, quelques clics suffisent !<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c2e1b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c2e1b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d02c0a5\" data-id=\"d02c0a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d1b836 elementor-widget elementor-widget-text-editor\" data-id=\"2d1b836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">1 achat d\u2019aliments Hill\u2019s<\/span><\/p><p><span style=\"font-weight: 400;\">=<\/span><\/p><p><b>1 repas offert*<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7f598f8\" data-id=\"7f598f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aef8599 elementor-widget elementor-widget-text-editor\" data-id=\"aef8599\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">1 photo avec @hillspetfr<\/span><\/p><p><span style=\"font-weight: 400;\">=<\/span><\/p><p><b>1 repas offert*<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1496117 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1496117\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4706ae5\" data-id=\"4706ae5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec2d30c elementor-widget elementor-widget-image\" data-id=\"ec2d30c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"376\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2.png\" class=\"attachment-large size-large wp-image-592946\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2.png 512w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-300x220.png 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1273b88\" data-id=\"1273b88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b45acef elementor-widget elementor-widget-image\" data-id=\"b45acef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/vetorino_off\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"287\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1-300x287.png\" class=\"attachment-medium size-medium wp-image-592948\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1-300x287.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1.png 314w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fab6f95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fab6f95\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-143721f\" data-id=\"143721f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62bc5d4 elementor-widget elementor-widget-text-editor\" data-id=\"62bc5d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Offrez une alimentation de qualit\u00e9 \u00e0 votre chien ou \u00e0 votre chat et profitez d\u2019un large choix d\u2019aliments d\u00e9clin\u00e9 selon son \u00e2ge, son mode de vie et ses besoins sp\u00e9cifiques.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d6d1a27\" data-id=\"d6d1a27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cf0b72 elementor-widget elementor-widget-text-editor\" data-id=\"8cf0b72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Retrouvez toutes les publications #MissionAmisPourLaVie sur Facebook et Instagram, des publications solidaires publi\u00e9es par des propri\u00e9taires aimants comme vous\u00a0!<\/span><\/p><p>\u00a0<\/p><p><b>Rejoignez le mouvement\u2026\u00a0<\/b><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a99d17 product_alcyon elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a99d17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d3cde36\" data-id=\"d3cde36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-313c474 elementor-align-right product_alcyon elementor-widget elementor-widget-button\" data-id=\"313c474\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/lasalvetatsaintgilles-31880\/boutique\/\/marque\/hills-pet-nutrition\/?categorie=chien&#038;s\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hill's pour chien \ud83d\udc36<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d13ae05\" data-id=\"d13ae05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80d503c elementor-align-left product_alcyon elementor-widget elementor-widget-button\" data-id=\"80d503c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/lasalvetatsaintgilles-31880\/boutique\/\/marque\/hills-pet-nutrition\/?categorie=chat&#038;s\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hill's pour chat \ud83d\udc31<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5270daa\" data-id=\"5270daa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98289b1 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"98289b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-007ed34\" href=\"https:\/\/www.facebook.com\/Vetorino\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8103460\" data-id=\"8103460\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1512826 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"1512826\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-007ed34\" href=\"https:\/\/www.instagram.com\/vetorino_off\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5351b7 product_centravet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5351b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5eba4e1\" data-id=\"5eba4e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53f22fb elementor-align-right elementor-widget elementor-widget-button\" data-id=\"53f22fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/lasalvetatsaintgilles-31880\/boutique\/\/marque\/hills-pet-nutrition\/?categorie=chien&#038;s\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hill's pour chien \ud83d\udc36<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-334dc27\" data-id=\"334dc27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43bc984 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"43bc984\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/lasalvetatsaintgilles-31880\/boutique\/\/marque\/hills-pet-nutrition\/?categorie=chat&#038;s\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hill's pour chat \ud83d\udc31<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-cf81057\" data-id=\"cf81057\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3929f6b elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"3929f6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-007ed34\" href=\"https:\/\/www.facebook.com\/Vetorino\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0813c8a\" data-id=\"0813c8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7e6057 elementor-shape-circle elementor-widget__width-initial elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"a7e6057\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-007ed34\" href=\"https:\/\/www.instagram.com\/vetorino_off\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-622592b product_coveto elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"622592b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2d6fc03\" data-id=\"2d6fc03\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc00556 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"fc00556\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/lasalvetatsaintgilles-31880\/boutique\/\/marque\/hills-pet-nutrition\/?categorie=chien&#038;s\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hill's pour chien \ud83d\udc36<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0b0b5fb\" data-id=\"0b0b5fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-148a0dc elementor-align-left elementor-widget elementor-widget-button\" data-id=\"148a0dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/lasalvetatsaintgilles-31880\/boutique\/\/marque\/hills-pet-nutrition\/?categorie=chat&#038;s\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hill's pour chat \ud83d\udc31<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a92def6\" data-id=\"a92def6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ece3b1c elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"ece3b1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-007ed34\" href=\"https:\/\/www.facebook.com\/Vetorino\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6f5f0ff\" data-id=\"6f5f0ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53912d6 elementor-shape-circle elementor-widget__width-initial elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"53912d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-007ed34\" href=\"https:\/\/www.instagram.com\/vetorino_off\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d995d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d995d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ec32d1\" data-id=\"7ec32d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7978ef elementor-widget elementor-widget-text-editor\" data-id=\"c7978ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">*\u00a0un\u00a0repas correspond \u00e0\u00a0environ 131 grammes d\u2019aliment.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af25021 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af25021\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-83111bc\" data-id=\"83111bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aeb5650 elementor-widget elementor-widget-spacer\" data-id=\"aeb5650\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91b713c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91b713c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e701b98\" data-id=\"e701b98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eb76eb elementor-widget elementor-widget-heading\" data-id=\"5eb76eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\ud83d\udc97 Le Programme \u201cNourrir, Accueillir &amp; Aimer\u201d de Hill\u2019s \ud83d\udc97<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c673166 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c673166\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-511ad06\" data-id=\"511ad06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f717ba7 product_alcyon elementor-widget elementor-widget-image\" data-id=\"f717ba7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/?s\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"216\" height=\"216\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.png\" class=\"attachment-large size-large wp-image-592945\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.png 216w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3-160x160.png 160w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca9474 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fca9474\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bed2beb\" data-id=\"bed2beb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cbed4b product_centravet elementor-widget elementor-widget-image\" data-id=\"1cbed4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"216\" height=\"216\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.png\" class=\"attachment-large size-large wp-image-592945\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.png 216w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3-160x160.png 160w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e2e1a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e2e1a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b8befe\" data-id=\"4b8befe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40c7c0a product_coveto elementor-widget elementor-widget-image\" data-id=\"40c7c0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/?s\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"216\" height=\"216\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.png\" class=\"attachment-large size-large wp-image-592945\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3.png 216w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-3-160x160.png 160w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4af7835 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4af7835\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5823325\" data-id=\"5823325\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68ab889 elementor-widget elementor-widget-text-editor\" data-id=\"68ab889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\"><strong>#MissionAmisPourLaVie<\/strong> s\u2019inscrit dans le cadre du programme <\/span><b>Nourrir, Accueillir &amp; Aimer<\/b><span style=\"font-weight: 400;\"> de Hill\u2019s qui a permis depuis 2002<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-978dc54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"978dc54\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b4b947\" data-id=\"5b4b947\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8c871e elementor-widget elementor-widget-text-editor\" data-id=\"c8c871e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">de cr\u00e9er des partenariats avec plus de <\/span><b>1000 <\/b><span style=\"font-weight: 400;\">refuges \u00e0 travers le monde&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">de fournir des aliments pour une valeur de plus de <\/span><b>235 millions<\/b><span style=\"font-weight: 400;\"> d\u2019euros<\/span><\/li>\n<li><span style=\"font-weight: 400;\">et d\u2019aider plus de <\/span><b>12 millions<\/b><span style=\"font-weight: 400;\"> d\u2019animaux \u00e0 retrouver un foyer aimant pour la vie&nbsp;! <\/span><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87170f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87170f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bff075e\" data-id=\"bff075e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa5d2c2 product_alcyon elementor-widget elementor-widget-image\" data-id=\"aa5d2c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"156\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2.jpg\" class=\"attachment-large size-large wp-image-592944\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2.jpg 512w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-2-300x91.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99fc9eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99fc9eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10b3d4e\" data-id=\"10b3d4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3d9247 product_centravet elementor-widget elementor-widget-image\" data-id=\"b3d9247\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.vetorino.com\/boutique\/2022\/07\/28\/un-bon-depart-dans-la-vie-grace-a-un-microbiome-sain\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"156\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1.jpg\" class=\"attachment-large size-large wp-image-592942\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1.jpg 512w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-1-300x91.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d59ca51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d59ca51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-baf77ff\" data-id=\"baf77ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ca7a8a product_coveto elementor-widget elementor-widget-image\" data-id=\"3ca7a8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/boutique\/marque\/hills-pet-nutrition\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"156\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed.jpg\" class=\"attachment-large size-large wp-image-592940\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed.jpg 512w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/unnamed-300x91.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Parce que nous sommes convaincus que TOUS les animaux m\u00e9ritent une seconde chance, nous nous associons cette ann\u00e9e encore au laboratoire Hill\u2019s afin de soutenir son action solidaire #MissionAmisPourLaVie \ud83d\udc99 Mission Amis Pour La Vie, c\u2019est quoi ? C\u2019est une op\u00e9ration solidaire organis\u00e9e par Hill\u2019s pour la 3\u00e8me ann\u00e9e cons\u00e9cutive qui vient en aide aux [&hellip;]<\/p>\n","protected":false},"author":8844,"featured_media":589901,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14089,14088,14086,14087],"tags":[],"class_list":["post-585967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentation-chat","category-alimentation-chien","category-chat","category-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hill&#039;s : Mission Amis Pour La Vie \ud83d\udc99 - V\u00e9torino<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hill&#039;s : Mission Amis Pour La Vie \ud83d\udc99 - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Parce que nous sommes convaincus que TOUS les animaux m\u00e9ritent une seconde chance, nous nous associons cette ann\u00e9e encore au laboratoire Hill\u2019s afin de soutenir son action solidaire #MissionAmisPourLaVie \ud83d\udc99 Mission Amis Pour La Vie, c\u2019est quoi ? C\u2019est une op\u00e9ration solidaire organis\u00e9e par Hill\u2019s pour la 3\u00e8me ann\u00e9e cons\u00e9cutive qui vient en aide aux [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-03T10:13:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/hill-vetorino-mission-pour-la-vie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"louisa.lecoq\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"louisa.lecoq\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/\"},\"author\":{\"name\":\"louisa.lecoq\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/3f7dbf40a28ebff86cc13d1ec5ed188b\"},\"headline\":\"Hill&#8217;s : Mission Amis Pour La Vie \ud83d\udc99\",\"datePublished\":\"2023-04-03T10:13:05+00:00\",\"dateModified\":\"2024-08-08T15:21:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/\"},\"wordCount\":348,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hill-vetorino-mission-pour-la-vie.jpg\",\"articleSection\":[\"Alimentation pour chat\",\"Alimentation pour chien\",\"Chat\",\"Chien\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/\",\"name\":\"Hill's : Mission Amis Pour La Vie \ud83d\udc99 - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hill-vetorino-mission-pour-la-vie.jpg\",\"datePublished\":\"2023-04-03T10:13:05+00:00\",\"dateModified\":\"2024-08-08T15:21:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hill-vetorino-mission-pour-la-vie.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hill-vetorino-mission-pour-la-vie.jpg\",\"width\":1024,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/04\\\/03\\\/mission-amis-pour-la-vie-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hill&#8217;s : Mission Amis Pour La Vie \ud83d\udc99\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/3f7dbf40a28ebff86cc13d1ec5ed188b\",\"name\":\"louisa.lecoq\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g\",\"caption\":\"louisa.lecoq\"},\"sameAs\":[\"louisa@vetorino.com\"],\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vaulxenvelin-69120\\\/boutique\\\/author\\\/louisa-lecoq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hill's : Mission Amis Pour La Vie \ud83d\udc99 - V\u00e9torino","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Hill's : Mission Amis Pour La Vie \ud83d\udc99 - V\u00e9torino","og_description":"Parce que nous sommes convaincus que TOUS les animaux m\u00e9ritent une seconde chance, nous nous associons cette ann\u00e9e encore au laboratoire Hill\u2019s afin de soutenir son action solidaire #MissionAmisPourLaVie \ud83d\udc99 Mission Amis Pour La Vie, c\u2019est quoi ? C\u2019est une op\u00e9ration solidaire organis\u00e9e par Hill\u2019s pour la 3\u00e8me ann\u00e9e cons\u00e9cutive qui vient en aide aux [&hellip;]","og_url":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2023-04-03T10:13:05+00:00","article_modified_time":"2024-08-08T15:21:32+00:00","og_image":[{"width":1024,"height":200,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/hill-vetorino-mission-pour-la-vie.jpg","type":"image\/jpeg"}],"author":"louisa.lecoq","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"louisa.lecoq","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/"},"author":{"name":"louisa.lecoq","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/3f7dbf40a28ebff86cc13d1ec5ed188b"},"headline":"Hill&#8217;s : Mission Amis Pour La Vie \ud83d\udc99","datePublished":"2023-04-03T10:13:05+00:00","dateModified":"2024-08-08T15:21:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/"},"wordCount":348,"commentCount":0,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/hill-vetorino-mission-pour-la-vie.jpg","articleSection":["Alimentation pour chat","Alimentation pour chien","Chat","Chien"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/","url":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/","name":"Hill's : Mission Amis Pour La Vie \ud83d\udc99 - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/hill-vetorino-mission-pour-la-vie.jpg","datePublished":"2023-04-03T10:13:05+00:00","dateModified":"2024-08-08T15:21:32+00:00","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/hill-vetorino-mission-pour-la-vie.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/04\/hill-vetorino-mission-pour-la-vie.jpg","width":1024,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/04\/03\/mission-amis-pour-la-vie-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chien","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chien\/"},{"@type":"ListItem","position":3,"name":"Hill&#8217;s : Mission Amis Pour La Vie \ud83d\udc99"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/3f7dbf40a28ebff86cc13d1ec5ed188b","name":"louisa.lecoq","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00509d5ba14116199a3cbd2883f4646ead7b314f922db472633779105bc1d560?s=96&d=mm&r=g","caption":"louisa.lecoq"},"sameAs":["louisa@vetorino.com"],"url":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/author\/louisa-lecoq\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/posts\/585967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/users\/8844"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/comments?post=585967"}],"version-history":[{"count":106,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/posts\/585967\/revisions"}],"predecessor-version":[{"id":593707,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/posts\/585967\/revisions\/593707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/media\/589901"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/media?parent=585967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/categories?post=585967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/tags?post=585967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}