{"id":1172404,"date":"2025-01-14T10:37:32","date_gmt":"2025-01-14T09:37:32","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/"},"modified":"2026-08-06T03:00:52","modified_gmt":"2026-08-06T01:00:52","slug":"chien-metabolic-mijotes-boeuf-legumes-boite","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/","title":{"rendered":"Chien Metabolic Mijot\u00e9 Boeuf &amp; L\u00e9gumes"},"content":{"rendered":"<p><strong>Aliment mijot\u00e9 au go\u00fbt de boeuf et de l\u00e9gumes pour chiens en surpoids.<\/strong><\/p>\n<p>Prescription Diet\u2122 Metabolic Canine Mijot\u00e9 est un aliment di\u00e9t\u00e9tique complet destin\u00e9 \u00e0 la r\u00e9duction de l\u2019exc\u00e8s de poids corporel et au maintien du poids de forme chez le chien adulte. Cet aliment di\u00e9t\u00e9tique pour animaux de compagnie pr\u00e9sente une faible densit\u00e9 \u00e9nerg\u00e9tique.<\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chien en surpoids ou ob\u00e8se<\/li>\n<\/ul>\n<p><strong>Bienfaits Essentiels :<\/strong><\/p>\n<ul>\n<li>Permet de\u00a0<strong>r\u00e9guler l&#8217;app\u00e9tit<\/strong>, de r\u00e9duire l&#8217;inflammation et de stimuler le m\u00e9tabolisme.<\/li>\n<li>Aide \u00e0 prot\u00e9ger contre l&#8217;oxydation par les radicaux libres pour aider \u00e0 maintenir un syst\u00e8me immunitaire sain<\/li>\n<li>Fibres solubles et insolubles pour aider \u00e0\u00a0<strong>d\u00e9clencher la sati\u00e9t\u00e9<\/strong>,\u00a0<strong>contr\u00f4ler l&#8217;app\u00e9tit<\/strong>\u00a0et maintenir la bonne sant\u00e9 gastro-intestinale.<\/li>\n<li>Aide les chiens \u00e0\u00a0<strong>br\u00fbler les graisses<\/strong>\u00a0tout en \u00e9pargnant la masse musculaire, ce qui permet\u00a0<strong>une perte de poids plus efficace.<\/strong><\/li>\n<li>Aide \u00e0 m\u00e9taboliser les graisses pour la\u00a0<strong>production d&#8217;\u00e9nergie<\/strong>\u00a0et pour maintenir la masse maigre.<\/li>\n<\/ul>\n<p><strong>Contre-indications :<\/strong><\/p>\n<ul>\n<li>Chiots, femelles en gestation et lactation<\/li>\n<\/ul>\n<p><strong>Cet aliment est\u00a0destin\u00e9 \u00e0 la prise en charge d&#8217;une maladie, il est conseill\u00e9 de consulter votre v\u00e9t\u00e9rinaire avant\u00a0de le donner \u00e0 votre animal.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Aliment mijot\u00e9 au go\u00fbt de boeuf et de l\u00e9gumes pour chiens en surpoids.<\/strong><\/p>\n<div id=\"product-description-short-5650\">\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chien en surpoids ou ob\u00e8se<\/li>\n<\/ul>\n<p><strong>Cet aliment est destin\u00e9 \u00e0 la prise en charge d&#8217;une maladie, il est conseill\u00e9 de consulter votre v\u00e9t\u00e9rinaire avant de le donner \u00e0 votre animal.<\/strong><\/p>\n<\/div>\n","protected":false},"featured_media":1172415,"template":"","meta":[],"product_cat":[12552,12582,2698],"product_tag":[],"class_list":["post-1172404","product","type-product","status-publish","has-post-thumbnail","product_cat-alimentation-du-chien","product_cat-alimentation-medicalisee-pour-chien","product_cat-chien","pa_marque-hills-pet-nutrition","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prescription Diet (Hill&#039;s) Chien Metabolic Mijot\u00e9 Boeuf &amp; L\u00e9gumes Hill&#039;s - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Aliment mijot\u00e9 au go\u00fbt de boeuf et de l\u00e9gumes pour chiens en surpoids.   Utilisation :   Chien en surpoids ou ob\u00e8se  Cet aliment est destin\u00e9 \u00e0 la prise en charge d&#039;une maladie, il est conseill\u00e9 de consulter votre v\u00e9t\u00e9rinaire avant de le donner \u00e0 votre animal.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prescription Diet (Hill&#039;s) Chien Metabolic Mijot\u00e9 Boeuf &amp; L\u00e9gumes Hill&#039;s - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Aliment mijot\u00e9 au go\u00fbt de boeuf et de l\u00e9gumes pour chiens en surpoids.   Utilisation :   Chien en surpoids ou ob\u00e8se  Cet aliment est destin\u00e9 \u00e0 la prise en charge d&#039;une maladie, il est conseill\u00e9 de consulter votre v\u00e9t\u00e9rinaire avant de le donner \u00e0 votre animal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-06T01:00:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/pd-metabolic-canine-vegetable-and-beef-stew-canned-productShot_zoom.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"73,45&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"Rupture de stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chien-metabolic-mijotes-boeuf-legumes-boite\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chien-metabolic-mijotes-boeuf-legumes-boite\\\/\",\"name\":\"Prescription Diet (Hill's) Chien Metabolic Mijot\u00e9 Boeuf &amp; L\u00e9gumes Hill's - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chien-metabolic-mijotes-boeuf-legumes-boite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chien-metabolic-mijotes-boeuf-legumes-boite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/pd-metabolic-canine-vegetable-and-beef-stew-canned-productShot_zoom.jpg\",\"datePublished\":\"2025-01-14T09:37:32+00:00\",\"dateModified\":\"2026-08-06T01:00:52+00:00\",\"description\":\"Aliment mijot\u00e9 au go\u00fbt de boeuf et de l\u00e9gumes pour chiens en surpoids. Utilisation : Chien en surpoids ou ob\u00e8se Cet aliment est destin\u00e9 \u00e0 la prise en charge d'une maladie, il est conseill\u00e9 de consulter votre v\u00e9t\u00e9rinaire avant de le donner \u00e0 votre animal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chien-metabolic-mijotes-boeuf-legumes-boite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chien-metabolic-mijotes-boeuf-legumes-boite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chien-metabolic-mijotes-boeuf-legumes-boite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/pd-metabolic-canine-vegetable-and-beef-stew-canned-productShot_zoom.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/pd-metabolic-canine-vegetable-and-beef-stew-canned-productShot_zoom.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chien-metabolic-mijotes-boeuf-legumes-boite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chien Metabolic Mijot\u00e9 Boeuf &amp; L\u00e9gumes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Hill&#039;s\" \/>\n<meta property=\"product:price:amount\" content=\"73.45\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-HCN077\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prescription Diet (Hill's) Chien Metabolic Mijot\u00e9 Boeuf &amp; L\u00e9gumes Hill's - V\u00e9torino","description":"Aliment mijot\u00e9 au go\u00fbt de boeuf et de l\u00e9gumes pour chiens en surpoids.   Utilisation :   Chien en surpoids ou ob\u00e8se  Cet aliment est destin\u00e9 \u00e0 la prise en charge d'une maladie, il est conseill\u00e9 de consulter votre v\u00e9t\u00e9rinaire avant de le donner \u00e0 votre animal.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Prescription Diet (Hill's) Chien Metabolic Mijot\u00e9 Boeuf &amp; L\u00e9gumes Hill's - V\u00e9torino","og_description":"Aliment mijot\u00e9 au go\u00fbt de boeuf et de l\u00e9gumes pour chiens en surpoids.   Utilisation :   Chien en surpoids ou ob\u00e8se  Cet aliment est destin\u00e9 \u00e0 la prise en charge d'une maladie, il est conseill\u00e9 de consulter votre v\u00e9t\u00e9rinaire avant de le donner \u00e0 votre animal.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-08-06T01:00:52+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/pd-metabolic-canine-vegetable-and-beef-stew-canned-productShot_zoom.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"73,45&euro;","Disponibilit\u00e9":"Rupture de stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/","name":"Prescription Diet (Hill's) Chien Metabolic Mijot\u00e9 Boeuf &amp; L\u00e9gumes Hill's - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/pd-metabolic-canine-vegetable-and-beef-stew-canned-productShot_zoom.jpg","datePublished":"2025-01-14T09:37:32+00:00","dateModified":"2026-08-06T01:00:52+00:00","description":"Aliment mijot\u00e9 au go\u00fbt de boeuf et de l\u00e9gumes pour chiens en surpoids. Utilisation : Chien en surpoids ou ob\u00e8se Cet aliment est destin\u00e9 \u00e0 la prise en charge d'une maladie, il est conseill\u00e9 de consulter votre v\u00e9t\u00e9rinaire avant de le donner \u00e0 votre animal.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/pd-metabolic-canine-vegetable-and-beef-stew-canned-productShot_zoom.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/pd-metabolic-canine-vegetable-and-beef-stew-canned-productShot_zoom.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/chien-metabolic-mijotes-boeuf-legumes-boite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Chien Metabolic Mijot\u00e9 Boeuf &amp; L\u00e9gumes"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Hill's","product_price_amount":"73.45","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"C-HCN077","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/product\/1172404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/media\/1172415"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/media?parent=1172404"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/product_cat?post=1172404"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/vaulxenvelin-69120\/boutique\/wp-json\/wp\/v2\/product_tag?post=1172404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}